{"id":81667,"date":"2023-03-07T11:20:48","date_gmt":"2023-03-07T08:20:48","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/pt-proteja-a-sua-relva-os-beneficios-do-trevo-branco\/"},"modified":"2023-03-07T11:20:48","modified_gmt":"2023-03-07T08:20:48","slug":"pt-proteja-a-sua-relva-os-beneficios-do-trevo-branco","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/pt\/2023\/03\/07\/pt-proteja-a-sua-relva-os-beneficios-do-trevo-branco\/","title":{"rendered":"Proteja a sua relva: Os benef\u00edcios do trevo branco"},"content":{"rendered":"<p>O Humane Guide to Critter Control (Cool Springs Press, 2017)&nbsp;de Theresa Rooney ajuda os jardineiros a manterem as pragas e os animais afastados dos seus preciosos jardins de forma segura e org\u00e2nica, de modo a n\u00e3o magoar o animal ou o jardim. No excerto seguinte, Rooney discute os benef\u00edcios de adicionar trevo branco ao seu relvado.\n<\/p>\n<h2>Repense a sua relva<br \/>\n<\/h2>\n<p>Se gosta do seu territ\u00f3rio (e muita gente gosta), h\u00e1 coisas que pode fazer para minimizar os danos causados por pragas. Talvez pensasse que eu diria para retirar todo o relvado e plantar plantas e \u00e1rvores nativas? Se tiver filhos ou animais de estima\u00e7\u00e3o, pode precisar de espa\u00e7o para eles brincarem. Um bom relvado pode destacar um belo jardim. A relva pode arrefecer o seu quintal e suavizar o som da vizinhan\u00e7a. Agora, aqui vem a ideia louca&mdash;considere adicionar trevo branco ao seu relvado.\n<\/p>\n<p>N\u00f3s, americanos, temos tido um caso de amor com o nosso territ\u00f3rio h\u00e1 muito tempo. Antes dos anos 50, permitimos o trevo e os dentes-de-le\u00e3o na relva. Sobretudo porque n\u00e3o&rsquo;n\u00e3o temos todos os herbicidas que temos agora. Mas na d\u00e9cada de 1950, os herbicidas tornaram-se populares. As empresas de sementes e qu\u00edmicas eram bastante inteligentes. Se matarmos todas as ervas daninhas de folha larga&mdash;isso pode realmente beneficiar a erva&mdash;agora temos de fertilizar a erva. Se cortar a relva mais curta, pode ser necess\u00e1rio regar mais e utilizar mais fertilizantes e herbicidas. Em vez de um pequeno prado manej\u00e1vel, dever\u00edamos aspirar a relvados verdes de mesa de bilhar.\n<\/p>\n<p>Se adicionar trevo ao seu relvado, poder\u00e1 encontrar os coelhos que o preferem (e realmente preferem) em vez dos seus l\u00edrios. Os Woodchucks tamb\u00e9m preferem o trevo&mdash; \u00e9 um dos seus preferidos. O trevo \u00e9 tamb\u00e9m um grande atractor de abelhas e encontra-se frequentemente em &ldquo;relvados de abelhas.&rdquo; os relvados de abelhas s\u00e3o uma alternativa aos espa\u00e7os tradicionais de erva que incluem plantas de baixo crescimento que florescem e fornecem n\u00e9ctar e p\u00f3len para os polinizadores. Isto pode incluir tomilho rastejante, trevo, sed\u00famen de baixo crescimento, violetas, ou gengibre canadiano. A festuca \u00e9 tamb\u00e9m a erva frequentemente utilizada nestas misturas, pois \u00e9 uma erva de crescimento mais lento e n\u00e3o&rsquo;n\u00e3o necessita dos fertilizantes que o azev\u00e9m do Kentucky faz. Algumas destas plantas podem suportar um pouco de tr\u00e1fego pedonal e outras muito pouco, pelo que precisam de ser planeadas e plantadas de acordo com a forma como a \u00e1rea deve ser utilizada. Pode descobrir que \u00e0 medida que aumenta a diversidade na sua paisagem, os seus problemas de pragas parecem diminuir ou mesmo desaparecer por completo.\n<\/p>\n<p>O trevo \u00e9 tamb\u00e9m um fixador de azoto. Os n\u00f3dulos nas suas ra\u00edzes permitem \u00e0 planta extrair azoto do ar e armazen\u00e1-lo nesses n\u00f3dulos. \u00c0 medida que as ra\u00edzes morrem, os n\u00f3dulos libertam esse azoto de volta para o solo at\u00e9 \u00e0s ra\u00edzes das gram\u00edneas. Se utilizar um fertilizante 30-0-15 no seu relvado, esse primeiro n\u00famero representa o nitrog\u00e9nio, a pr\u00f3pria coisa que o trevo fornece gratuitamente. O trevo n\u00e3o precisar\u00e1 de ser cortado com a mesma frequ\u00eancia com que a sua relva possa precisar de ser cortada. Mais tempo poupado para si. \u00c0 medida que acrescenta diversidade \u00e0 sua relva, poder\u00e1 notar que parece mais saud\u00e1vel. \u00c9 mais capaz de crescer espessa e exuberante. Mais capaz de resistir a alguns danos causados por insectos, ou evitar completamente os danos, porque o solo \u00e9 t\u00e3o saud\u00e1vel que nenhum dos &ldquo;bad&rdquo; os insectos do solo ficam fora de controlo. A utiliza\u00e7\u00e3o de produtos no seu relvado que s\u00e3o&rsquo;t org\u00e2nicos ou naturais podem diminuir a sa\u00fade do solo e a resili\u00eancia do seu relvado, for\u00e7ando-o a utilizar ainda mais produtos.\n<\/p>\n<p>E quanto a esses dentes-de-le\u00e3o? Se puder, deixe-os estar! Basta cortar as flores antes de elas irem para a semente&mdash;isso manter\u00e1 os seus vizinhos mais felizes. Os dentes-de-le\u00e3o s\u00e3o uma planta de flora\u00e7\u00e3o precoce. Podem ser uma das poucas plantas em flor quando as abelhas f\u00eameas saem da hiberna\u00e7\u00e3o e est\u00e3o esfomeadas. Ainda recentemente, a abelha enferrujada foi colocada na lista das amea\u00e7adas. Sim, uma abelha est\u00e1 em perigo de extin\u00e7\u00e3o. Pode at\u00e9 haver algumas j\u00e1 extintas, uma vez que n\u00e3o s\u00e3o vistas h\u00e1 anos. Para mim, o bumblebee \u00e9 uma parte ic\u00f3nica do Ver\u00e3o&mdash;ouvir o zumbido pregui\u00e7oso e ver que aparentemente imposs\u00edvel de voar a abelha passa lentamente \u00e9 um deleite de que eu gosto sempre.\n<\/p>\n<p>Os dentes-de-le\u00e3o t\u00eam uma raiz axial grande, robusta e profunda que quebra o solo compacto e retira nutrientes de longe do subsolo. Como \u00e9 cortado e as folhas deixadas no relvado para se decomporem, esses nutrientes est\u00e3o novamente dispon\u00edveis para a relva. At\u00e9 os dentes-de-le\u00e3o alimentam a relva para si, enquanto soltam o solo e os canais de malva a serem criados para que a chuva possa ser mantida l\u00e1 e filtrada de volta para os aqu\u00edferos abaixo, em vez de correr para os nossos lagos e riachos.\n<\/p>\n<p>Como pode um bom relvado cheio de trevo ajudar a controlar as pragas? Lembre-se, os coelhos e os patos-de-pau preferem o trevo, por isso podem deixar as suas plantas e hortas em paz. Al\u00e9m disso, enquanto os coelhos gostam de aperitivos de trevo, os falc\u00f5es ou corujas nos seus poleiros no alto, preparam-se para agarrar um coelho ou dois para alimentar as suas pr\u00f3prias crias.\n<\/p>\n<p>Um espa\u00e7o exterior saud\u00e1vel e diversificado pode atrair algumas pragas para \u00e1reas onde elas causam menos danos. Este espa\u00e7o exterior pode ser desconfort\u00e1vel para muitas pragas animais porque se est\u00e1 mais frequentemente no exterior porque \u00e9 um espa\u00e7o maravilhosamente belo e energizante para se estar dentro. O seu espa\u00e7o exterior saud\u00e1vel pode criar barreiras que algumas pragas n\u00e3o querem atravessar (sebes grossas) ou demasiada cobertura&mdash;pode esconder predadores&mdash;ou n\u00e3o oferecer espa\u00e7o para as pragas se alojarem. Pode ser t\u00e3o diverso que ningu\u00e9m est\u00e1 em abund\u00e2ncia suficiente para atrair uma praga&mdash;ou se tiver muita coisa a dizer, hostas, elas est\u00e3o espalhadas por todo o lado ou aconchegadas em seguran\u00e7a perto da sua casa, fora do alcance das pragas que gostam de as mordiscar.\n<\/p>\n<p>Como o seu espa\u00e7o exterior est\u00e1 t\u00e3o cheio de vida de p\u00e1ssaros, os insectos s\u00e3o mantidos sob controlo. As aves t\u00eam tantos outros alimentos que n\u00e3o&rsquo;n\u00e3o incomodam as suas colheitas. Parece-lhe um para\u00edso? E pode ser o seu para\u00edso, se assim o desejar.\n<\/p>\n<h2>Manter as coisas em ordem<br \/>\n<\/h2>\n<p>O aspecto final de um jardim saud\u00e1vel pode ser uma simples limpeza e asseio. Armazene pilhas de madeira longe da sua casa para que os ratos e, talvez, as cobras fiquem longe da sua funda\u00e7\u00e3o. (Se a constru\u00edrem, elas vir\u00e3o).\n<\/p>\n<p>Caixas e pilhas de composto s\u00e3o \u00f3ptimas para criar o seu pr\u00f3prio composto, mas se colocar as coisas erradas na pilha, como carne, queijo ou ossos, est\u00e1 a convidar pragas para o seu quintal. Mantenha as pilhas de composto limpas e afaste-as ligeiramente de sua casa&mdash;n\u00e3o at\u00e9 agora; quer ter acesso f\u00e1cil a elas. Alguns locais podem exigir que as mantenha cobertas. Se for este o caso na sua cidade, preste aten\u00e7\u00e3o para se certificar de que ficam suficientemente h\u00famidas&mdash;quando for necess\u00e1ria \u00e1gua, retire a cobertura antes de uma tempestade.\n<\/p>\n<h3>Mais de: O Guia para um Controlo Humano de Crit\u00e9rios<br \/>\n<\/h3>\n<p>&bull; Controlo de veados org\u00e2nicos para o seu jardim\n<\/p>\n<p>Reimpresso com permiss\u00e3o de The Human Guide to Critter Controlby Theresa Rooney e publicado por Cool Springs Press, 2017.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Humane Guide to Critter Control (Cool Springs Press, 2017)&nbsp;de Theresa Rooney ajuda os jardineiros a manterem as pragas e os animais afastados dos seus preciosos jardins de forma segura e org\u00e2nica, de modo a n\u00e3o magoar o animal ou o jardim. No excerto seguinte, Rooney discute os benef\u00edcios de adicionar trevo branco ao seu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81678,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121],"tags":[],"class_list":["post-81667","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-pest-control"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts\/81667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/comments?post=81667"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts\/81667\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/media\/81678"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/media?parent=81667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/categories?post=81667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/tags?post=81667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}