{"id":81615,"date":"2023-03-07T11:20:26","date_gmt":"2023-03-07T08:20:26","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/pt-rega-de-pavio-simples-e-eficiente\/"},"modified":"2023-03-07T11:20:26","modified_gmt":"2023-03-07T08:20:26","slug":"pt-rega-de-pavio-simples-e-eficiente","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/pt\/2023\/03\/07\/pt-rega-de-pavio-simples-e-eficiente\/","title":{"rendered":"Rega de pavio: Simples e Eficiente"},"content":{"rendered":"<p>Utilize a rega com pavio para manter as suas plantas hidratadas. Os sistemas de rega por pavio s\u00e3o simples de montar, e utilizam menos \u00e1gua do que outros m\u00e9todos.\n<\/p>\n<p>A rega com pavio \u00e9 um m\u00e9todo menos conhecido de irriga\u00e7\u00e3o eficiente. Fui apresentado pela primeira vez ao conceito enquanto lia um artigo da \u00cdndia h\u00e1 muitos anos atr\u00e1s, no qual se utilizavam pavios em conjunto com a irriga\u00e7\u00e3o enterrada de vasos de argila. Mais tarde descobri uma variedade de sistemas de rega por pavio que tinham sido utilizados em estudos de laborat\u00f3rio para medir o uso de \u00e1gua, plantas de f\u00e9rias-\u00e1gua, fornecer um abastecimento constante de \u00e1gua para plantas em estufas, e sementes de arranque. N\u00e3o consegui&#8217;n\u00e3o encontrei nenhuma pesquisa sobre o uso da rega com pavio no campo ou jardim, por isso tentei. Nos \u00faltimos 30 anos, I&#8217;realizei muitas experi\u00eancias e ensaios de campo que me ajudaram a compreender como conceber e utilizar sistemas de pavio de rega autom\u00e1tica.\n<\/p>\n<p>A irriga\u00e7\u00e3o com pavio utiliza um tecido molh\u00e1vel ou corda para transportar \u00e1gua de um reservat\u00f3rio ou tubo para as ra\u00edzes de uma planta. A rega por pavio pode funcionar por fluxo capilar que sobe e sobe, resultando num fluxo lento; por fluxo por gravidade, onde a \u00e1gua escorre pelo pavio, o que produz um fluxo r\u00e1pido; ou por um h\u00edbrido de ambos os sistemas. Aqui&#8217;s um olhar mais atento sobre ambas as t\u00e9cnicas para que possa determinar qual funcionar\u00e1 melhor para as suas plantas.\n<\/p>\n<h2>Puxadores capilares<br \/>\n<\/h2>\n<p>Com pavios capilares, a \u00e1gua sobe atrav\u00e9s de pequenos canais no material de pavimenta\u00e7\u00e3o. Num teste que realizei, a \u00e1gua num 7\n<\/p>\n<figure><img decoding=\"async\" src=\"https:\/\/my-garden.blog\/auto_content\/local_image\/5241213616462224.webp\" \/><\/figure>\n<p>A irriga\u00e7\u00e3o capilar utiliza normalmente um pavio de rega autom\u00e1tica com uma extremidade num reservat\u00f3rio de \u00e1gua ao lado de uma planta e a outra no solo, o que significa que o pavio tem de sair do reservat\u00f3rio e dobrar-se para o solo. Isto tamb\u00e9m pode ser feito com um pavio que se eleva do reservat\u00f3rio sob uma planta atrav\u00e9s de um buraco no vaso.\n<\/p>\n<p>Na Universidade da Calif\u00f3rnia, Riverside, estudei uma muda de \u00e1rvore palo verde (Parkinsonia florida) usando um pavio capilar de um reservat\u00f3rio debaixo da planta. A pl\u00e2ntula cresceu num balde de areia de s\u00edlica pura de 16 gramas. Ap\u00f3s um m\u00eas, a planta ainda estava a crescer e n\u00e3o apresentava sinais de stress h\u00eddrico com um consumo de \u00e1gua inferior a 2 colheres de sopa por dia.\n<\/p>\n<h2>Rega por fluxo gravitacional de pavio<br \/>\n<\/h2>\n<p>Os pavios por gravidade funcionam de forma semelhante aos pavios capilares, mas o fluxo \u00e9 descendente. (Por exemplo, um reservat\u00f3rio sentado no ch\u00e3o ao lado de uma planta, com o pavio a sair do fundo do reservat\u00f3rio e a descer at\u00e9 \u00e0s ra\u00edzes abaixo do solo).\n<\/p>\n<p>Num teste que realizei com o novo 7\n<\/p>\n<p>Os ensaios de campo no Deserto de Sonoran demonstraram o valor da irriga\u00e7\u00e3o por mecha de gravidade em climas \u00e1ridos, utilizando uma bra\u00e7adeira de mangueira perto de um reservat\u00f3rio de 5 gal\u00f5es para ajustar o fluxo de \u00e1gua. Depois de receberem menos de 30 gal\u00f5es de \u00e1gua, todas as plantas testadas permaneceram vivas e bem depois de tr\u00eas anos. Isto \u00e9 compar\u00e1vel ao uso de \u00e1gua que poderia&#8217;ter ultrapassado os 360 gal\u00f5es durante o mesmo per\u00edodo.\n<\/p>\n<h2>Preparar um pavio de rega autom\u00e1tica<br \/>\n<\/h2>\n<p>Para moldar o seu pr\u00f3prio sistema de rega de pavio para plantas em vaso ou em terra, primeiro junte os materiais b\u00e1sicos: pavio, tubos de pl\u00e1stico transparente em que o pavio se encaixar\u00e1 bem, e um reservat\u00f3rio de \u00e1gua. Para pavios de gravidade, voc\u00ea&#8217;necessitar\u00e1 tamb\u00e9m de uma bra\u00e7adeira de mangueira e um encaixe de barbela para fixar a tubagem de pl\u00e1stico ao reservat\u00f3rio. Se puder&##8217;n\u00e3o encontrar um encaixe de barbela para rosca na sua loja de ferragens local, pode encomendar um online. Voc\u00ea&#8217;necessitar\u00e1 tamb\u00e9m de um berbequim, uma broca de p\u00e1s dimensionada para o encaixe barbela a rosca, e cola de poliuretano.\n<\/p>\n<figure><img decoding=\"async\" src=\"https:\/\/my-garden.blog\/auto_content\/local_image\/3040659998197303.webp\" \/><\/figure>\n<p>Eu prefiro 7\n<\/p>\n<p>Para um reservat\u00f3rio, os recipientes reciclados funcionam bem, tais como garrafas de refrigerante velhas e jarras de pl\u00e1stico, assim como os baldes de 5 gal\u00f5es. Os recipientes de polipropileno durar\u00e3o anos, mas o polietileno pode durar apenas uma esta\u00e7\u00e3o. Em zonas de vento forte, poder\u00e1 ser necess\u00e1rio estacionar ou amarrar os reservat\u00f3rios para evitar que se desprendam.\n<\/p>\n<figure><img decoding=\"async\" src=\"https:\/\/my-garden.blog\/auto_content\/local_image\/9246698779965323.webp\" \/><\/figure>\n<p>Os sistemas de pavio capilar funcionam bem para cuidar das plantas da casa. Estes pavios auto regadores s\u00e3o f\u00e1ceis de instalar em casa e bons para dar \u00e1gua nas f\u00e9rias. Para isso, tudo o que precisa \u00e9 de um pavio, um pouco de tubo de pl\u00e1stico, e um reservat\u00f3rio. Basta passar o pavio pelo tubo (o que ajuda a reduzir a evapora\u00e7\u00e3o), e depois enfiar uma ponta na \u00e1gua e uma ponta no vaso de plantas. Pode empurrar a extremidade do pavio para dentro do recipiente com um pau ou uma chave de fendas.\n<\/p>\n<p>Para um sistema de pavio por gravidade, fa\u00e7a um furo na lateral do seu reservat\u00f3rio, perto do fundo (coloque fita adesiva sobre o local antes de perfurar, se o pl\u00e1stico for fino). Isto ajudar\u00e1 a evitar fissuras). Uma broca de espada com esporas far\u00e1 cortes mais limpos que proporcionam uma melhor veda\u00e7\u00e3o. Em seguida, coloque cola de poliuretano nas roscas do seu encaixe barbela a rosca e aparafuse-a no furo. Poder\u00e1 precisar de uma chave inglesa para o apertar correctamente. A cola ajudar\u00e1 a fortalecer e a selar a junta. Enfie o seu pavio atrav\u00e9s do tubo de vinil, e prenda o tubo \u00e0 extremidade do encaixe. Fixe a bra\u00e7adeira da mangueira ao tubo de pl\u00e1stico para que possa controlar a sa\u00edda de \u00e1gua no seu novo pavio de rega autom\u00e1tica.\n<\/p>\n<figure><img decoding=\"async\" src=\"https:\/\/my-garden.blog\/auto_content\/local_image\/2645358925692342.webp\" \/><\/figure>\n<p>Para plantas em terra, colocar o pavio no buraco de plantio o mais fundo poss\u00edvel. Adicione v\u00e1rios gal\u00f5es de \u00e1gua e deixe-a escorrer. Depois, adicionar a muda com ra\u00edzes perto do pavio, e voltar a encher o buraco com terra. Comprimir a terra para evitar bolsas de ar. Se quiser obter mais detalhes com o seu esquema de irriga\u00e7\u00e3o, pode usar um arranjo de v\u00e1rios pavios para o desenvolvimento de padr\u00f5es radiculares que ajudar\u00e3o a melhorar uma planta&#8217;s de vento-firmidade.\n<\/p>\n<p>Tamb\u00e9m se pode desenvolver um sistema de capta\u00e7\u00e3o para rega por mecha que utiliza \u00e1gua da chuva. O horticultor australiano Preslav Trenchev descobriu uma excelente forma de regar \u00e1rvores com \u00e1gua da chuva, pavios de rega autom\u00e1tica, e folhas de pl\u00e1stico. Trenchev concebeu um reservat\u00f3rio de bolso e uma bacia de capta\u00e7\u00e3o moldando o solo e encaixando uma folha de pl\u00e1stico \u00e0 volta de uma \u00e1rvore (ver foto acima). Depois, a \u00e1gua da chuva pode ser armazenada no reservat\u00f3rio e alimentada \u00e0 \u00e1rvore por pavio. O produto comercial Groasis Waterboxx alcan\u00e7a um efeito semelhante.\n<\/p>\n<h2>O futuro \u00e9 pavios<br \/>\n<\/h2>\n<p>Experimente os pavios de rega &#8212; penso que voc\u00ea&#8217;vai gostar dos resultados. A rega com pavio pode ser uma ferramenta valiosa para jardineiros, horticultores, e agricultores. Os sistemas s\u00e3o robustos e de baixo custo, e oferecem um longo intervalo de rega. Para al\u00e9m da sua utiliza\u00e7\u00e3o no jardim ou campo m\u00e9dio, a rega com pavio tamb\u00e9m pode desempenhar um papel na planta\u00e7\u00e3o de \u00e1rvores para sequestrar carbono, e no cultivo de vegetais com menos \u00e1gua nos ambientes mais dif\u00edceis. E as possibilidades don&#8217;t terminam a\u00ed: Podemos desenvolver melhores pavios para diferentes usos e compreender os melhores usos dos pavios capilares e dos pavios alimentados por gravidade. \u00c0 medida que continuamos a procurar formas de assegurar um futuro melhor para os nossos jardins e o nosso planeta, esta t\u00e9cnica mostra-se promissora.\n<\/p>\n<h2>Usos adicionais para a rega de pavio<br \/>\n<\/h2>\n<h3>Rega capilar de pavio para plantas de contentores<br \/>\n<\/h3>\n<p>Quem n\u00e3o&##8217;n\u00e3o adora um cesto de flores pendurado? Mas mant\u00ea-las saud\u00e1veis pode ser um desafio, porque elas&##8217;est\u00e3o expostas ao sol e ao vento, e o factor de pendurar pode torn\u00e1-las dif\u00edceis de regar. Adicionar pavios a um cesto suspenso torna mais f\u00e1cil manter os seus ornamentos florais. Comece por obter material de pavio e um cesto suspenso com um reservat\u00f3rio integrado. O cesto pode vir com um pavio j\u00e1 no lugar, mas voc\u00ea&#8217;provavelmente precisar\u00e1 de adicionar pavios adicionais. Fa\u00e7a quatro furos no topo do reservat\u00f3rio de \u00e1gua e insira dois pavios, espetando uma extremidade em cada furo para que os pavios formem um &#8220;U&#8221; forma com as extremidades estendidas no meio de crescimento e a parte inferior sentada no reservat\u00f3rio de \u00e1gua. Encher o reservat\u00f3rio com \u00e1gua, e depois deixar os pavios a funcionar.\n<\/p>\n<h3>Tapetes capilares para o arranque de sementes<br \/>\n<\/h3>\n<p>O tecido de pavimenta\u00e7\u00e3o pode fazer arranjos de irriga\u00e7\u00e3o eficazes para as pl\u00e2ntulas e arranques de plantas. Voc\u00ea&#8217;precisar\u00e1 de um tapete capilar ou de um tecido. Coloque-a debaixo dos seus vasos com as extremidades do tapete num reservat\u00f3rio de \u00e1gua. A \u00e1gua subir\u00e1 ao tapete e mover-se-\u00e1 debaixo dos vasos, mantendo o solo h\u00famido.\n<\/p>\n<p>Os tapetes capilares s\u00e3o utilizados frequentemente em estufas comerciais, porque&#8217;s\u00e3o quase infal\u00edveis, e distribuem a \u00e1gua de forma uniforme e eficiente. Geralmente, uma vez estabelecido no tapete, um vaso deve&##8217;n\u00e3o ser movido durante a produ\u00e7\u00e3o, pois pode ser dif\u00edcil ligar o tapete \u00e0 mistura do solo do recipiente. As estufas utilizam controlos autom\u00e1ticos para manter os seus tapetes consistentemente h\u00famidos, mas se tiver um bom reservat\u00f3rio e prestar aten\u00e7\u00e3o a quando este necessita de ser reabastecido, a instala\u00e7\u00e3o deve funcionar bem em casa.\n<\/p>\n<p>Pode fazer o seu pr\u00f3prio tapete capilar usando um cobertor de poli\u00e9ster, ou pode comprar tapetes em lojas de jardim ou online. H\u00e1 muitos tipos de tapetes capilares dispon\u00edveis. Alguns v\u00eam em kits que incluem tudo o que voc\u00ea&#8217;precisar\u00e1 de come\u00e7ar, tais como um reservat\u00f3rio, tapete, copos de mudas, e tampas de ventila\u00e7\u00e3o ajust\u00e1veis. Tal como os pavios, voc\u00ea&#8217;precisar\u00e1 de testar um tapete capilar antes de o enfiar debaixo das suas panelas para ter a certeza de que molha bem. Assim que vir como funcionam bem os tapetes capilares, \u00e9 prov\u00e1vel que&#8217;queira us\u00e1-los vezes sem conta.\n<\/p>\n<p>David Bainbridge iniciou a investiga\u00e7\u00e3o e consulta no deserto e restaura\u00e7\u00e3o de terras secas em 1981. He&#8217;s o autor de A Guide for Desert and Dryland Restoration and Gardening with Less Water, bem como de mais de 300 artigos e relat\u00f3rios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Utilize a rega com pavio para manter as suas plantas hidratadas. Os sistemas de rega por pavio s\u00e3o simples de montar, e utilizam menos \u00e1gua do que outros m\u00e9todos. A rega com pavio \u00e9 um m\u00e9todo menos conhecido de irriga\u00e7\u00e3o eficiente. Fui apresentado pela primeira vez ao conceito enquanto lia um artigo da \u00cdndia h\u00e1 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81626,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[118],"tags":[],"class_list":["post-81615","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-gardening-techniques"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts\/81615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/comments?post=81615"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts\/81615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/media\/81626"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/media?parent=81615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/categories?post=81615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/tags?post=81615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}