{"id":81225,"date":"2023-03-07T11:10:01","date_gmt":"2023-03-07T08:10:01","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/pt-cultivar-arvores-de-fruta-na-horta-familiar\/"},"modified":"2023-03-07T11:10:01","modified_gmt":"2023-03-07T08:10:01","slug":"pt-cultivar-arvores-de-fruta-na-horta-familiar","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/pt\/2023\/03\/07\/pt-cultivar-arvores-de-fruta-na-horta-familiar\/","title":{"rendered":"Cultivar \u00e1rvores de fruta na Horta Familiar"},"content":{"rendered":"<p>Um velho prov\u00e9rbio diz, &#8220;A melhor altura para plantar uma \u00e1rvore \u00e9 h\u00e1 vinte anos atr\u00e1s. A segunda melhor altura \u00e9 agora.&#8221; penso que esta pequena p\u00e9rola de sabedoria \u00e9 especialmente verdadeira quando se trata de \u00e1rvores de fruto.\n<\/p>\n<p>It&#8217;s demasiado f\u00e1cil de adiar a compra e a planta\u00e7\u00e3o de \u00e1rvores. Podem ser caras e a\u00ed&#8217;s h\u00e1 sempre muito mais a fazer. Quando se pensa em \u00e1rvores de fruto, \u00e9&#8217;s tamb\u00e9m f\u00e1cil de torcer uma&#8217;s l\u00f3gica: &#8220;Pode levar sete anos at\u00e9 que I&#8217;dessem frutos, ent\u00e3o porqu\u00ea incomodar&#8221; Mas adivinhem o qu\u00ea. Voc\u00ea&#8217;estar\u00e1 \u00e0 espera muito mais tempo se nunca plantar aquelas \u00e1rvores.\n<\/p>\n<p>Aqui&#8217;s o meu conselho para a selec\u00e7\u00e3o e cultivo de \u00e1rvores de fruto.\n<\/p>\n<h3>Don&##8217;t Desligar<br \/>\n<\/h3>\n<p>Quanto mais cedo plantar as suas \u00e1rvores de fruto, mais cedo elas&#8217;produzir\u00e3o. Uma vez que vai levar um m\u00ednimo de dois anos (para algumas variedades de ma\u00e7\u00e3) a cinco ou mais (cerejas ou papaia), nunca \u00e9 demasiado cedo para come\u00e7ar. Se uma \u00e1rvore de fruto \u00e9 mais do que o seu or\u00e7amento pode suportar, poder\u00e1 considerar a hip\u00f3tese de sugerir uma \u00e1rvore&#8211;ou um certificado de oferta a um viveiro de renome que as armazena&#8211;como uma ideia de oferta.\n<\/p>\n<h3>Fa\u00e7a a sua investiga\u00e7\u00e3o<br \/>\n<\/h3>\n<p>Algumas \u00e1rvores s\u00e3o auto-polinizantes (a maioria das nectarinas, p\u00eassegos, cerejas \u00e1cidas). Outras requerem outra variedade da mesma fruta para polinizar (a maioria das ma\u00e7\u00e3s, p\u00earas, ameixas). \u00c9 melhor plantar polinizadores cruzados a n\u00e3o mais de 50 p\u00e9s de dist\u00e2ncia. Se voc\u00ea&#8217;tiver sorte, um vizinho pr\u00f3ximo plantou um bom polinizador cruzado por perto. O tempo \u00e9 tudo quando se trata de poliniza\u00e7\u00e3o: certifique-se que as \u00e1rvores que compra para poliniza\u00e7\u00e3o cruzada florescem na mesma altura do ano.\n<\/p>\n<p>It&#8217;s tamb\u00e9m \u00e9 importante saber o melhor momento para plantar. A maioria dos viveiros s\u00e3o enviados com base no tempo de plantio apropriado para a sua \u00e1rea; contudo, se voc\u00ea&#8217;estiver a comprar localmente, precisa de aprender tudo o que puder sobre as condi\u00e7\u00f5es favor\u00e1veis de plantio.\n<\/p>\n<p>Aprender sobre a profundidade e largura dos furos, necessidades de rega, requisitos de poda. A\u00ed&#8217;s h\u00e1 muito para aprender. Se a sua \u00e1rvore n\u00e3o&##8217;n\u00e3o vem com estas instru\u00e7\u00f5es, pesquise na internet. Certifique-se apenas de que as suas fontes s\u00e3o fi\u00e1veis.\n<\/p>\n<h3>Saiba quais as \u00e1rvores a seleccionar para a sua zona de plantio<br \/>\n<\/h3>\n<p>Por mais que deseje que seja verdade, pode&#8217;n\u00e3o cultivar todo o tipo de fruta em todos os climas. As ma\u00e7\u00e3s, por exemplo, requerem uma esta\u00e7\u00e3o dormente. A geada e os citrinos n\u00e3o&#8217;t se misturam. E enquanto h\u00e1 pessoas que empurram o envelope, ele&##8217;\u00e9 muita aprendizagem e trabalho para cultivar fruta num clima pouco convidativo. Para saber se pode cultivar a sua fruta favorita onde vive, verifique com o seu servi\u00e7o local de extens\u00e3o agr\u00edcola.\n<\/p>\n<h3>Proteja as Suas \u00c1rvores<br \/>\n<\/h3>\n<p>Uma \u00e1rvore jovem&#8217;s casca \u00e9 especialmente suscept\u00edvel a danos, no entanto&#8217;s apela a veados esfomeados. Esteja a salvo e use algum tipo de envolt\u00f3rio ou guarda de \u00e1rvore. Pode comprar rede, tubagem, ou papel ou papel de embrulho. Ou pode ser criativo e fazer a sua pr\u00f3pria guarda de \u00e1rvore. Quando plantamos uma \u00e1rvore de caranguejo, n\u00e3o conseguimos encontrar localmente um embrulho de \u00e1rvore, por isso improvis\u00e1mos comprando um tubo de drenagem de pl\u00e1stico corrugado preto que cortamos a um comprimento apropriado e depois cortamos de um lado. S\u00f3 n\u00e3o constringir a \u00e1rvore&#8217;s tronco, embrulhando com demasiada for\u00e7a.\n<\/p>\n<h3>Lembre-se de proteger tamb\u00e9m a fruta<br \/>\n<\/h3>\n<p>Nada \u00e9 mais decepcionante do que descobrir que pouco antes da fruta estar totalmente amadurecida, algo chegou a ela antes de si. Para manter os p\u00e1ssaros afastados, cubra as \u00e1rvores de fruto com redes. C\u00e3es ao ar livre ajudar\u00e3o a manter guaxinins, veados, e ursos afastados, mas tamb\u00e9m h\u00e1 outras op\u00e7\u00f5es. Manter as suas \u00e1rvores dentro de uma \u00e1rea devidamente vedada. (As veda\u00e7\u00f5es para veados ou duas filas paralelas de cerca de quatro metros de altura espa\u00e7adas a quatro p\u00e9s devem manter os veados afastados). Se acrescentar uma fila de veda\u00e7\u00f5es el\u00e9ctricas sobre a sua outra veda\u00e7\u00e3o, os guaxinins tamb\u00e9m devem manter-se afastados. Decidimos ampliar a nossa horta para acomodar \u00e1rvores de fruto e fech\u00e1mos tudo com uma veda\u00e7\u00e3o para veados. At\u00e9 agora, tudo bem.\n<\/p>\n<h3>Esteja certo de que tem espa\u00e7o suficiente<br \/>\n<\/h3>\n<p>Qual \u00e9 a largura madura das \u00e1rvores que est\u00e1 a considerar&#8217;est\u00e1 a considerar? Certifique-se de que tem espa\u00e7o suficiente entre elas. \u00c9&#8217;\u00e9 poss\u00edvel cultivar as suas \u00e1rvores de forma mais compacta do que o espa\u00e7amento padr\u00e3o sugere com m\u00e9todos de poda especiais; no entanto, \u00e9&#8217;\u00e9 crucial para pesquisar esta t\u00e9cnica. Um bom recurso \u00e9 o livro Grow a Little Fruit Tree: T\u00e9cnicas de poda simples para \u00e1rvores de fruto de pequeno espa\u00e7o e de f\u00e1cil colheita.\n<\/p>\n<h3>Pense em Altura<br \/>\n<\/h3>\n<p>\u00c9 preciso pensar em como voc\u00ea&#8217;colher\u00e1 tamb\u00e9m os seus frutos. Quer realmente subir uma escada de extens\u00e3o contra membros de \u00e1rvores para recolher os seus frutos? Ou para podar as suas \u00e1rvores? Isso pode ser perigoso, especialmente para os jardineiros idosos. Quando eles&#8217;estiverem dispon\u00edveis, considere \u00e1rvores an\u00e3s ou semi-an\u00e3s em vez das maiores, para tornar mais simples o cuidado e a colheita.\n<\/p>\n<h3>A localiza\u00e7\u00e3o \u00e9 importante<br \/>\n<\/h3>\n<p>O solo para \u00e1rvores de fruto deve ter muitos nutrientes, e poder\u00e1 ser necess\u00e1rio acrescentar emendas em qualquer caso. Planta onde a drenagem \u00e9 boa. E plante onde as suas \u00e1rvores estejam asseguradas de um m\u00ednimo de cinco horas de luz solar por dia.\n<\/p>\n<h3>Rightsize o seu pomar<br \/>\n<\/h3>\n<p>Se plantar em excesso, \u00e9...#8217;n\u00e3o \u00e9 t\u00e3o prov\u00e1vel que consiga acompanhar a manuten\u00e7\u00e3o necess\u00e1ria. Considere quais os frutos que a sua fam\u00edlia tem mais probabilidade de comer, quais s\u00e3o os mais vers\u00e1teis, quanta fruta realmente precisa. N\u00e3o h\u00e1&#8217;n\u00e3o h\u00e1 raz\u00e3o para plantar um pomar de ma\u00e7\u00e3s inteiro se a sua colheita servir apenas a sua fam\u00edlia. (Por outro lado, lembre-se que as ma\u00e7\u00e3s podem ser secas para comer no final do Inverno, conservadas como molho de ma\u00e7\u00e3 enlatado em banho-maria ou recheio de tarte, ou sumo para cidra).\n<\/p>\n<h3>Esteja atento<br \/>\n<\/h3>\n<p>As \u00e1rvores frut\u00edferas anseiam por aten\u00e7\u00e3o, umas mais do que outras. Mais uma vez, a investiga\u00e7\u00e3o \u00e9 imperativa para ver o quanto \u00e1rvores espec\u00edficas requerem cuidados. Todas elas precisam de cobertura morta, poda, fertiliza\u00e7\u00e3o, e rega regular e frequente. Deve tamb\u00e9m ser diligente na protec\u00e7\u00e3o das suas \u00e1rvores contra pragas e doen\u00e7as. Uma limpeza rigorosa das quedas \u00e9 essencial.\n<\/p>\n<p>O que recompensa a sua fam\u00edlia colher\u00e1 se adicionar \u00e1rvores de fruto ao seu jardim. N\u00e3o h\u00e1&#8217;n\u00e3o h\u00e1 tempo como o presente para come\u00e7ar.\n<\/p>\n<p>Para mais informa\u00e7\u00f5es sobre planta\u00e7\u00e3o, poda, colheita e muito mais, consulte este artigo do guru de jardinagem da Mother Earth News, Barbara Pleasant.\n<\/p>\n<p>Carole Coates \u00e9 jardineira e conservadora de alimentos, arquivista familiar, ensa\u00edsta, poetisa, fot\u00f3grafa, e moderna propriet\u00e1ria de casas. Pode encontrar Carole em Living On the Diagonal, onde ela partilha a sua tomada de vida, incluindo a moderna homesteading, prepara\u00e7\u00e3o e conserva\u00e7\u00e3o de alimentos, e viagens, bem como pensamentos e reflex\u00f5es aleat\u00f3rias, ensaios pessoais, poesia, e fotografia.\n<\/p>\n<p>Todos os bloggers da comunidade M\u00c3E TERRA concordaram em seguir as nossas Directrizes de Blogging, e s\u00e3o respons\u00e1veis pela exactid\u00e3o dos seus posts. Para saber mais sobre o autor deste post, clique no seu link no topo da p\u00e1gina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um velho prov\u00e9rbio diz, &#8220;A melhor altura para plantar uma \u00e1rvore \u00e9 h\u00e1 vinte anos atr\u00e1s. A segunda melhor altura \u00e9 agora.&#8221; penso que esta pequena p\u00e9rola de sabedoria \u00e9 especialmente verdadeira quando se trata de \u00e1rvores de fruto. It&#8217;s demasiado f\u00e1cil de adiar a compra e a planta\u00e7\u00e3o de \u00e1rvores. Podem ser caras e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81236,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115],"tags":[],"class_list":["post-81225","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-fruits"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts\/81225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/comments?post=81225"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts\/81225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/media\/81236"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/media?parent=81225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/categories?post=81225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/tags?post=81225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}