{"id":80887,"date":"2023-03-07T11:00:58","date_gmt":"2023-03-07T08:00:58","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/pt-o-jardineiro-do-mercado\/"},"modified":"2023-03-07T11:00:58","modified_gmt":"2023-03-07T08:00:58","slug":"pt-o-jardineiro-do-mercado","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/pt\/2023\/03\/07\/pt-o-jardineiro-do-mercado\/","title":{"rendered":"O jardineiro do mercado"},"content":{"rendered":"<p>Jean-Martin Fortier&rsquo;s, fazenda de mercado org\u00e2nico no sul do Qu\u00e9bec, ganha $150.000 em rendimentos por ano de apenas 1,5 acres de terra. Com not\u00e1vel sucesso nesta escala durante a \u00faltima d\u00e9cada, Fortier tornou-se um mentor e educador para outros agricultores que querem viver de forma sustent\u00e1vel vendendo frutas e legumes cultivados em pequenas parcelas de terra.\n<\/p>\n<p>Depois de publicar um livro popular sobre o tema,O Jardineiro do Mercado: A Successful Grower&rsquo;s Handbook for Small-Scale Organic Farming, Fortier&rsquo;s O \u00faltimo esfor\u00e7o educacional do The Market Gardener&rsquo;s vem sob a forma de um novo filme chamado The Market Gardener&rsquo;s Toolkit. A conta de 80 minutos da vida real, que foi filmada ao longo de uma esta\u00e7\u00e3o completa de cultivo, est\u00e1 repleta de conselhos sobre como lidar com sucesso com as opera\u00e7\u00f5es do dia-a-dia numa quinta de vegetais em pequena escala. Cerca de 1.800 pessoas contribu\u00edram para uma campanha de financiamento da multid\u00e3o para tornar o projecto documental poss\u00edvel.\n<\/p>\n<p>Observando The Market Gardener&rsquo;s Toolkit e aprendendo com a experi\u00eancia real da Fortier&rsquo;s, os agricultores actuais e aspirantes a agricultores reunir\u00e3o conhecimentos valiosos sobre muitos aspectos essenciais em crescimento, incluindo\n<\/p>\n<p>&bull; Criando um desenho eficiente para o seu jardim de mercado.\n<\/p>\n<p>&bull; Gerir um viveiro de sementes a partir de um viveiro.\n<\/p>\n<p>&bull; Encontrar o sucesso a longo prazo com o m\u00ednimo de lavoura e ferramentas manuais de baixa tecnologia.\n<\/p>\n<p>&bull; Dominando a rota\u00e7\u00e3o de culturas.\n<\/p>\n<p>&bull; Utiliza\u00e7\u00e3o de hoop houses para extens\u00e3o da esta\u00e7\u00e3o.\n<\/p>\n<p>&bull;&nbsp;Aplica\u00e7\u00e3o de composto e outras emendas.\n<\/p>\n<p>&bull;&nbsp;Utilizando culturas de cobertura de adubo verde.\n<\/p>\n<p>&bull;&nbsp;Rega eficiente.\n<\/p>\n<p>&bull;&nbsp;Controlo de pragas e ervas daninhas.\n<\/p>\n<p>&bull;&nbsp;M\u00e9todos de colheita e armazenamento.\n<\/p>\n<p>Ao gui\u00e1-lo pessoalmente atrav\u00e9s das t\u00e9cnicas que funcionaram melhor na sua quinta, Fortier volta continuamente a um tema: efici\u00eancia. Para que uma pequena quinta seja economicamente vi\u00e1vel e, ao mesmo tempo, enfrente tarefas \u00e0 m\u00e3o com o m\u00ednimo de empregados a tempo inteiro, os operadores devem aperfei\u00e7oar os m\u00e9todos mais eficientes &mdash; e este filme oferece ideias inovadoras e testadas para fazer exactamente isso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jean-Martin Fortier&rsquo;s, fazenda de mercado org\u00e2nico no sul do Qu\u00e9bec, ganha $150.000 em rendimentos por ano de apenas 1,5 acres de terra. Com not\u00e1vel sucesso nesta escala durante a \u00faltima d\u00e9cada, Fortier tornou-se um mentor e educador para outros agricultores que querem viver de forma sustent\u00e1vel vendendo frutas e legumes cultivados em pequenas parcelas de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":80898,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117],"tags":[],"class_list":["post-80887","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-garden-tools"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts\/80887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/comments?post=80887"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts\/80887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/media\/80898"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/media?parent=80887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/categories?post=80887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/tags?post=80887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}