{"id":80003,"date":"2023-03-07T10:40:01","date_gmt":"2023-03-07T07:40:01","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/pt-propagacao-de-amoras-pretas-por-tip-rooting\/"},"modified":"2023-03-07T10:40:01","modified_gmt":"2023-03-07T07:40:01","slug":"pt-propagacao-de-amoras-pretas-por-tip-rooting","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/pt\/2023\/03\/07\/pt-propagacao-de-amoras-pretas-por-tip-rooting\/","title":{"rendered":"Propaga\u00e7\u00e3o de amoras pretas por Tip-Rooting"},"content":{"rendered":"<p>Em vez da camada mais tradicional de ponta, aprenda a propagar amoras pretas usando uma ponta de raiz, o que n\u00e3o&#8217;n\u00e3o perturba a sa\u00fade do seu solo.\n<\/p>\n<p>Em crian\u00e7a, lembro-me de colher amoras com as minhas irm\u00e3s e primos ao longo de um caminho-de-ferro abandonado. Tivemos alguns momentos assustadores em que perturb\u00e1mos as serpentes. (Na realidade, essas cobras estavam provavelmente a mover-se o mais r\u00e1pido poss\u00edvel, tentando fugir de todo o nosso barulho e p\u00e9s). E volt\u00e1vamos para casa com arranh\u00f5es nos bra\u00e7os e m\u00e3os, mas com baldes cheios de bagas suculentas para a m\u00e3e fazer em geleia e deliciosos sapateiros.\n<\/p>\n<p>No ano passado, o meu marido e eu decidimos acrescentar uma variedade de amora sem espinho a uma cama elevada no nosso jardim.  Mal me apercebi de como esta planta em particular seria t\u00e3o vigorosa e enviaria tantas bengalas para o pr\u00f3ximo ano.  O nosso canteiro elevado era&#8217;t pequeno, mas tamb\u00e9m n\u00e3o era&#8217;t excessivamente grande.\n<\/p>\n<p>Assim, em Agosto do ano passado, comecei a ler em Extens\u00e3o publica\u00e7\u00f5es o processo de propaga\u00e7\u00e3o de amoras silvestres. A camada de ponta era o m\u00e9todo globalmente favorecido, mas na minha cama elevada, eu n\u00e3o&#8217;n\u00e3o queria desestabilizar a minha camada de lasanha.  O objectivo da camada de lasanha \u00e9 evitar perturbar o solo e permitir que belas minhocas e outros micr\u00f3bios enrique\u00e7am o solo.\n<\/p>\n<p>Decidimos apenas &#8220;tip-root&#8221; as bengalas de bagas. Arredondei para cima 1 gal\u00e3o de potes pretos e enchi-os com terra para vaso. As panelas pretas tinham sido lavadas com um pouco de lix\u00edvia e \u00e1gua para garantir que estavam limpas. As folhas nas pontas das bengalas estavam enroladas e vermelhas, mas eu arranquei as folhas e plantei uma ponta de amora em cada vaso.\n<\/p>\n<p>Durante os meses de Agosto e Setembro, mantive os vasos regados, mas n\u00e3o saturados, e anexados \u00e0 planta original. No in\u00edcio de Outubro, cortei a cana cerca de 1 p\u00e9 acima do vaso e deixei todos os vasos no lugar at\u00e9 Janeiro. Nessa altura, mudei todas as novas plantas para a sua casa, plantando e aplicando mulching pesado. As ra\u00edzes eram bonitas e grossas no fundo de cada vaso. A experi\u00eancia faz-me pensar se posso duplicar este mesmo processo de propaga\u00e7\u00e3o com outras plantas.\n<\/p>\n<p>Quando a Primavera rolou, estava ansioso por ver se as novas plantas estavam a prosperar. Sim, todas as plantas tinham arrancado e estavam a lan\u00e7ar novas flores. Algumas eram mais vigorosas do que outras, mas eu estava contente por ver novas folhas e flores em todas as plantas. As abelhas estavam a adorar a pulveriza\u00e7\u00e3o de novas flores e s\u00f3 isso fez com que o processo valesse o esfor\u00e7o.\n<\/p>\n<p>Se tiver um amigo ou vizinho que tenha amoras sem espinhos, visite com eles sobre o enraizamento e a partilha da sua boa fortuna. Gostamos de expandir a nossa cama elevada de amoras silvestres e esperamos encontrar novas variedades para experimentar no futuro.\n<\/p>\n<p>Esther Coco Boe vive na Louisiana, onde trabalha para melhorar os habitats de polinizadores, planta ervas arom\u00e1ticas no seu jardim de casa, cultiva tomates de heran\u00e7a e exp\u00f5e as crian\u00e7as \u00e0 jardinagem. Ligue-se com Esther no Facebook .\n<\/p>\n<p>Todos os bloggers da comunidade M\u00c3E TERRA concordaram em seguir as nossas Directrizes de Blogging, e s\u00e3o respons\u00e1veis pela exactid\u00e3o dos seus posts. Para saber mais sobre o autor deste post, clique no seu link no topo da p\u00e1gina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em vez da camada mais tradicional de ponta, aprenda a propagar amoras pretas usando uma ponta de raiz, o que n\u00e3o&#8217;n\u00e3o perturba a sa\u00fade do seu solo. Em crian\u00e7a, lembro-me de colher amoras com as minhas irm\u00e3s e primos ao longo de um caminho-de-ferro abandonado. Tivemos alguns momentos assustadores em que perturb\u00e1mos as serpentes. (Na [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":80014,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115],"tags":[],"class_list":["post-80003","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-fruits"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts\/80003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/comments?post=80003"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts\/80003\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/media\/80014"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/media?parent=80003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/categories?post=80003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/tags?post=80003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}