{"id":79873,"date":"2023-03-07T10:17:34","date_gmt":"2023-03-07T07:17:34","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/pt-como-acrescentar-carbono-ao-solo\/"},"modified":"2023-03-07T10:17:34","modified_gmt":"2023-03-07T07:17:34","slug":"pt-como-acrescentar-carbono-ao-solo","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/pt\/2023\/03\/07\/pt-como-acrescentar-carbono-ao-solo\/","title":{"rendered":"Como Acrescentar Carbono ao Solo"},"content":{"rendered":"<p>O solo de alta qualidade acontece quando se tem solos ricos em h\u00famus. Aprenda como adicionar carbono ao solo, e como adicionar nitrog\u00e9nio ao solo naturalmente para tornar o seu jardim mais saud\u00e1vel.\n<\/p>\n<p>Tirar o carbono do ar e entrar no nosso solo \u00e9&#8217; n\u00e3o \u00e9 apenas uma \u00f3ptima forma de os jardineiros ajudarem a mitigar os piores impactos das altera\u00e7\u00f5es clim\u00e1ticas. \u00c9&#8217;\u00e9 uma ferramenta fant\u00e1stica para tornar os nossos jardins mais saud\u00e1veis e mais resistentes \u00e0 erva daninha a partir de agora.\n<\/p>\n<p>Os solos ricos em carbono podem fornecer a seguinte lista de servi\u00e7os que os solos pobres em carbono podem&#8217;t.\n<\/p>\n<ul>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Absorve muita \u00e1gua<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Resistir \u00e0 compacta\u00e7\u00e3o<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Suporta grandes quantidades de microvida ben\u00e9fica<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Reter nutrientes cr\u00edticos como nitrog\u00eanio<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Regular a temperatura do solo<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Proteja as plantas cultivadas contra estresse, pragas e pat\u00f3genos<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Prevenir ervas daninhas<\/font><\/font><\/li>\n<\/ul>\n<p>Assim, \u00e9 claro, a maioria dos jardineiros mataria para ter um solo rico em carbono! E isso&#8217;s \u00e9 bom, porque vai precisar de muitos cad\u00e1veres no seu solo se quiser que este permane\u00e7a rico em carbono a longo prazo.\n<\/p>\n<h2>Humus<br \/>\n<\/h2>\n<p>Sei que isso parece assustador. Mas o facto \u00e9 que o solo de alta qualidade acontece quando se tem um conte\u00fado h\u00famico elevado, tamb\u00e9m referido como solos ricos em h\u00famus. O h\u00famus \u00e9 frequentemente descrito como mat\u00e9ria vegetal apodrecida. No entanto, isso&#8217;n\u00e3o \u00e9 exactamente exacto.\n<\/p>\n<p>O h\u00famus \u00e9 feito a partir dos corpos acumulados de in\u00fameras formas de vida microsc\u00f3picas que estavam envolvidas na decomposi\u00e7\u00e3o dessa mat\u00e9ria vegetal rica em carbono. Por outras palavras, enormes quantidades de microrganismos mortos s\u00e3o o que sequestra o carbono e promove um ambiente de jardim saud\u00e1vel.\n<\/p>\n<p>Deixe&#8217;s ver como isso funciona para que possa aumentar a contagem de carca\u00e7as ricas em carbono no seu solo.\n<\/p>\n<h2>Fixa\u00e7\u00e3o de carbono<br \/>\n<\/h2>\n<p>As plantas absorvem carbono transportado pelo ar que&#8217;s est\u00e1 preso entre duas mol\u00e9culas de oxig\u00e9nio (CO2). Depois, separam esse carbono daquelas mol\u00e9culas de oxig\u00e9nio utilizando a energia do sol.\n<\/p>\n<p>Para evitar que essas mol\u00e9culas de carbono se voltem a ligar com oxig\u00e9nio e flutuem, as plantas suspendem o carbono numa esp\u00e9cie de xarope. Depois, utilizam esse xarope, mais nutrientes e \u00e1gua do solo, para fazer partes de plantas, incluindo ra\u00edzes, folhas e caules.\n<\/p>\n<p>Esse processo de convers\u00e3o de carbono transportado pelo ar em carbono vegetal utiliz\u00e1vel chama-se fixa\u00e7\u00e3o de carbono. \u00c9&#8217;s a primeira fase do ciclo do carbono. A seguir, muitas dessas folhas, caules e ra\u00edzes de plantas ricas em carbono que funcionam como um sumidouro tempor\u00e1rio de carbono devem morrer.\n<\/p>\n<h2>Captura de Carbono<br \/>\n<\/h2>\n<p>Quando essas plantas ou as suas partes morrem (queda anual de folhas), se permanecerem no solo ou no solo, formas de vida como insectos e bact\u00e9rias comer\u00e3o essa mat\u00e9ria vegetal. Elas&#8217;ir\u00e3o excretar algumas delas. Mas algumas permanecer\u00e3o nos seus corpos e c\u00e9lulas at\u00e9 \u00e0 sua morte.\n<\/p>\n<p>Depois, os seus corpos e res\u00edduos ser\u00e3o comidos e excretados por outra coisa. Eventualmente, atrav\u00e9s de in\u00fameras itera\u00e7\u00f5es de seres vivos comendo uma vez seres vivos ou os seus res\u00edduos, todo esse carbono se torna mais est\u00e1vel armazenado em partes microsc\u00f3picas da carca\u00e7a que n\u00e3o&#8217;t se decomp\u00f5em t\u00e3o prontamente.\n<\/p>\n<p>O carbono vegetal, transformado em microorganismo carbono armazenado, permanece uma fonte alimentar activa para a vida do solo at\u00e9 que eventualmente tenha sido utilizado tantas vezes que se transforma em h\u00famus. Depois, torna-se a infra-estrutura est\u00e1vel que suporta o bem-estar de toda a vida do solo, incluindo as plantas.\n<\/p>\n<p>Tanto aquele carbono ainda comest\u00edvel como o conte\u00fado h\u00famico podem absorver e reter humidade e nutrientes que filtram atrav\u00e9s do solo. Actuam como um por\u00e3o de raiz\n<\/p>\n<h3>Compostagem<br \/>\n<\/h3>\n<p>A compostagem \u00e9 um m\u00e9todo alternativo de captura de carbono para jardins. Em vez de deixar material vegetal, ou o desperd\u00edcio de coisas que comeram estrume vegetal (como vacas), no topo do solo recolhe-se o mesmo. Depois mistura-se com outros materiais org\u00e2nicos para fazer uma pilha de compostagem.\n<\/p>\n<figure><img decoding=\"async\" src=\"https:\/\/my-garden.blog\/auto_content\/local_image\/3361898856981723.webp\" \/><\/figure>\n<p>Se se aproximar da quantidade certa de carbono (30 partes), azoto (1 parte), ar (40%) e \u00e1gua (60%) numa pilha suficientemente grande, chegam n\u00fameros colossais de organismos microsc\u00f3picos term\u00f3filos (amantes do calor). Decomp\u00f5em rapidamente esses res\u00edduos de mat\u00e9ria vegetal. Depois, isso pode ser reaplicado ao solo.\n<\/p>\n<p>Durante a compostagem, algum carbono \u00e9 perdido para a oxida\u00e7\u00e3o e metaniza\u00e7\u00e3o. No entanto, uma grande parte permanece para tr\u00e1s nas incr\u00edveis quantidades de bact\u00e9rias term\u00f3filas de curta dura\u00e7\u00e3o que morreram naquela pilha. Como tal, it&#8217;\u00e9 uma \u00f3ptima maneira de carregar pesadamente o seu solo com carca\u00e7as microsc\u00f3picas ricas em carbono.\n<\/p>\n<h2>Exsudados de Carbono<br \/>\n<\/h2>\n<p>Al\u00e9m disso, as plantas vivas enviam um fornecimento regular desse xarope de carbono para o solo atrav\u00e9s das ra\u00edzes. Essa mistura de carbono doce, chamada exsudados de carbono, \u00e9 apanhada por microlife. Enquanto s\u00e3o recolhidas, essas micro-vidas tamb\u00e9m deixam cair nutrientes utiliz\u00e1veis pelas plantas, muitas vezes como res\u00edduos ou deixando cair mortos em tr\u00e2nsito, perto da zona radicular.\n<\/p>\n<p>Em muitas leguminosas e algumas n\u00e3o leguminosas, as bact\u00e9rias depositam mesmo quantidades excessivamente grandes de azoto directamente nas ra\u00edzes das plantas atrav\u00e9s de n\u00f3dulos enquanto apanham exsudados de carbono. Esses exsudados s\u00e3o ent\u00e3o ciclados atrav\u00e9s do sistema de vida do solo, como faz a mat\u00e9ria morta das plantas. Al\u00e9m disso, quando as ra\u00edzes das plantas morrem, o azoto nos n\u00f3dulos \u00e9 libertado no solo para que outras plantas pr\u00f3ximas o utilizem.\n<\/p>\n<h2>Maximizar a Sequestra\u00e7\u00e3o de Carbono<br \/>\n<\/h2>\n<p>Com este fundo em mente, tenho a certeza que pode adivinhar como aumentar o carbono no seu jardim. Sim, \u00e9 isso mesmo! Cultivar toneladas de plantas. Deixar mat\u00e9ria vegetal e ra\u00edzes no solo e no solo. E adicione adubo.\n<\/p>\n<p>Isso&#8217;\u00e9 a ess\u00eancia b\u00e1sica de como obter um grande n\u00famero de carca\u00e7as ricas em carbono no solo. Contudo, existem algumas etapas espec\u00edficas que podem acelerar a cria\u00e7\u00e3o dessa catacumba rica em carbono para apoiar a sa\u00fade geral do jardim. Aqui est\u00e3o eles!\n<\/p>\n<h3>Passo 1: Quebrar a Compacta\u00e7\u00e3o<br \/>\n<\/h3>\n<p>N\u00e3o \u00e9 comum a jardinagem biol\u00f3gica com ou sem escava\u00e7\u00e3o. No entanto, a mat\u00e9ria org\u00e2nica rica em carbono s\u00f3 \u00e9 sequestrada no solo se puder mover-se no subsolo atrav\u00e9s das ra\u00edzes, insectos, e \u00e1gua.\n<\/p>\n<p>Se o seu solo for demasiado compactado para que as ra\u00edzes furem em profundidade com relativa facilidade, voc\u00ea&#8217;precisar\u00e1 de arejar, ligeiramente at\u00e9, ou cavar duas vezes para quebrar a compacta\u00e7\u00e3o antes de come\u00e7ar.\n<\/p>\n<h3>Passo 2: Popula\u00e7\u00e3o<br \/>\n<\/h3>\n<p>\u00c9 necess\u00e1rio aumentar a quantidade de micro-vida viva e morta no seu solo. A forma mais r\u00e1pida de o fazer \u00e9 adicionar adubo acabado.\n<\/p>\n<p>Composto com mais de um ano de idade \u00e9 melhor. Dessa forma, as bact\u00e9rias que amam o calor ter\u00e3o morrido e as bact\u00e9rias ben\u00e9ficas para o solo, frescas, ter\u00e3o come\u00e7ado a processar essas cabe\u00e7as quentes em h\u00famus.  Uma camada de tr\u00eas a quatro polegadas de espessura aplicada em cima da sua cama n\u00e3o compactada \u00e9 ideal.\n<\/p>\n<figure><img decoding=\"async\" src=\"https:\/\/my-garden.blog\/auto_content\/local_image\/7940068761152223.webp\" \/><\/figure>\n<p>Em alternativa, pode utilizar m\u00e9todos de compostagem no local, seguidos da planta\u00e7\u00e3o de uma cultura de cobertura como o trigo ou o rabanete da lavoura para acelerar as coisas. Aqui est\u00e3o algumas op\u00e7\u00f5es a considerar.\n<\/p>\n<ul>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Cubra o solo com 6-8 polegadas de cama de gado, grama cortada ou outros materiais org\u00e2nicos. <\/font><font style=\"vertical-align: inherit\">Quando os materiais estiverem quase totalmente decompostos, semeie sementes de cobertura na \u00e1rea.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Cave uma trincheira e encha-a com restos de cozinha e cubra com 4-6 polegadas de solo para continuar desenterrando as pragas. <\/font><font style=\"vertical-align: inherit\">Semear imediatamente culturas de cobertura em ambos os lados da trincheira.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Construa uma cama de lasanha com camadas de ervas daninhas, res\u00edduos vegetais da cozinha, cama de gado e outras mat\u00e9rias org\u00e2nicas cobertas com 4 polegadas de mistura de solo de jardim. <\/font><font style=\"vertical-align: inherit\">Inicie imediatamente uma cultura de cobertura.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Jardim em fardos de palha para come\u00e7ar e depois deixar os res\u00edduos de palha decomposta no solo. <\/font><font style=\"vertical-align: inherit\">Cultive uma cultura de cobertura nos fardos compostados gastos.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Construa uma pilha de compostagem em seu novo canteiro. <\/font><font style=\"vertical-align: inherit\">Quando estiver quase todo deteriorado, rasteje at\u00e9 4-6 polegadas de profundidade e cultive uma cultura de cobertura.<\/font><\/font><\/li>\n<\/ul>\n<h3>Passo 3: Estabilizar<br \/>\n<\/h3>\n<p>Depois de quebrar a compacta\u00e7\u00e3o e a carga pesada com carca\u00e7as microsc\u00f3picas, o objectivo de avan\u00e7ar \u00e9 fazer um ciclo em carbono novo a um ritmo est\u00e1vel. Aqui&#8217;s como fazer isso.\n<\/p>\n<ul>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Cultive o m\u00e1ximo de plantas que seu solo suportar, o m\u00e1ximo poss\u00edvel durante o ano, para manter o fluxo constante de exsudatos de carbono.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Deixe as partes da planta no solo para decomp\u00f4-las ou compost\u00e1-las, envelhecer o composto por 1 ano e depois aplicar. <\/font><font style=\"vertical-align: inherit\">(Compre composto envelhecido nesse \u00ednterim para usar at\u00e9 que o seu esteja pronto.)<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Se voc\u00ea colher materiais vegetais de seu jardim (por exemplo, como vegetais ou flores cortadas), substitua o que voc\u00ea remove por camadas leves de adubo verde (aparas de grama, culturas de cobertura), composto ou outras coberturas org\u00e2nicas (folhas, palha).<\/font><\/font><\/li>\n<\/ul>\n<p>Note-se tamb\u00e9m que, sempre que se verifica uma r\u00e1pida perda de carbono, as reac\u00e7\u00f5es qu\u00edmicas no solo despertar\u00e3o automaticamente as sementes de ervas daninhas adormecidas. Se n\u00e3o&#8217;n\u00e3o quer que as ervas daninhas venham ajud\u00e1-lo a jardinar, evite criar perda de carbono pelas vias mais comuns: oxida\u00e7\u00e3o e metaniza\u00e7\u00e3o.\n<\/p>\n<h2>Oxida\u00e7\u00e3o<br \/>\n<\/h2>\n<p>A oxida\u00e7\u00e3o acontece quando o carbono no solo \u00e9 exposto a grandes quantidades de ar. A escava\u00e7\u00e3o, a lavra e o arrancar de ra\u00edzes causam-no.\n<\/p>\n<p>Para o evitar, remover ervas daninhas quando elas&#8217;s\u00e3o pequenas e t\u00eam ra\u00edzes pouco profundas. Colher cuidadosamente as culturas para manter a terra no lugar, mesmo ao remover as ra\u00edzes dos vegetais. Repetir o corte das plantas maduras at\u00e9 \u00e0 coroa para as matar, em vez de as arrancar. Ou cobri-las com papel\u00e3o para as roubar o acesso \u00e0 luz.\n<\/p>\n<p>Al\u00e9m disso, quando se corta o fornecimento de exsudados de carbono deixando o solo sem planta\u00e7\u00e3o, a vida do solo consumir\u00e1 carbono j\u00e1 no solo. \u00c0 medida que v\u00e3o consumindo as reservas de carbono do solo, o ar vai-se deslocando para o espa\u00e7o esvaziado. Isso pode oxidar o solo a partir de dentro, mesmo quando n\u00e3o&#8217;t cultivam ou rasgam ra\u00edzes.\n<\/p>\n<p>Se por acaso precisar de uma pausa na jardinagem activa, encha os canteiros com culturas de cobertura ou perenes de baixa manuten\u00e7\u00e3o de curta dura\u00e7\u00e3o para manter esse fluxo cr\u00edtico de exsudados de carbono. Ou, espere que as ervas daninhas cheguem e fa\u00e7a este trabalho por si.\n<\/p>\n<h2>Metaniza\u00e7\u00e3o<br \/>\n<\/h2>\n<p>A metaniza\u00e7\u00e3o acontece quando o solo rico em carbono se torna anaer\u00f3bico ou combustivel.\n<\/p>\n<h3>Actividade anaer\u00f3bica<br \/>\n<\/h3>\n<p>Se se aplicar muito material rico em carbono mesmo antes de uma chuva encharcada, o material torna-se encharcado. Isso impede que o ar atinja o solo. Depois, as bact\u00e9rias que respiram o ar ficam adormecidas.\n<\/p>\n<p>As bact\u00e9rias anaer\u00f3bias acordam. Transformam o carbono em g\u00e1s metano que se evapora. Al\u00e9m disso, \u00e0 medida que o solo seca, os espa\u00e7os de ar deixados para tr\u00e1s ap\u00f3s a mecaniza\u00e7\u00e3o do carbono podem levar a uma maior oxida\u00e7\u00e3o.\n<\/p>\n<h3>Combust\u00e3o<br \/>\n<\/h3>\n<p>A combust\u00e3o com base no solo acontece quando se aplicam materiais ricos em carbono, como a cobertura morta ou o composto, e depois obt\u00e9m-se um influxo de azoto que desencadeia a compostagem a quente. O azoto prov\u00e9m frequentemente de fertilizantes, de uma chuva rica em azoto, ou de um rel\u00e2mpago. Tamb\u00e9m pode ser libertado por fungos que amam o carbono.\n<\/p>\n<p>Se ocorrer combust\u00e3o, aumenta a temperatura do solo e cozinha as plantas. Rouba o solo de \u00e1gua por evapora\u00e7\u00e3o r\u00e1pida e evapotranspira\u00e7\u00e3o. Al\u00e9m disso, liberta carbono para a atmosfera como metano, desencadeando ervas daninhas.\n<\/p>\n<p>Para evitar actividade anaer\u00f3bica e problemas de combust\u00e3o no solo, aplicar camadas leves de materiais ricos em carbono em tempo fresco e seco. Mover as palhas para fora do caminho antes da fertiliza\u00e7\u00e3o. Se o solo come\u00e7ar a aquecer ou a ficar pantanoso, remova esses materiais ricos em carbono. Em seguida, aplicar em camadas mais leves para a frente.\n<\/p>\n<h3>Passo 4: Aproveite os benef\u00edcios!<br \/>\n<\/h3>\n<p>Uma vez que voc\u00ea&#8217;tenha implantado com sucesso essas tr\u00eas primeiras etapas, com o tempo o seu solo ir\u00e1 sequestrar muito carbono est\u00e1vel. O seu conte\u00fado h\u00famico (e o ritmo a que \u00e9 produzido) ir\u00e1 aumentar. Isso levar\u00e1 a benef\u00edcios compostos. Por exemplo, solos com elevado conte\u00fado h\u00famico desenvolvem col\u00f3nias micorr\u00edzicas ben\u00e9ficas significativas.\n<\/p>\n<h2>Col\u00f3nias micorr\u00edzicas<br \/>\n<\/h2>\n<p>Estes fungos especiais desempenham um papel no fornecimento de nutrientes e \u00e1gua \u00e0s plantas a pedido. Al\u00e9m disso, podem controlar o sistema de sinaliza\u00e7\u00e3o baseado no solo que avisa as plantas de invas\u00f5es iminentes de pragas ou agentes patog\u00e9nicos.\n<\/p>\n<p>Mesmo quando as plantas n\u00e3o&#8217;t formam rela\u00e7\u00f5es espec\u00edficas com micorriza, esses pequenos fungos mant\u00eam o solo mais fresco durante os per\u00edodos de calor, reduzindo o stress das plantas. Al\u00e9m disso, ret\u00eam reservas de \u00e1gua perto das ra\u00edzes das plantas para ajudar durante as secas.\n<\/p>\n<h2>A liga\u00e7\u00e3o de nitrog\u00e9nio<br \/>\n<\/h2>\n<p>Os solos ricos em carbono com elevado teor h\u00famico e extensas col\u00f3nias micorr\u00edzicas tamb\u00e9m ret\u00eam mais azoto utiliz\u00e1vel pelas plantas. O nitrog\u00e9nio \u00e9 abundante na natureza. Entra no solo por estas vias.\n<\/p>\n<ul>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Mam\u00edferos e p\u00e1ssaros o jogam como esterco.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Os insetos o soltam como excremento.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Gotas de chuva pegam nitrog\u00eanio quando caem no solo.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">O nitrog\u00eanio transportado pelo ar no solo \u00e9 convertido em nitrog\u00eanio utiliz\u00e1vel pelas plantas por raios.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">As bact\u00e9rias processam o nitrog\u00eanio transportado pelo ar em formatos prontos para plantas.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">O nitrog\u00eanio contido nos corpos dos microrganismos \u00e9 liberado quando eles morrem.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">O nitrog\u00eanio na mat\u00e9ria vegetal morta \u00e9 reciclado para uso por plantas vivas.<\/font><\/font><\/li>\n<\/ul>\n<p>Infelizmente, estas fontes ou nitrog\u00e9nio s\u00e3o sol\u00faveis em \u00e1gua. Isso torna-as propensas a serem lavadas ou evaporadas antes das plantas terem a oportunidade de as utilizar. No entanto, o carbono e a micorriza actuam como esponjas para manter o azoto no solo.\n<\/p>\n<p>Isto significa que os jardins com solo rico em carbono ganharam&#8217;n\u00e3o precisam de muito (se algum) fertilizante. Uma vez que as aplica\u00e7\u00f5es de fertilizantes de ac\u00e7\u00e3o r\u00e1pida quase sempre desencadeiam a germina\u00e7\u00e3o de algumas sementes de ervas daninhas adormecidas, n\u00e3o as utilizar pode reduzir os custos e poupar tempo de mondadura!\n<\/p>\n<figure><img decoding=\"async\" src=\"https:\/\/my-garden.blog\/auto_content\/local_image\/8469204450009319.webp\" \/><\/figure>\n<h2>Bom para jardineiros<br \/>\n<\/h2>\n<p>Quando o seu solo \u00e9 rico em carbono, h\u00famus e micorrizas, as plantas s\u00e3o mais capazes de se cuidar a si pr\u00f3prias sem interven\u00e7\u00f5es constantes do jardineiro. Isso significa que pode relaxar no seu belo jardim em vez de ter problemas com plantas e arrancar ervas daninhas. E, tirar o carbono do ar e mergulhar profundamente no nosso solo \u00e9 uma grande forma de os jardineiros poderem ajudar a combater as altera\u00e7\u00f5es clim\u00e1ticas fazendo algo que amamos.\n<\/p>\n<p>Tasha Greer \u00e9 uma escritora e homesteader epicureana que vive no condado de Surry, Carolina do Norte. Ela&#8217;s a autora de Grow Your Own Spices and Weed-Free Gardening. Pode encontr\u00e1-la em Simplestead.com.\n<\/p>\n<p>Todos os bloggers da comunidade M\u00c3E TERRA concordaram em seguir as nossas Directrizes de Blogging, e s\u00e3o respons\u00e1veis pela exactid\u00e3o dos seus posts.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O solo de alta qualidade acontece quando se tem solos ricos em h\u00famus. Aprenda como adicionar carbono ao solo, e como adicionar nitrog\u00e9nio ao solo naturalmente para tornar o seu jardim mais saud\u00e1vel. Tirar o carbono do ar e entrar no nosso solo \u00e9&#8217; n\u00e3o \u00e9 apenas uma \u00f3ptima forma de os jardineiros ajudarem a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":79884,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[118],"tags":[],"class_list":["post-79873","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-gardening-techniques"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts\/79873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/comments?post=79873"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/posts\/79873\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/media\/79884"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/media?parent=79873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/categories?post=79873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/pt\/wp-json\/wp\/v2\/tags?post=79873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}