{"id":116,"count":350,"description":"","link":"https:\/\/my-garden.blog\/lv\/category\/garden-planning\/","name":"planificaci\u00f3n de jardi","slug":"garden-planning","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/lv\/wp-json\/wp\/v2\/categories\/116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/lv\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/my-garden.blog\/lv\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/my-garden.blog\/lv\/wp-json\/wp\/v2\/posts?categories=116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}