{"id":81635,"date":"2023-03-07T11:20:37","date_gmt":"2023-03-07T08:20:37","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/it-ambienti-artificiali-e-proliferazione-della-canapa-industriale\/"},"modified":"2023-03-07T11:20:37","modified_gmt":"2023-03-07T08:20:37","slug":"it-ambienti-artificiali-e-proliferazione-della-canapa-industriale","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/it\/2023\/03\/07\/it-ambienti-artificiali-e-proliferazione-della-canapa-industriale\/","title":{"rendered":"Ambienti artificiali e proliferazione della canapa industriale"},"content":{"rendered":"<p>Cannabis: Evolution and Ethnobotany(University of California Press, 2016) di Robert Clarke&nbsp;e Mark Merlin\u00e8 un'esplorazione completa e interdisciplinare delle origini naturali e della prima evoluzione di questa famosa pianta, evidenziandone il ruolo storico nello sviluppo delle societ\u00e0 umane. Questa sezione proviene dal capitolo &ldquo;La diffusione culturale della cannabis&rdquo;.\n<\/p>\n<p>Verso la fine del secondo millennio e nel ventunesimo secolo, la produzione di Cannabis ha subito cambiamenti significativi che continueranno a indirizzare l'evoluzione e la diffusione delle variet\u00e0 di canapa e marijuana anche nel prossimo futuro. I procedimenti penali per la coltivazione di Cannabis stupefacente nei Paesi occidentali prevedevano pene sempre pi\u00f9 severe e i coltivatori clandestini spostavano le loro coltivazioni al chiuso, in condizioni di crescita artificiale, per evitare di essere scoperti dalle forze dell'ordine. Allo stesso tempo, la canapa industriale ha ottenuto un nuovo status legale in molte giurisdizioni; di conseguenza, la coltivazione commerciale di fibre e semi si \u00e8 diffusa in tutta Europa, la produzione di semi \u00e8 iniziata in Canada e Nuova Zelanda e sono stati avviati progetti di sperimentazione e di allevamento della canapa in molte localit\u00e0. Anche Paesi asiatici come la Cina hanno ampliato la produzione di canapa per soddisfare la crescente domanda del mercato occidentale. Si stanno sviluppando nuove variet\u00e0 di fibre e semi di canapa industriale utilizzando ibridi interspecie tra C. sativa ssp. sativa NLH e C. indica ssp. chinenesis BLH, con l'intenzione di espandere la produzione di canapa industriale in aree pi\u00f9 equatoriali dove le attuali cultivar europee NLH non crescono bene. La selezione della cannabis medica ha puntato ad aumentare i livelli di THC e di altri cannabinoidi, nonch\u00e9 a profili terpenoidi unici. Tuttavia, gli Stati Uniti, nonostante siano diventati il pi\u00f9 grande importatore mondiale di fibre e semi di canapa, ancora resistono alla legalizzazione della coltivazione della canapa industriale. Tutte queste tendenze derivano da cambiamenti nella legalit\u00e0 della Cannabis, restrittivi o favorevoli, nelle societ\u00e0 occidentali. Ci\u00f2 ha comportato sia l'inasprimento delle leggi per frenare la produzione illegale di droghe, sia l'accettazione della canapa come coltura industriale praticabile e la conseguente modifica delle leggi nazionali sulle droghe e dei trattati internazionali per consentirne la coltivazione.\n<\/p>\n<p>Le variet\u00e0 di sinsemilla BLD &times; NLD nordamericane ed europee sono oggi comunemente coltivate nella maggior parte delle nazioni occidentali, comprese Australia e Nuova Zelanda. Gli ibridi moderni e le variet\u00e0 esotiche raggiungono spesso le culture agricole rurali dei Paesi in via di sviluppo, dove un tempo i contadini coltivavano le loro variet\u00e0 tradizionali di fibre e droghe, e negli ultimi anni i semi ibridi prodotti in Nord America e in Europa sono stati coltivati sempre pi\u00f9 spesso nei Paesi produttori tradizionali di marijuana e hashish (per esempio, Messico, Marocco, Nepal, Giamaica, Colombia e Thailandia). La coltivazione tradizionale all'aperto, cos\u00ec come la coltivazione indoor a luce artificiale di variet\u00e0 ibride appositamente selezionate, continuer\u00e0 ad aumentare in tutto il mondo con l'espansione del mercato della marijuana e dell'hashish di alta qualit\u00e0. Con la crescente diffusione di semi esotici nelle regioni di coltivazione commerciale, le variet\u00e0 introdotte si ibridano con le variet\u00e0 tradizionali consolidate. Di conseguenza, le variet\u00e0 locali geneticamente pure vengono contaminate dai geni introdotti e si estinguono. Sebbene la Cannabis nel suo complesso fiorisca in tutto il mondo e sia ben lontana dall'estinguersi, abbiamo perso gran parte della diversit\u00e0 genetica degli anni '70 e '80, quando le variet\u00e0 autoctone erano comunemente coltivate da culture agricole tradizionali in habitat geografici isolati e le nuove introduzioni di semi in Occidente da fonti straniere avvenivano frequentemente. In cambio, gli allevatori di semi occidentali (attraverso i coltivatori di marijuana e i contrabbandieri) hanno introdotto le loro variet\u00e0 ibride &ldquo;migliorate&rdquo; nelle culture tradizionali di coltivazione della cannabis e hanno involontariamente contribuito all'estinzione delle loro variet\u00e0 landrace preferite.\n<\/p>\n<p>Le coltivazioni di marijuana in serra e con luce artificiale sono ora pi\u00f9 comunemente coltivate da talee ibride BLD e NLD riprodotte per via vegetativa, e i semi sono raramente utilizzati se non per coltivare talee di ricambio. Questo limita il miglioramento delle colture attraverso la selezione selettiva, poich\u00e9 i semi sono raramente utilizzati o prodotti e, di conseguenza, la riproduzione sessuale si interrompe e l'evoluzione cessa o, certamente, rallenta drasticamente. Tuttavia, i selezionatori di sinsemilla continuano a sviluppare variet\u00e0 a maturazione precoce e ad alta resa, corte e compatte per l'uso in grow room e per evitare di essere individuati all'aperto. Dagli anni '90, le coltivazioni indoor di marijuana sinsemilla sono state coltivate per presunto uso medico, dato che le giurisdizioni statali e locali del Nord America e dell'Europa riconoscono sempre pi\u00f9 la cannabis medica come una questione separata dall'uso ricreativo e legiferano di conseguenza. La diffusione di cloni prodotti per via vegetativa in ambienti artificiali durante la Fase 6 ha aumentato il raggio d'azione della cannabis nelle aree urbane, dove acqua, elettricit\u00e0, input agricoli e privacy sono tutti facilmente disponibili. Questo ha finalmente portato almeno alcune variet\u00e0 di Cannabis stupefacente alla piena domesticazione e quindi alla completa dipendenza dall'uomo per la loro sopravvivenza e proliferazione. Inoltre, ha reso la produzione illecita di cannabis stupefacente ancora pi\u00f9 difficile da controllare.\n<\/p>\n<p>Altro da Cannabis: Evoluzione ed etnobotanica:\n<\/p>\n<ul>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Semi di canapa come nutrimento per l'uomo &nbsp;<\/font><\/font><\/li>\n<\/ul>\n<p>Estratto da Cannabis: Evolution and Ethnobotany (2016) di Robert Clarke e Mark Merlin con il permesso della University of California Press.\n<\/p>\n<p>Video correlati: Ottenere un permesso per la canapa industriale\n<\/p>\n<p>Iscrivetevi al nostro canale YouTube per altri fantastici video.\n<\/p>\n<p>&nbsp;\n<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cannabis: Evolution and Ethnobotany(University of California Press, 2016) di Robert Clarke&nbsp;e Mark Merlin\u00e8 un'esplorazione completa e interdisciplinare delle origini naturali e della prima evoluzione di questa famosa pianta, evidenziandone il ruolo storico nello sviluppo delle societ\u00e0 umane. Questa sezione proviene dal capitolo &ldquo;La diffusione culturale della cannabis&rdquo;. Verso la fine del secondo millennio e nel [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81652,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[119],"tags":[],"class_list":["post-81635","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-herbs"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/posts\/81635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/comments?post=81635"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/posts\/81635\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/media\/81652"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/media?parent=81635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/categories?post=81635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/tags?post=81635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}