{"id":81063,"date":"2023-03-07T11:05:48","date_gmt":"2023-03-07T08:05:48","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/it-cultivar-autoctone\/"},"modified":"2023-03-07T11:05:48","modified_gmt":"2023-03-07T08:05:48","slug":"it-cultivar-autoctone","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/it\/2023\/03\/07\/it-cultivar-autoctone\/","title":{"rendered":"Cultivar autoctone"},"content":{"rendered":"<p>In questa stagione mi sto concentrando sulle cultivar autoctone.\n<\/p>\n<p>Le cultivar autoctone per me significano piantare un orto adattato al clima del luogo in cui vivo.  \u00c8 una proposta molto eccitante. Ho fatto giardinaggio in Iowa o in California e questa \u00e8 la prima volta che ho la possibilit\u00e0 di piantare al 100% piante autoctone.\n<\/p>\n<p>L'alto deserto del sud-est dell'Arizona \u00e8 un mondo completamente nuovo.  Fortunatamente, persone incredibilmente intelligenti e resilienti mi hanno preceduto, quindi non ho dovuto imparare tutto da zero. Nel corso di migliaia di anni di vita in questo clima, le popolazioni native del sud-ovest hanno capito quali sono gli alimenti nutrienti e soddisfacenti che si possono coltivare facilmente.\n<\/p>\n<p>Inizio con: Anguria Mayo, meloni Santo Domingo, mais dolce Anasazi, popcorn Navajo, amaranto e fagioli tepari.\n<\/p>\n<p>Quali sono i frutti e gli ortaggi autoctoni che potete coltivare e che si adattano al clima della vostra zona? Ecco un breve elenco per ispirarvi:\n<\/p>\n<p>Persimmon americano: \u00e8 originario della Florida e del Connecticut, a ovest dell'Iowa e a sud del Texas. Ha un alto contenuto di vitamine A e C, fibre e antiossidanti, e un basso contenuto di calorie e grassi. Gli alberi sono a bassa manutenzione. I frutti sono utilizzati per preparare dolci, pane, zuppe, gelati e caramelle.\n<\/p>\n<p>Camas blu: Originaria del Pacifico nordoccidentale, dalle Montagne Rocciose del Canada fino alla California e allo Utah, la cama blu ha radici ricche di carboidrati e proteine. Cuocete i bulbi in un forno lento per renderli commestibili e dolci.\n<\/p>\n<p>Zucca Candy Roaster: Coltivata per la prima volta dalle trib\u00f9 Cherokee dei Monti Appalachi meridionali. Usata in zuppe, torte, burri e pane, viene ancora coltivata secondo la pratica tradizionale delle Tre Sorelle, in cui zucca, mais e fagioli vengono coltivati insieme per prevenire le erbacce e mantenere l'umidit\u00e0 del terreno.\n<\/p>\n<p>Peperone Chiltepin: Si tratta di peperoncini selvatici molto piccanti che crescono nel sud-ovest degli Stati Uniti e da cui provengono i peperoni domestici. Sono molto piccanti e pungenti e possono essere consumati essiccati al sole, aggiunti a formaggi e gelati o fermentati in salse.\n<\/p>\n<p>Mirtillo rosso a cespuglio: Non \u00e8 un vero e proprio mirtillo rosso, ma pu\u00f2 essere coltivato. \u00c8 originario di tutto il confine del Canada. Pu\u00f2 crescere senza irrigazione, fertilizzazione o altre pratiche agricole invasive o intensive. Le bacche vengono consumate crude o utilizzate per preparare marmellate, gelatine, salse e vini di frutta.\n<\/p>\n<p>Mesquite: Questo piccolo albero \u00e8 originario del sud-ovest. I baccelli dei semi possono essere macinati e utilizzati per preparare torte e focacce o per addensare stufati. Dai fiori e dalle foglie si ricava il t\u00e8. Il t\u00e8 ai fiori pu\u00f2 avere propriet\u00e0 lassative e antidolorifiche.\n<\/p>\n<p>Testa di violino di felce di struzzo: Queste piante crescono nel nord-est. \u00c8 l'unico ortaggio nativo del Canada ad essere stato commercializzato con successo. Originariamente veniva raccolto dai Mi&#8217;kmaq del Canada orientale e del Maine. Ha un sapore simile a quello degli asparagi, con in pi\u00f9 una qualit\u00e0 di nocciola. Bollire o cuocere a vapore prima di mangiarli. Sono una buona fonte di proteine, manganese e ferro. Sono anche ricchi di antiossidanti, acidi grassi omega-3 e fibre.\n<\/p>\n<p>Zampone: Le zampone sono il pi\u00f9 grande frutto commestibile originario del Nord America. Sono originari degli Stati del sud-est. Hanno un sapore tropicale che ricorda il mango e la banana e sono una buona fonte di vitamine e minerali. Si possono usare per fare pane, torte, marmellata e birra.\n<\/p>\n<p>Mais Selce di Calais: Originariamente coltivato dagli Abenaki del Vermont, questo mais cresce bene in aree come il confine tra Stati Uniti e Canada, caratterizzate da climi freddi e stagioni di crescita brevi. \u00c8 pi\u00f9 saporito di altri tipi di mais prodotti industrialmente e viene utilizzato per produrre farina di mais, farina e hominy.\n<\/p>\n<p>Zucca Seminole: Questa zucca \u00e8 originaria della regione delle Everglades, nel sud della Florida. Tollera il caldo, la siccit\u00e0, gli insetti e l'oidio. Pu\u00f2 essere cucinata al forno, bollita, schiacciata o utilizzata per preparare torte e pane. I semi possono essere arrostiti o decorticati e macinati. I giovani germogli e le foglie possono essere cucinati come le verdure, mentre i fiori possono essere fritti per preparare frittelle.\n<\/p>\n<p>Amaranto: \u00c8 un alimento base delle popolazioni preispaniche dal Messico al Per\u00f9. Cresce bene nelle regioni aride, \u00e8 privo di glutine, ricco di proteine e le sue foglie contengono livelli di ferro superiori a quelli degli spinaci. Le foglie sono utilizzate nelle insalate e nelle zuppe. I semi possono essere tostati e utilizzati nei dolci. Se mescolata con la farina di mais, la farina di amaranto viene utilizzata per preparare tortillas, torte e biscotti.\n<\/p>\n<p>Fagioli Tepary: Questi fagioli sono originari del deserto del sud-ovest degli Stati Uniti e del Messico nord-occidentale. Sono stati importanti per la dieta delle popolazioni del deserto per migliaia di anni. Sono molto tolleranti al caldo, alla siccit\u00e0 e ai terreni alcalini. Non sono adatti a climi umidi o a terreni argillosi. I fagioli contengono alti livelli di proteine e fibre solubili, che aiutano a controllare il colesterolo e il diabete.\n<\/p>\n<p>Ramponi: I rampi sono cipolle selvatiche perenni che crescono nel Nord America orientale e sono facilmente coltivabili nel vostro giardino. Venivano raccolte dai nativi americani come cibo e medicina. Le foglie, i gambi e i bulbi sono commestibili e possono essere consumati crudi o cotti.\n<\/p>\n<p>Per un'ampia variet\u00e0 di sementi adattate alle regioni desertiche, alte e basse, visitate questo sito di Native Seeds con sede a Tucson, in Arizona.\n<\/p>\n<p>Ren\u00e9e Benoit vive nel sud-est dell'Arizona. Dal suo salotto si vede il Messico! Lei e il suo compagno Marty stanno trasformando la loro propriet\u00e0 in una fattoria sostenibile. Al momento hanno 2 cani, 2 cavalli e 1 gatto a far loro compagnia. Le piace anche viaggiare in nuovi luoghi alla scoperta di cibi autoctoni e della fauna selvatica. Scrive saggistica creativa e nel tempo libero si dedica al giardinaggio, alle escursioni, alla lettura, alla cucitura, all'inscatolamento, alla fermentazione, al forno, alla cucina e al feltro ad ago.\n<\/p>\n<p>Tutti i blogger della comunit\u00e0 di MOTHER EARTH NEWS hanno accettato di seguire le nostre Linee guida per i blog e sono responsabili dell'accuratezza dei loro post.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In questa stagione mi sto concentrando sulle cultivar autoctone. Le cultivar autoctone per me significano piantare un orto adattato al clima del luogo in cui vivo. \u00c8 una proposta molto eccitante. Ho fatto giardinaggio in Iowa o in California e questa \u00e8 la prima volta che ho la possibilit\u00e0 di piantare al 100% piante autoctone. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81080,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[116],"tags":[],"class_list":["post-81063","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-garden-planning"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/posts\/81063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/comments?post=81063"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/posts\/81063\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/media\/81080"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/media?parent=81063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/categories?post=81063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/tags?post=81063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}