{"id":80777,"date":"2023-03-07T10:56:03","date_gmt":"2023-03-07T07:56:03","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/it-il-coleottero-degli-asparagi-consigli-per-la-lotta-biologica\/"},"modified":"2023-03-07T10:56:03","modified_gmt":"2023-03-07T07:56:03","slug":"it-il-coleottero-degli-asparagi-consigli-per-la-lotta-biologica","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/it\/2023\/03\/07\/it-il-coleottero-degli-asparagi-consigli-per-la-lotta-biologica\/","title":{"rendered":"Il coleottero degli asparagi: Consigli per la lotta biologica"},"content":{"rendered":"<p>Questo articolo fa parte della nostra serie di articoli sulla lotta biologica ai parassiti, che comprende articoli sull'attrazione degli insetti utili, sul controllo di specifici parassiti del giardino e sull'uso di pesticidi biologici;\n<\/p>\n<p>I coleotteri degli asparagi, i pi\u00f9 comuni tra i parassiti degli asparagi, indeboliscono le piante quando si nutrono di adulti e larve. I metodi biologici di controllo degli asparagi comprendono la raccolta a mano, la raccolta e il compostaggio del fogliame e delle bacche di asparagi vecchi. Originario dell'Europa, il coleottero dell'asparago \u00e8 oggi presente in tutto il Nord America, ovunque si coltivino asparagi.\n<\/p>\n<h2>Cosa sono i coleotteri degli asparagi?<br \/>\n<\/h2>\n<p>Il coleottero degli asparagi (Crioceris asparagi) \u00e8 il parassita degli asparagi pi\u00f9 diffuso e danneggia i giovani turioni. Questo coleottero snello e allungato, che sverna come adulto, presenta quattro macchie bianche o giallastre sulle ali, \u00e8 rossastro sotto e sui bordi delle ali e ha un torace rosso scuro. \u00c8&nbsp;1\n<\/p>\n<p>Anche il coleottero degli asparagi (Crioceris duodecimpunctata) \u00e8 piuttosto colorato. Negli Stati Uniti occidentali, l'asparago maculato \u00e8 di colore arancione zucca brillante con piccoli punti neri sulle ali. In altre zone, il colore di fondo degli asparagi maculati pu\u00f2 essere dal rosso al rosso scuro. Le antenne di entrambi i parassiti degli asparagi misurano circa la met\u00e0 della lunghezza del corpo.\n<\/p>\n<h2>Danni da coleottero degli asparagi&nbsp;<br \/>\n<\/h2>\n<p>All'inizio della primavera, proprio quando gli asparagi stanno spuntando in superficie, i coleotteri adulti degli asparagi emergono dopo aver svernato nei detriti vegetali. Cominciano a nutrirsi dei primi turioni, facendoli incurvare come un bastone da pastore. Poco dopo l'accoppiamento, le femmine depongono piccole uova scure e allungate sulle piccole lance e sul nuovo fogliame, che sporgono ad angolo retto. Gli adulti si nutrono delle lance principali, mentre le larve grigio-verdi, dal corpo molle, si nutrono di lance e fogliame. Le fenditure causate dall'alimentazione sono di colore marrone e riducono il vigore e le dimensioni delle lance colpite. Una forte alimentazione riduce il vigore delle piante di asparagi.\n<\/p>\n<p>Gli adulti degli asparagi maculati emergono da una a tre settimane pi\u00f9 tardi rispetto agli asparagi comuni. In tarda primavera, questi parassiti degli asparagi possono essere trovati su tutte le piante di asparagi, ma di solito causano solo danni minori. Il ciclo di deposizione delle uova coincide con la formazione delle bacche di asparago. Gli adulti depongono le uova sulle bacche o in prossimit\u00e0 di esse, le larve penetrano all'interno per nutrirsi e poi cadono a terra per impuparsi e diventare adulti. Le larve si nutrono solo all'interno delle bacche. Le larve di asparago macchiato sono giallastre con testa e zampe nere.\n<\/p>\n<h2>Riproduzione del coleottero degli asparagi&nbsp;<br \/>\n<\/h2>\n<p>Poco dopo la comparsa in primavera, i coleotteri dell'asparago depongono le uova sui turioni emergenti, che si schiudono in tre-otto giorni. Le piccole larve dal corpo morbido e grigiastro si nutrono della tenera nuova crescita in primavera. Pi\u00f9 tardi, in estate, si possono trovare uova e larve che si nutrono del fogliame degli asparagi. Quando le larve maturano dopo circa due settimane di alimentazione, cadono a terra e si impupano all'interno di una cella di terra per sette-dieci giorni prima di emergere come adulti. Nella maggior parte dei climi si verificano due generazioni all'anno, ma nei climi caldi le generazioni di questo parassita degli asparagi possono arrivare fino a cinque.\n<\/p>\n<p>I coleotteri degli asparagi emergono a met\u00e0 primavera e iniziano subito a mangiare il fogliame degli asparagi, ma aspettano che le piante di asparagi sviluppino le bacche per deporre le uova. Dopo la schiusa delle uova, le larve penetrano nelle bacche per nutrirsi.\n<\/p>\n<h2>Nemici naturali dei coleotteri degli asparagi&nbsp;<br \/>\n<\/h2>\n<p>Gli uccelli si nutrono spesso di coleotteri e larve di asparagi, che compaiono durante la stagione della nidificazione, quando gli uccelli hanno bisogno di pi\u00f9 proteine.&nbsp;Le coccinelle mangiano le giovani larve, ma il predatore pi\u00f9 efficace \u00e8 la piccola vespa Eulophid nera ( Tetrastichus asparagi ), che mangia le uova di coleottero degli asparagi all'inizio della stagione e depone le uova nelle uova di coleottero degli asparagi in estate. Questo insetto benefico, cos\u00ec utile per il controllo del coleottero degli asparagi, \u00e8 stato identificato nel Massachusetts nel 1915 ed \u00e8 ora presente ovunque si coltivino asparagi. Attualmente non \u00e8 in vendita a livello commerciale.\n<\/p>\n<h2>Controllo biologico del coleottero degli asparagi<br \/>\n<\/h2>\n<p>Quando si ha a che fare con il coleottero degli asparagi, i metodi di lotta biologica possono essere molto efficaci. Uno dei punti chiave&nbsp;\u00e8 quello di rimuovere i residui vegetali dall'appezzamento in autunno e compostarli in un cumulo di compost attivo. Larve e adulti possono essere rimossi a mano. Quando si raccolgono a mano, \u00e8 bene mettere a terra un secchio d'acqua: molti coleotteri vi cadranno dentro quando vengono colpiti dalle piante. Le vespe benefiche parassitano le uova dei coleotteri. Anche le galline fanno un buon lavoro nel raccogliere i coleotteri degli asparagi quando vengono lasciate libere di razzolare nell'appezzamento alla fine dell'estate. In situazioni gravi, \u00e8 possibile ottenere un buon controllo organico dei coleotteri degli asparagi spruzzando le piante con&nbsp;neem all'inizio della stagione, quando le popolazioni sono modeste. Non utilizzate il neem o qualsiasi altro pesticida se nella vostra asparagiaia sono presenti piccole vespe nere.\n<\/p>\n<p>I coleotteri degli asparagi saranno scoraggiati se le piante di asparagi sono cultivar di soli maschi che non producono bacche. Se le vostre piante producono bacche, raccogliete e compostate tutte le bacche di asparagi se sono stati avvistati coleotteri degli asparagi maculati. Questa \u00e8 la migliore lotta biologica contro il coleottero degli asparagi.\n<\/p>\n<h2>Altri&nbsp;Consigli per la lotta biologica ai parassiti per&nbsp;i coleotteri degli asparagi<br \/>\n<\/h2>\n<p>Riducete le popolazioni di adulti svernanti di entrambi i parassiti degli asparagi mantenendo l'area circostante leggermente lavorata ed eliminando i residui vegetali. Questo costringe i coleotteri degli asparagi a svernare nel terreno, dove i predatori sotterranei li divorano.\n<\/p>\n<p>All'inizio della primavera, tagliare prontamente i turioni a livello del terreno con un coltello affilato. Una raccolta attenta impedir\u00e0 a molte uova di coleottero degli asparagi di schiudersi.\n<\/p>\n<p>Entrambi i tipi di coleotteri degli asparagi possono essere facilmente raccolti a mano. L'istinto di un coleottero \u00e8 quello di cadere a terra quando si sente disturbato, quindi tenete un contenitore d'acqua sotto la pianta prima di scuoterla delicatamente: gli insetti cadranno nell'acqua. Anche un foglio di giornale o una scatola per la pizza funzionano bene.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questo articolo fa parte della nostra serie di articoli sulla lotta biologica ai parassiti, che comprende articoli sull'attrazione degli insetti utili, sul controllo di specifici parassiti del giardino e sull'uso di pesticidi biologici; I coleotteri degli asparagi, i pi\u00f9 comuni tra i parassiti degli asparagi, indeboliscono le piante quando si nutrono di adulti e larve. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":80794,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121],"tags":[],"class_list":["post-80777","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-pest-control"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/posts\/80777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/comments?post=80777"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/posts\/80777\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/media\/80794"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/media?parent=80777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/categories?post=80777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/it\/wp-json\/wp\/v2\/tags?post=80777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}