{"id":82011,"date":"2023-03-07T11:40:07","date_gmt":"2023-03-07T08:40:07","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/fr-inspiration-pour-les-amenagements-paysagers-comestibles\/"},"modified":"2023-03-07T11:40:07","modified_gmt":"2023-03-07T08:40:07","slug":"fr-inspiration-pour-les-amenagements-paysagers-comestibles","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/fr\/2023\/03\/07\/fr-inspiration-pour-les-amenagements-paysagers-comestibles\/","title":{"rendered":"Inspiration pour les am\u00e9nagements paysagers comestibles"},"content":{"rendered":"<p>Imaginez que notre gouvernement nous demande de r\u00e9pondre \u00e0 la crise du r\u00e9chauffement climatique, \u00e0 la rar\u00e9faction du p\u00e9trole et \u00e0 la d\u00e9t\u00e9rioration de la sant\u00e9 en plantant des jardins potagers ;\n<\/p>\n<p>Ceux qui ont v\u00e9cu aux \u00c9tats-Unis et en Grande-Bretagne pendant la Seconde Guerre mondiale et ont connu le rationnement alimentaire des ann\u00e9es 1940 peuvent faire plus qu'imaginer, ils peuvent se souvenir. Dans le cadre de l'effort de guerre, tous les civils \u00e9taient encourag\u00e9s \u00e0 transformer leurs terrains et leurs pelouses &mdash ; litt\u00e9ralement &mdash ; en cultures vivri\u00e8res pour eux-m\u00eames et pour les troupes. Les millions de cours, de terrains vagues, de pelouses et de plates-bandes am\u00e9nag\u00e9es dans les centres communautaires, les terrains de jeu des \u00e9coles et les lieux de culte ont \u00e9t\u00e9 appel\u00e9s \"jardins de la victoire\" et ont constitu\u00e9, pendant de nombreuses ann\u00e9es, une source essentielle de fruits, de l\u00e9gumes, de noix et de l\u00e9gumineuses difficiles \u00e0 produire en temps de guerre en raison de la r\u00e9duction de la main-d'\u0153uvre et du rationnement de l'essence.\n<\/p>\n<p>Les voisins partageaient et \u00e9changeaient leurs produits entre eux, les fruits et l\u00e9gumes de l'\u00e9t\u00e9 \u00e9taient mis en conserve ou mis de c\u00f4t\u00e9 pour l'hiver, et de nombreux Am\u00e9ricains se sont mis \u00e0 manger des produits locaux d'une mani\u00e8re qui n'avait pas \u00e9t\u00e9 vue depuis que leurs anc\u00eatres avaient immigr\u00e9 dans ce pays.\n<\/p>\n<p>Si l'id\u00e9e de manger des aliments locaux et les sujets qui s'y rapportent (pr\u00e9occupations relatives \u00e0 la disponibilit\u00e9 et \u00e0 l'accessibilit\u00e9 des aliments, ainsi qu'aux co\u00fbts environnementaux et mon\u00e9taires \u00e9lev\u00e9s du transport des aliments sur de grandes distances) vous semblent familiers, c'est probablement parce que ces questions ont fait la une de l'actualit\u00e9 au cours des derni\u00e8res ann\u00e9es. Pour de nombreux lecteurs de MOTHER EARTH NEWS et un nombre croissant d'auteurs, d'activistes de l'alimentation et d'experts en jardinage, l'automne est le moment de l'ann\u00e9e o\u00f9 l'on recommence \u00e0 retourner nos pelouses, \u00e0 la recherche d'une sant\u00e9 \u00e9conomique, environnementale et physique.\n<\/p>\n<p>L'auteur et activiste communautaire Heather Flores et son livre Food Not Lawns : How To Turn Your Yard Into a Garden and Your Neighborhood Into a Community (De la nourriture pas des pelouses : comment transformer votre jardin en un jardin et votre quartier en une communaut\u00e9) \u00e9tait un appel radical aux citadins am\u00e9ricains pour qu'ils transforment leurs pelouses entretenues et leurs arri\u00e8re-cours en jardins produisant de la nourriture pour le b\u00e9n\u00e9fice non seulement de l'habitant mais aussi de la communaut\u00e9 dans son ensemble. Si l'id\u00e9e semblait un peu r\u00e9volutionnaire \u00e0 l'\u00e9poque o\u00f9 le livre a \u00e9t\u00e9 publi\u00e9, elle semble aujourd'hui trouver un \u00e9cho chez les Am\u00e9ricains d'une mani\u00e8re in\u00e9dite depuis la Seconde Guerre mondiale.\n<\/p>\n<h2>Jardins de Descanso : D'abord l'art, puis le militantisme<br \/>\n<\/h2>\n<p>Les jardins de Descanso, un jardin public de 150 acres situ\u00e9 \u00e0 seulement 20 minutes du centre-ville de Los Angeles, sont une vitrine des expositions botaniques formelles depuis plus de quatre d\u00e9cennies. En 2008, \u00e0 la suite d'un s\u00e9minaire organis\u00e9 sur place par l'architecte local Fritz Haeg, un changement majeur a \u00e9t\u00e9 apport\u00e9 au Center Circle de Descanso, la premi\u00e8re zone de pr\u00e9sentation que les visiteurs voient en entrant dans les jardins. Il a \u00e9t\u00e9 d\u00e9moli et remplac\u00e9 par un jardin comparatif c\u00f4te \u00e0 c\u00f4te comprenant une pelouse entretenue et un jardin comestible.\n<\/p>\n<p>Bien qu'ayant re\u00e7u une formation d'architecte, Haeg avait pass\u00e9 les derni\u00e8res ann\u00e9es en tant qu'artiste d'exposition. Lors d'une exposition particuli\u00e8re au Kansas, l'id\u00e9e de cr\u00e9er un \"domaine comestible\", ou une cour d'entr\u00e9e comestible semblable \u00e0 un jardin de la victoire, a fait son chemin. En fait, l'exposition de 2005 a \u00e9t\u00e9 si populaire que l'installation a donn\u00e9 naissance \u00e0 des projets similaires pour Haeg en Californie du Sud, dans le New Jersey, \u00e0 Austin, au Texas, \u00e0 Baltimore et \u00e0 Londres. Le succ\u00e8s de chaque projet a incit\u00e9 Haeg \u00e0 faire une chronique de ces exp\u00e9riences dans Edible Estates : Attack on the Front Lawn, et a donn\u00e9 lieu \u00e0 une tourn\u00e9e du livre qui a amen\u00e9 Haeg \u00e0 Descanso Gardens.\n<\/p>\n<p>Brian Sullivan, l'horticulteur principal des jardins de Descanso responsable de la planification des nouvelles expositions, a \u00e9t\u00e9 inspir\u00e9 par l'argument de Haeg en faveur des am\u00e9nagements paysagers comestibles. \u00c0 une \u00e9poque o\u00f9 les gens s'inqui\u00e8tent du co\u00fbt de la nourriture, de la s\u00e9curit\u00e9 de ce qu'ils mangent, de l'impact de l'importation de nourriture sur de longues distances et du co\u00fbt du carburant, pourquoi ne proposerions-nous pas une exposition qui permette aux visiteurs de voir par eux-m\u00eames les options dont ils disposent pour am\u00e9liorer leur vie et leur mode de vie ?\n<\/p>\n<p>C'est ainsi qu'est n\u00e9 le jardin de d\u00e9monstration des Domaines comestibles. Le squelette d'une petite maison qui symbolise le foyer am\u00e9ricain est flanqu\u00e9 d'une pelouse ordinaire et d'une pelouse comestible, ou potager. Les deux pelouses sont surveill\u00e9es par l'\u00e9quipe d'horticulture de Descanso&rsquo;et par des \u00e9coliers locaux, qui mesurent la quantit\u00e9 d'eau, d'engrais, de travail et de carburant que chaque pelouse n\u00e9cessite. Ils mesurent \u00e9galement les r\u00e9sultats : les aliments r\u00e9colt\u00e9s, les d\u00e9chets verts et la biodiversit\u00e9.\n<\/p>\n<p>Au milieu du printemps, sous les temp\u00e9ratures d\u00e9j\u00e0 chaudes de la Californie du Sud, le jardin de d\u00e9monstration produisait des l\u00e9gumes verts pr\u00e9coces, des haricots, des fraises, des herbes et des fleurs comestibles. Certaines plantes qui avaient pass\u00e9 l'hiver ont \u00e9t\u00e9 autoris\u00e9es \u00e0 monter en graines pour que les \u00e9l\u00e8ves puissent en tirer des enseignements et parce que Mme Haeg les trouve belles.\n<\/p>\n<p>La plupart des visiteurs du jardin s'attendent \u00e0 voir des jardins botaniques immacul\u00e9s et incroyablement soign\u00e9s, ainsi que de vastes pelouses ouvertes, comme c'est g\u00e9n\u00e9ralement le cas dans un espace public urbain tel que les jardins de Descanso, explique M. Haeg. Ils entrent ensuite dans le jardin comestible et d\u00e9couvrent un autre type de beaut\u00e9. Le jardin offre une vari\u00e9t\u00e9 de couleurs, de formes et de textures qui est tout aussi \u00e9tonnante &mdash ; parfois plus &mdash ; que ce que l'on voit habituellement dans une cour d'entr\u00e9e. En plus, c'est comestible ! Nous demandons aux gens de red\u00e9finir dans leur esprit et dans leur communaut\u00e9 ce qu'est la \"beaut\u00e9\" ;\n<\/p>\n<h2>Jardins de d\u00e9monstration : Apprentissage par l'exp\u00e9rience<br \/>\n<\/h2>\n<p>L'une des beaut\u00e9s ind\u00e9niables que l'on trouve dans le jardin de d\u00e9monstration est le parfum. Une vari\u00e9t\u00e9 d'arbres fruitiers, dont des kakis, des grenadiers, des pommiers, des kumquats, des nectariniers et une large s\u00e9lection d'agrumes, sont en fleurs et le parfum de leurs fleurs porte loin dans l'air du printemps. Il y a un bourdonnement r\u00e9gulier d'abeilles autour des arbres en fleurs et des buissons de myrtilles. Les papillons et les oiseaux vont et viennent dans le jardin, sans se soucier des humains qui se prom\u00e8nent sur le chemin.\n<\/p>\n<p>Quelqu'un fait remarquer que le nombre de semis pr\u00eats \u00e0 \u00eatre plant\u00e9s semble mieux convenir \u00e0 un jardin deux fois plus grand que le jardin de d\u00e9monstration, mais Sullivan se contente de sourire : \" Les gens sont \u00e9tonn\u00e9s de la quantit\u00e9 de produits comestibles qui sortent de cet espace. La production de ce jardin pourrait facilement combler ou presque les besoins en fruits et l\u00e9gumes d'une famille et il ne fait qu'une fraction de la taille des pelouses de la plupart des propri\u00e9taires. Nous encourageons les enfants qui travaillent dans le jardin et les visiteurs \u00e0 \"tester le go\u00fbt\" d'un haricot, d'une fraise ou d'un brin de romarin, et ils ne font m\u00eame pas une entaille \u00e0 ce qui est produit. En fait, selon M. Sullivan, ce qui n'est pas cueilli et mang\u00e9 par les \u00e9coliers participant \u00e0 l'\u00e9tude et par les visiteurs est r\u00e9colt\u00e9 et donn\u00e9 \u00e0 la banque alimentaire locale.\n<\/p>\n<h2>Des pelouses alimentaires de toutes les saveurs<br \/>\n<\/h2>\n<p>Si les jardins de Descanso sont un exemple formidable de projet de jardinage comestible, avec des statistiques sur le retour sur investissement financier et environnemental, ils sont loin d'\u00eatre les seuls. Des centaines de paysages comestibles et de jardins de la victoire apparaissent dans tout le pays.\n<\/p>\n<p>Certains, comme les projets Haeg \u00e0 Lakewood, en Californie (banlieue de Los Angeles), et \u00e0 Austin, au Texas, sont situ\u00e9s dans de grandes agglom\u00e9rations. Port\u00e9s par l'attention des m\u00e9dias, ils ont montr\u00e9 \u00e0 des milliers de spectateurs \u00e0 quoi ressemble un am\u00e9nagement paysager comestible soigneusement planifi\u00e9.\n<\/p>\n<p>D'autres projets ont d\u00e9but\u00e9 par des d\u00e9clarations sur la n\u00e9cessit\u00e9 de disposer de produits biologiques et de c\u00e9r\u00e9ales \u00e0 un prix abordable. \u00c0 Northampton, dans le Massachusetts, les propri\u00e9taires de la Hungry Ghost Bakery ont commenc\u00e9 \u00e0 donner aux clients des baies de bl\u00e9 anciennes \u00e0 planter dans leur propre jardin. Ils esp\u00e8rent que les habitants de la r\u00e9gion seront en mesure de cultiver suffisamment de bl\u00e9 pour r\u00e9pondre aux besoins de la boulangerie en farine biologique.\n<\/p>\n<p>Dans la banlieue de Scottsdale, en Arizona, une artiste qui a transform\u00e9 sa pelouse en jardin comestible rapporte que les voitures du quartier ralentissent consid\u00e9rablement lorsque les conducteurs regardent ce qui pousse.\n<\/p>\n<p>Dans le nord-ouest du Pacifique, les clubs de jardinage, les programmes de vulgarisation universitaire et les experts en conception de paysages comestibles et la philosophie qui les sous-tend s'adressent \u00e0 des groupes qui font salle comble. Et pour ceux qui n'ont pas de pelouses \u00e0 arracher et \u00e0 remplacer, les possibilit\u00e9s offertes par les jardins communautaires se sont av\u00e9r\u00e9es tr\u00e8s populaires. Dans la ville de Seattle, par exemple, bien qu'il y ait d\u00e9j\u00e0 de la place pour 6 000 jardiniers communautaires, un millier d'autres personnes sont sur des listes d'attente pour obtenir une parcelle.\n<\/p>\n<p>Cette popularit\u00e9 ne surprend pas Charlie Nardozzi, expert en am\u00e9nagement paysager comestible et horticulteur principal \u00e0 la National Gardening Association : \"Ce que nous avons en ce moment, dans cette \u00e9conomie, c'est ce que j'aime appeler une \"temp\u00eate parfaite de jardins comestibles\", qui a \u00e9t\u00e9 stimul\u00e9e par les pr\u00e9occupations concernant le r\u00e9chauffement climatique, l'impact du carbone et nos empreintes carbone individuelles, et aussi par des choses comme la s\u00e9curit\u00e9 alimentaire, la s\u00e9curit\u00e9 alimentaire, les prix de l'\u00e9nergie et les prix des aliments. Une partie de ce ph\u00e9nom\u00e8ne est certainement li\u00e9e \u00e0 l'\u00e9conomie ; historiquement, chaque fois que l'inflation est en hausse et l'\u00e9conomie en baisse, il y a un regain d'int\u00e9r\u00eat pour le jardinage. Je pense que les gens commencent \u00e0 se demander pourquoi ils paient 4 dollars pour des salades biologiques alors qu'ils pourraient faire pousser deux ou trois douzaines de t\u00eates de laitue pour moins que \u00e7a& ;\n<\/p>\n<p>Selon M. Nardozzi, &ldquo;Les gens veulent avoir un certain contr\u00f4le sur leur vie lorsqu'il y a de l'incertitude et un sentiment de chaos. Cela va de la hausse des prix aux inqui\u00e9tudes sur la s\u00e9curit\u00e9 et la disponibilit\u00e9 des aliments. En supposant que vous pratiquez le jardinage biologique, le fait de tirer une partie de votre nourriture de votre propre jardin signifie que vous ne vous inqui\u00e9tez pas de la contamination par les pesticides et que vous n'attendez pas non plus que des avions et des semi-remorques remplis de produits arrivent du Chili et de Floride.\n<\/p>\n<p>Dans cette optique, et avec des ressources comme Edible Estates de Haeg&rsquo; : Attack on the Front Lawn et Flores&rsquo ; Food Not Lawns continuant \u00e0 susciter des tourn\u00e9es de conf\u00e9rences et des demandes de jardins de d\u00e9monstration, pourrions-nous commencer \u00e0 assister \u00e0 la renaissance des jardins de la victoire de la Seconde Guerre mondiale ?\n<\/p>\n<h3>Inspiration pour&nbsp;Votre pelouse comestible<br \/>\n<\/h3>\n<ul>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Food Not Lawns: Comment transformer votre cour en jardin et votre quartier en communaut\u00e9 par Heather C. Flores (Chelsea Green, 2006)<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Edible Estates: Attack on the Front Lawn par Fritz Haeg, et al. <\/font><font style=\"vertical-align: inherit\">(M\u00e9tropole, 2010)<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Am\u00e9nagement paysager comestible par Rosalind Creasy (Sierra Club, 2010)<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Concevoir et entretenir naturellement votre paysage comestible par Robert Kourik et Rosalind Creasy (Permanent, 2005)<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Le jardin comestible par les \u00e9diteurs de Sunset Books (Oxymoor House, 2004)<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">L\u00e9gumes vivaces: des artichauts au Zuiki Taro, un guide du jardinier sur plus de 100 produits comestibles d\u00e9licieux et faciles \u00e0 cultiver par Eric Toensmeier (Chelsea Green, 2007)<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">The Bountiful Container: Cr\u00e9ez des jardins de l\u00e9gumes, d'herbes, de fruits et de fleurs comestibles par Rose Marie Nichols McGee et Maggie Stuckey (Workman, 2002)<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">L\u00e9gumes incroyables provenant de r\u00e9cipients auto-arrosants par Edward C. Smith (Storey, 2006)<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Am\u00e9nagement paysager avec des fruits et l\u00e9gumes par Fred Hagy (Overlook, 2001)<\/font><\/font><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Imaginez que notre gouvernement nous demande de r\u00e9pondre \u00e0 la crise du r\u00e9chauffement climatique, \u00e0 la rar\u00e9faction du p\u00e9trole et \u00e0 la d\u00e9t\u00e9rioration de la sant\u00e9 en plantant des jardins potagers ; Ceux qui ont v\u00e9cu aux \u00c9tats-Unis et en Grande-Bretagne pendant la Seconde Guerre mondiale et ont connu le rationnement alimentaire des ann\u00e9es 1940 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":82016,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[116],"tags":[],"class_list":["post-82011","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-garden-planning"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/posts\/82011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/comments?post=82011"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/posts\/82011\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/media\/82016"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/media?parent=82011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/categories?post=82011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/tags?post=82011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}