{"id":81673,"date":"2023-03-07T11:20:49","date_gmt":"2023-03-07T08:20:49","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/fr-protegez-votre-gazon-les-avantages-du-trefle-blanc\/"},"modified":"2023-03-07T11:20:49","modified_gmt":"2023-03-07T08:20:49","slug":"fr-protegez-votre-gazon-les-avantages-du-trefle-blanc","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/fr\/2023\/03\/07\/fr-protegez-votre-gazon-les-avantages-du-trefle-blanc\/","title":{"rendered":"Prot\u00e9gez votre gazon : Les avantages du tr\u00e8fle blanc"},"content":{"rendered":"<p>The Humane Guide to Critter Control (Cool Springs Press, 2017)&nbsp;de Theresa Rooney aide les jardiniers \u00e0 \u00e9loigner les nuisibles et les bestioles de leurs pr\u00e9cieux jardins de mani\u00e8re s\u00fbre et organique, afin de ne pas blesser la bestiole ou le jardin. Dans l'extrait suivant, Rooney discute des avantages de l'ajout de tr\u00e8fle blanc \u00e0 votre pelouse.\n<\/p>\n<h2>Repensez votre pelouse<br \/>\n<\/h2>\n<p>Si vous aimez votre gazon (et c'est le cas de beaucoup de gens), il y a des choses que vous pouvez faire pour minimiser les dommages caus\u00e9s par les parasites. Peut-\u00eatre avez-vous pens\u00e9 que je vous dirais d'arracher tout le gazon et de planter des plantes et des arbres indig\u00e8nes ? Si vous avez des enfants ou des animaux de compagnie, vous avez peut-\u00eatre besoin d'espace pour qu'ils puissent s'\u00e9battre. Un beau gazon peut mettre en valeur un beau jardin. Le gazon peut rafra\u00eechir votre cour et adoucir le bruit du voisinage. Maintenant, voici l'id\u00e9e folle&mdash ; pensez \u00e0 ajouter du tr\u00e8fle blanc \u00e0 votre gazon.\n<\/p>\n<p>Nous, Am\u00e9ricains, avons une histoire d'amour avec notre gazon depuis longtemps. Avant les ann\u00e9es 1950, nous autorisions le tr\u00e8fle et les pissenlits dans l'herbe. Surtout parce que nous n'avions pas tous les herbicides dont nous disposons aujourd'hui. Mais dans les ann\u00e9es 1950, les herbicides sont devenus populaires. Les entreprises de semences et de produits chimiques \u00e9taient assez intelligentes. Si vous tuez toutes les mauvaises herbes \u00e0 feuilles larges, ce qui peut \u00eatre b\u00e9n\u00e9fique pour le gazon, vous devez maintenant fertiliser le gazon. Si vous coupez l'herbe plus courte, vous devrez peut-\u00eatre arroser davantage et utiliser plus d'engrais et d'herbicides. Au lieu d'une prairie courte et g\u00e9rable, nous devions aspirer \u00e0 des pelouses vertes plates comme des tables de billard.\n<\/p>\n<p>Si vous ajoutez du tr\u00e8fle \u00e0 votre pelouse, vous constaterez peut-\u00eatre que les lapins le pr\u00e9f\u00e8rent (et c'est vraiment le cas) \u00e0 vos lys. Les marmottes pr\u00e9f\u00e8rent aussi le tr\u00e8fle&mdash;c'est l'un de leurs pr\u00e9f\u00e9r\u00e9s. Le tr\u00e8fle attire \u00e9galement les abeilles et se trouve souvent dans les pelouses \u00e0 abeilles. Les pelouses \u00e0 abeilles sont une alternative aux espaces herbeux traditionnels qui comprennent des plantes \u00e0 faible croissance qui fleurissent et fournissent du nectar et du pollen aux pollinisateurs. Il peut s'agir de thym rampant, de tr\u00e8fle, de s\u00e9dums \u00e0 faible croissance, de violettes ou de gingembre canadien. La f\u00e9tuque est \u00e9galement l'herbe souvent utilis\u00e9e dans ces m\u00e9langes, car elle pousse plus lentement et n'a pas besoin d'engrais comme le p\u00e2turin du Kentucky. Certaines de ces plantes peuvent supporter un certain trafic pi\u00e9tonnier et d'autres tr\u00e8s peu, elles doivent donc \u00eatre planifi\u00e9es et plant\u00e9es en fonction de l'utilisation de la zone. Vous constaterez peut-\u00eatre qu'en augmentant la diversit\u00e9 de votre paysage, vos probl\u00e8mes de parasites semblent s'att\u00e9nuer ou m\u00eame dispara\u00eetre compl\u00e8tement.\n<\/p>\n<p>Le tr\u00e8fle est \u00e9galement un fixateur d'azote. Les nodules sur ses racines permettent \u00e0 la plante d'extraire l'azote de l'air et de le stocker dans ces nodules. Lorsque les racines meurent, les nodules lib\u00e8rent l'azote dans le sol pour les racines de l'herbe. Si vous utilisez un engrais 30-0-15 sur votre pelouse, le premier chiffre repr\u00e9sente l'azote, la chose m\u00eame que le tr\u00e8fle fournit gratuitement. Le tr\u00e8fle n'aura pas besoin d'\u00eatre tondu aussi souvent que votre gazon. Un gain de temps suppl\u00e9mentaire pour vous. Lorsque vous ajoutez de la diversit\u00e9 \u00e0 votre gazon, vous pouvez remarquer qu'il semble plus sain. Il est plus apte \u00e0 pousser de mani\u00e8re \u00e9paisse et luxuriante. Il est plus \u00e0 m\u00eame de r\u00e9sister \u00e0 certains d\u00e9g\u00e2ts caus\u00e9s par les insectes, voire de les \u00e9viter compl\u00e8tement, car le sol est tellement sain qu'aucun des \"mauvais\" insectes du sol ne peut s'\u00e9chapper. L'utilisation sur votre pelouse de produits qui ne sont pas biologiques ou naturels peut diminuer la sant\u00e9 du sol et la r\u00e9sistance de votre pelouse, ce qui vous obligera \u00e0 utiliser encore plus de produits.\n<\/p>\n<p>Et ces pissenlits ? Si vous le pouvez, laissez-les vivre ! Il suffit de faucher les fleurs avant qu'elles ne montent en graine... cela rendra vos voisins plus heureux. Les pissenlits sont une plante \u00e0 floraison pr\u00e9coce. Ils sont peut-\u00eatre l'une des rares plantes en fleur lorsque les bourdons femelles sortent d'hibernation et sont affam\u00e9s. Tout r\u00e9cemment, le bourdon \u00e0 pattes rouill\u00e9es a \u00e9t\u00e9 mis sur la liste des esp\u00e8ces menac\u00e9es. Oui, un bourdon est en voie de disparition. Il se peut m\u00eame que certains soient d\u00e9j\u00e0 \u00e9teints, car on ne les a pas vus depuis des ann\u00e9es. Pour moi, le bourdon est un \u00e9l\u00e9ment embl\u00e9matique de l'\u00e9t\u00e9. Entendre le bourdonnement paresseux et voir cette abeille apparemment impossible \u00e0 voler passer lentement est un plaisir que j'appr\u00e9cie \u00e0 chaque fois.\n<\/p>\n<p>Les pissenlits ont une grosse racine pivotante, r\u00e9sistante et profonde, qui brise le sol compact et puise les nutriments loin sous terre. Lorsque le gazon est tondu et que les feuilles sont laiss\u00e9es sur la pelouse pour se d\u00e9composer, ces nutriments sont \u00e0 nouveau disponibles pour l'herbe. M\u00eame les pissenlits nourrissent le gazon pour vous, tandis qu'ils ameublissent le sol et permettent la cr\u00e9ation de canaux pour que la pluie puisse y \u00eatre retenue et filtr\u00e9e vers les aquif\u00e8res situ\u00e9s en dessous plut\u00f4t que de s'\u00e9couler dans nos lacs et nos cours d'eau.\n<\/p>\n<p>Comment une belle pelouse remplie de tr\u00e8fle peut-elle aider \u00e0 lutter contre les nuisibles ? N'oubliez pas que les lapins et les marmottes pr\u00e9f\u00e8rent le tr\u00e8fle et qu'ils peuvent donc laisser vos plantes et votre potager tranquilles. De plus, alors que les lapins appr\u00e9cient le tr\u00e8fle, les faucons ou les hiboux, perch\u00e9s en hauteur, se pr\u00e9parent \u00e0 attraper un ou deux lapins pour nourrir leurs petits.\n<\/p>\n<p>Un espace ext\u00e9rieur sain et diversifi\u00e9 peut attirer certains nuisibles vers des zones o\u00f9 ils font moins de d\u00e9g\u00e2ts. Cet espace ext\u00e9rieur peut \u00eatre inconfortable pour de nombreux animaux nuisibles parce que vous y \u00eates plus souvent dehors et que c'est un espace merveilleusement beau et \u00e9nergisant. Votre espace ext\u00e9rieur sain peut cr\u00e9er des barri\u00e8res que certains animaux nuisibles ne veulent pas franchir (haies \u00e9paisses) ou trop de couverture, ce qui pourrait cacher des pr\u00e9dateurs, ou n'offrir aucun espace aux animaux nuisibles. Il peut \u00eatre si diversifi\u00e9 qu'aucun \u00e9l\u00e9ment n'est suffisamment abondant pour attirer un ravageur&mdash;ou si vous avez beaucoup de hostas, par exemple, elles sont diss\u00e9min\u00e9es partout ou bien nich\u00e9es en s\u00e9curit\u00e9 pr\u00e8s de votre maison, hors de port\u00e9e des ravageurs qui aiment les grignoter.\n<\/p>\n<p>Parce que votre espace ext\u00e9rieur est si riche en oiseaux, les insectes sont tenus en \u00e9chec. Les oiseaux ont tellement d'autre nourriture qu'ils ne d\u00e9rangent pas vos cultures. Cela ne ressemble-t-il pas \u00e0 un paradis ? Et cela peut \u00eatre votre paradis si vous le souhaitez.\n<\/p>\n<h2>Gardez les choses en ordre<br \/>\n<\/h2>\n<p>Le dernier aspect d'un jardin sain peut \u00eatre le simple nettoyage et la propret\u00e9. Stockez les tas de bois loin de votre maison afin que les souris et, peut-\u00eatre, les serpents soient loin de vos fondations. (Si vous le construisez, ils viendront).\n<\/p>\n<p>Les bacs et les tas de compost sont parfaits pour cr\u00e9er votre propre compost, mais si vous y mettez les mauvaises choses, comme de la viande, du fromage ou des os, vous invitez les nuisibles dans votre jardin. Gardez les tas de compost propres et placez-les l\u00e9g\u00e8rement \u00e0 l'\u00e9cart de votre maison ; vous devez pouvoir y acc\u00e9der facilement. Certains endroits peuvent exiger que vous les gardiez couverts. Si c'est le cas dans votre ville, veillez \u00e0 ce qu'ils restent suffisamment humides&mdash;si vous avez besoin d'eau, retirez la couverture avant une temp\u00eate de pluie.\n<\/p>\n<h3>Plus de : Le guide du contr\u00f4le humain des cr\u00e9atures<br \/>\n<\/h3>\n<p>&bull ; Contr\u00f4le organique des cerfs pour votre jardin\n<\/p>\n<p>Reproduit avec l'autorisation de The Human Guide to Critter Controlpar Theresa Rooney et publi\u00e9 par Cool Springs Press, 2017.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The Humane Guide to Critter Control (Cool Springs Press, 2017)&nbsp;de Theresa Rooney aide les jardiniers \u00e0 \u00e9loigner les nuisibles et les bestioles de leurs pr\u00e9cieux jardins de mani\u00e8re s\u00fbre et organique, afin de ne pas blesser la bestiole ou le jardin. Dans l'extrait suivant, Rooney discute des avantages de l'ajout de tr\u00e8fle blanc \u00e0 votre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81678,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121],"tags":[],"class_list":["post-81673","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-pest-control"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/posts\/81673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/comments?post=81673"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/posts\/81673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/media\/81678"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/media?parent=81673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/categories?post=81673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/tags?post=81673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}