{"id":81231,"date":"2023-03-07T11:10:01","date_gmt":"2023-03-07T08:10:01","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/fr-la-culture-des-arbres-fruitiers-dans-le-jardin-familial\/"},"modified":"2023-03-07T11:10:01","modified_gmt":"2023-03-07T08:10:01","slug":"fr-la-culture-des-arbres-fruitiers-dans-le-jardin-familial","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/fr\/2023\/03\/07\/fr-la-culture-des-arbres-fruitiers-dans-le-jardin-familial\/","title":{"rendered":"La culture des arbres fruitiers dans le jardin familial"},"content":{"rendered":"<p>Un vieux proverbe dit : \"Le meilleur moment pour planter un arbre, c'est il y a vingt ans. Je pense que cette petite perle de sagesse est particuli\u00e8rement vraie lorsqu'il s'agit d'arbres fruitiers.\n<\/p>\n<p>Il est trop facile de remettre \u00e0 plus tard l'achat et la plantation d'arbres. Ils peuvent co\u00fbter cher et il y a toujours tant d&#8217autres choses \u00e0 faire. Lorsque l&#8217on pense \u00e0 des arbres fruitiers, il est \u00e9galement facile de d\u00e9former sa logique : \"Il faudra peut-\u00eatre attendre sept ans avant d&#8217obtenir des fruits, alors pourquoi se donner la peine ? Vous attendrez bien plus longtemps si vous ne plantez jamais ces arbres.\n<\/p>\n<p>Voici mes conseils pour choisir et faire pousser des arbres fruitiers.\n<\/p>\n<h3>Ne le remettez pas \u00e0 plus tard<br \/>\n<\/h3>\n<p>Plus t\u00f4t vous plantez vos arbres fruitiers, plus t\u00f4t ils produiront. \u00c9tant donn\u00e9 qu&#8217il faudra au minimum deux ans (pour certaines vari\u00e9t\u00e9s de pommes) \u00e0 cinq ans ou plus (cerises ou papayes), il n&#8217est jamais trop t\u00f4t pour commencer. Si un arbre fruitier est plus que votre budget ne peut supporter, vous pouvez envisager de sugg\u00e9rer un arbre&#8211ou un ch\u00e8que-cadeau \u00e0 une p\u00e9pini\u00e8re r\u00e9put\u00e9e qui en stocke&#8211comme id\u00e9e de cadeau.\n<\/p>\n<h3>Faites vos recherches<br \/>\n<\/h3>\n<p>Certains arbres sont autopollinisants (la plupart des nectarines, des p\u00eaches, des cerises acides). D'autres ont besoin d'une autre vari\u00e9t\u00e9 du m\u00eame fruit pour se polliniser (la plupart des pommes, poires, prunes). Il est pr\u00e9f\u00e9rable de ne pas planter les pollinisateurs crois\u00e9s \u00e0 plus de 15 m\u00e8tres de distance. Si vous avez de la chance, un voisin proche a d\u00e9j\u00e0 plant\u00e9 un bon pollinisateur crois\u00e9 \u00e0 proximit\u00e9. Le timing est essentiel en mati\u00e8re de pollinisation : assurez-vous que les arbres que vous achetez pour la pollinisation crois\u00e9e fleurissent \u00e0 la m\u00eame p\u00e9riode de l'ann\u00e9e.\n<\/p>\n<p>Il est \u00e9galement important de conna\u00eetre le meilleur moment pour planter. La plupart des p\u00e9pini\u00e8res livrent en fonction de la p\u00e9riode de plantation appropri\u00e9e pour votre r\u00e9gion ; cependant, si vous achetez localement, vous devez vous renseigner sur les conditions de plantation favorables.\n<\/p>\n<p>Apprenez \u00e0 conna\u00eetre la profondeur et la largeur des trous, les besoins en arrosage, les exigences en mati\u00e8re de taille. Il y a beaucoup \u00e0 apprendre. Si votre arbre n&#8217est pas livr\u00e9 avec ces instructions, cherchez sur Internet. Assurez-vous simplement que vos sources sont fiables.\n<\/p>\n<h3>Savoir quels arbres choisir pour votre zone de plantation<br \/>\n<\/h3>\n<p>Bien que vous puissiez souhaiter que ce soit vrai, vous ne pouvez pas faire pousser toutes les sortes de fruits sous tous les climats. Les pommes, par exemple, ont besoin d'une saison de dormance. Le gel et les agrumes ne font pas bon m\u00e9nage. Et bien que certaines personnes repoussent les limites, c&#8217est beaucoup d&#8217apprentissage et de travail que de faire pousser des fruits dans un climat peu engageant. Pour savoir si vous pouvez faire pousser vos fruits pr\u00e9f\u00e9r\u00e9s l\u00e0 o\u00f9 vous vivez, renseignez-vous aupr\u00e8s du service de vulgarisation agricole de votre r\u00e9gion.\n<\/p>\n<h3>Prot\u00e9gez vos arbres<br \/>\n<\/h3>\n<p>L&#8217\u00e9corce d&#8217un jeune arbre est particuli\u00e8rement susceptible d&#8217\u00eatre endommag\u00e9e, mais elle attire les cerfs affam\u00e9s. Soyez prudent et utilisez une sorte d'enveloppe ou de protection pour les arbres. Vous pouvez acheter des filets, des tubes, du papier ou de la toile de jute. Vous pouvez aussi faire preuve de cr\u00e9ativit\u00e9 et fabriquer votre propre protection. Lorsque nous avons plant\u00e9 un pommier, nous n'avons pas pu trouver d'emballage pour arbre dans notre r\u00e9gion. Nous avons donc improvis\u00e9 en achetant un tuyau d'\u00e9vacuation en plastique ondul\u00e9 noir que nous avons coup\u00e9 \u00e0 la longueur appropri\u00e9e et fendu sur un c\u00f4t\u00e9. Veillez \u00e0 ne pas comprimer le tronc de l&#8217arbre en l&#8217enveloppant trop serr\u00e9.\n<\/p>\n<h3>N'oubliez pas de prot\u00e9ger \u00e9galement les fruits<br \/>\n<\/h3>\n<p>Rien n'est plus d\u00e9cevant que de d\u00e9couvrir que, juste avant que votre fruit ne soit compl\u00e8tement m\u00fbr, quelque chose l'a atteint avant vous. Pour \u00e9loigner les oiseaux, couvrez les arbres fruitiers d'un filet. Les chiens d'ext\u00e9rieur aideront \u00e0 \u00e9loigner les ratons laveurs, les chevreuils et les ours, mais il existe aussi d'autres options. Gardez vos arbres \u00e0 l'int\u00e9rieur d'une zone correctement cl\u00f4tur\u00e9e. (Une cl\u00f4ture \u00e0 cerfs ou deux rang\u00e9es parall\u00e8les de cl\u00f4tures de quatre pieds de haut espac\u00e9es de quatre pieds devraient emp\u00eacher les cerfs d'entrer). Si vous ajoutez une rang\u00e9e de cl\u00f4ture \u00e9lectrique au-dessus de votre autre cl\u00f4ture, les ratons laveurs devraient \u00e9galement se tenir \u00e0 l'\u00e9cart. Nous avons d\u00e9cid\u00e9 d'agrandir notre potager pour accueillir des arbres fruitiers et nous avons entour\u00e9 le tout d'une cl\u00f4ture anti-cerfs. Jusqu'\u00e0 pr\u00e9sent, tout va bien.\n<\/p>\n<h3>Assurez-vous d'avoir suffisamment d'espace<br \/>\n<\/h3>\n<p>Quelle est la largeur \u00e0 maturit\u00e9 des arbres que vous envisagez ? Assurez-vous d'avoir suffisamment d'espace entre eux. Il est possible de faire pousser vos arbres de mani\u00e8re plus compacte que ne le sugg\u00e8re l&#8217espacement standard gr\u00e2ce \u00e0 des m\u00e9thodes de taille sp\u00e9ciales ; cependant, il est crucial de faire des recherches sur cette technique. Une bonne ressource est le livre Grow a Little Fruit Tree : Simple Pruning Techniques for Small-Space, Easy-Harvest Fruit Trees.\n<\/p>\n<h3>Pensez \u00e0 la taille<br \/>\n<\/h3>\n<p>Vous devez \u00e9galement r\u00e9fl\u00e9chir \u00e0 la mani\u00e8re dont vous allez r\u00e9colter vos fruits. Voulez-vous vraiment grimper sur une \u00e9chelle \u00e0 coulisse appuy\u00e9e contre les branches d'un arbre pour r\u00e9colter vos fruits ? Ou pour tailler vos arbres ? Cela peut \u00eatre dangereux, surtout pour les jardiniers \u00e2g\u00e9s. Lorsqu&#8217ils sont disponibles, envisagez des arbres nains ou semi-nains plut\u00f4t que des arbres standard plus grands pour simplifier les soins et la r\u00e9colte.\n<\/p>\n<h3>L'emplacement est important<br \/>\n<\/h3>\n<p>Le sol pour les arbres fruitiers doit \u00eatre riche en nutriments, et vous devrez peut-\u00eatre ajouter des amendements dans tous les cas. Plantez l\u00e0 o\u00f9 le drainage est bon. Et plantez l\u00e0 o\u00f9 vos arbres b\u00e9n\u00e9ficient d'un minimum de cinq heures d'ensoleillement par jour.\n<\/p>\n<h3>Redimensionner votre verger<br \/>\n<\/h3>\n<p>Si vous plantez trop, vous ne serez pas en mesure d&#8217assurer l&#8217entretien n\u00e9cessaire. R\u00e9fl\u00e9chissez aux fruits que votre famille est la plus susceptible de manger, \u00e0 ceux qui sont les plus polyvalents, \u00e0 la quantit\u00e9 de fruits dont vous avez r\u00e9ellement besoin. Il n&#8217y a aucune raison de planter un verger entier de pommiers si votre r\u00e9colte ne servira qu&#8217\u00e0 votre famille. (D'un autre c\u00f4t\u00e9, n'oubliez pas que les pommes peuvent \u00eatre s\u00e9ch\u00e9es pour \u00eatre mang\u00e9es \u00e0 la fin de l'hiver, conserv\u00e9es sous forme de compote ou de garniture de tarte en conserve au bain-marie, ou transform\u00e9es en jus pour le cidre).\n<\/p>\n<h3>Soyez attentif<br \/>\n<\/h3>\n<p>Les arbres fruitiers ont besoin d'attention, certains plus que d'autres. L\u00e0 encore, il est imp\u00e9ratif de faire des recherches pour savoir combien de soins certains arbres sp\u00e9cifiques requi\u00e8rent. Tous ont besoin de paillage, de taille, d'engrais et d'un arrosage r\u00e9gulier et fr\u00e9quent. Vous devez \u00e9galement faire preuve de diligence pour prot\u00e9ger vos arbres des parasites et des maladies. Un nettoyage rigoureux \u00e0 l'automne est essentiel.\n<\/p>\n<p>Quelles r\u00e9compenses votre famille r\u00e9coltera si vous ajoutez des arbres fruitiers \u00e0 votre jardin. Il n&#8217y a pas de meilleur moment pour commencer.\n<\/p>\n<p>Pour en savoir plus sur la plantation, la taille, la r\u00e9colte et bien d'autres choses encore, consultez cet article de Barbara Pleasant, gourou du jardinage de Mother Earth News.\n<\/p>\n<p>Carole Coates est une jardini\u00e8re et une conservatrice des aliments, une archiviste familiale, une essayiste, une po\u00e8te, une photographe et une homesteader moderne. Vous pouvez trouver Carole \u00e0 Living On the Diagonal, o\u00f9 elle partage son point de vue sur la vie, notamment sur le homesteading moderne, la pr\u00e9paration et la conservation des aliments, les voyages, ainsi que des pens\u00e9es et des r\u00e9flexions al\u00e9atoires, des essais personnels, de la po\u00e9sie et des photographies.\n<\/p>\n<p>Tous les blogueurs de la communaut\u00e9 MOTHER EARTH NEWS ont accept\u00e9 de suivre nos Directives pour les blogueurs, et ils sont responsables de l'exactitude de leurs articles. Pour en savoir plus sur l'auteur de ce billet, cliquez sur le lien de sa signature en haut de la page.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un vieux proverbe dit : \"Le meilleur moment pour planter un arbre, c'est il y a vingt ans. Je pense que cette petite perle de sagesse est particuli\u00e8rement vraie lorsqu'il s'agit d'arbres fruitiers. Il est trop facile de remettre \u00e0 plus tard l'achat et la plantation d'arbres. Ils peuvent co\u00fbter cher et il y a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81236,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115],"tags":[],"class_list":["post-81231","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-fruits"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/posts\/81231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/comments?post=81231"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/posts\/81231\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/media\/81236"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/media?parent=81231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/categories?post=81231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/tags?post=81231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}