{"id":80789,"date":"2023-03-07T10:56:03","date_gmt":"2023-03-07T07:56:03","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/fr-le-scarabee-de-lasperge-conseils-de-lutte-biologique\/"},"modified":"2023-03-07T10:56:03","modified_gmt":"2023-03-07T07:56:03","slug":"fr-le-scarabee-de-lasperge-conseils-de-lutte-biologique","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/fr\/2023\/03\/07\/fr-le-scarabee-de-lasperge-conseils-de-lutte-biologique\/","title":{"rendered":"Le scarab\u00e9e de l'asperge : Conseils de lutte biologique"},"content":{"rendered":"<p>Cet article fait partie de notre s\u00e9rie sur la lutte biologique contre les parasites, qui comprend des articles sur la fa\u00e7on d'attirer les insectes b\u00e9n\u00e9fiques, de lutter contre certains parasites du jardin et d'utiliser des pesticides biologiques ;\n<\/p>\n<p>Le plus commun des ravageurs de l'asperge, le scarab\u00e9e de l'asperge affaiblit les plantes lorsqu'il est nourri par les adultes et les larves. Les m\u00e9thodes biologiques de lutte contre les coccinelles de l'asperge comprennent la cueillette \u00e0 la main, le ramassage et le compostage du feuillage et des baies des asperges. Originaire d'Europe, le scarab\u00e9e de l'asperge est maintenant pr\u00e9sent dans toute l'Am\u00e9rique du Nord, partout o\u00f9 l'on cultive l'asperge.\n<\/p>\n<h2>Que sont les scarab\u00e9es de l'asperge ?<br \/>\n<\/h2>\n<p>Le crioc\u00e8re de l'asperge (Crioceris asparagi) est le ravageur de l'asperge le plus r\u00e9pandu, qui endommage les jeunes tiges d'asperge. Hivernant \u00e0 l'\u00e9tat adulte, ce col\u00e9opt\u00e8re mince et allong\u00e9 porte quatre taches blanches ou jaun\u00e2tres sur les ailes, est rouge\u00e2tre en dessous et sur les bords des ailes, et a un thorax rouge fonc\u00e9. Il est&nbsp;1\n<\/p>\n<p>Le crioc\u00e8re tachet\u00e9 de l'asperge (Crioceris duodecimpunctata) est \u00e9galement tr\u00e8s color\u00e9. Dans l'ouest des \u00c9tats-Unis, le crioc\u00e8re de l'asperge est orange citrouille vif avec de minuscules points noirs sur les ailes. Dans d'autres r\u00e9gions, la couleur de fond des asperges tachet\u00e9es peut \u00eatre rouge \u00e0 rouge fonc\u00e9. Les antennes de ces deux ravageurs de l'asperge mesurent environ la moiti\u00e9 de la longueur du corps.\n<\/p>\n<h2>D\u00e9g\u00e2ts caus\u00e9s par le scarab\u00e9e de l'asperge&nbsp ;<br \/>\n<\/h2>\n<p>Au d\u00e9but du printemps, alors que les asperges commencent \u00e0 sortir de terre, les scarab\u00e9es adultes \u00e9mergent apr\u00e8s avoir pass\u00e9 l'hiver dans les d\u00e9bris v\u00e9g\u00e9taux. Ils commencent \u00e0 se nourrir des premi\u00e8res asperges, les faisant se recroqueviller comme une houlette de berger. Peu apr\u00e8s l'accouplement, les femelles pondent des \u0153ufs minuscules, sombres et allong\u00e9s sur les petites lances et le nouveau feuillage, qui d\u00e9passent \u00e0 angle droit. Les adultes se nourrissent des lances principales, tandis que les larves au corps mou, de couleur gris-vert, se nourrissent des lances et du feuillage. Les indentations caus\u00e9es par l'alimentation sont de couleur brune et diminuent la vigueur et la taille des tiges affect\u00e9es. Une alimentation s\u00e9v\u00e8re r\u00e9duit la vigueur des plants d'asperges.\n<\/p>\n<p>Les coccinelles tachet\u00e9es adultes \u00e9mergent une \u00e0 trois semaines plus tard que les coccinelles communes de l'asperge. \u00c0 la fin du printemps, ces ravageurs de l'asperge peuvent \u00eatre trouv\u00e9s partout sur les plants d'asperges, mais ils ne causent g\u00e9n\u00e9ralement que des dommages mineurs. Le cycle de ponte co\u00efncide avec la formation des baies d'asperge. Les adultes pondent des \u0153ufs sur ou pr\u00e8s des baies, les larves s'y enfoncent pour se nourrir, puis tombent au sol pour se transformer en adultes. Les larves se nourrissent uniquement \u00e0 l'int\u00e9rieur des baies. Les larves du scarab\u00e9e tachet\u00e9 de l'asperge sont jaun\u00e2tres avec la t\u00eate et les pattes noires.\n<\/p>\n<h2>Reproduction du scarab\u00e9e de l'asperge&nbsp ;<br \/>\n<\/h2>\n<p>Peu apr\u00e8s leur apparition au printemps, les coccinelles de l'asperge pondent des \u0153ufs sur les tiges \u00e9mergentes, qui \u00e9closent au bout de trois \u00e0 huit jours. Les petits vers gris\u00e2tres \u00e0 corps mou se nourrissent de la nouvelle croissance tendre au printemps. Plus tard en \u00e9t\u00e9, on peut trouver des \u0153ufs et des larves qui se nourrissent du feuillage des asperges. Lorsque les larves arrivent \u00e0 maturit\u00e9 apr\u00e8s environ deux semaines d'alimentation, elles tombent sur le sol et se transforment en chrysalides dans une cellule en terre pendant sept \u00e0 dix jours avant d'\u00e9merger en tant qu'adultes. Dans la plupart des climats, il y a deux g\u00e9n\u00e9rations chaque ann\u00e9e, mais dans les climats chauds, il peut y avoir jusqu'\u00e0 cinq g\u00e9n\u00e9rations de ce ravageur de l'asperge.\n<\/p>\n<p>Les coccinelles tachet\u00e9es de l'asperge \u00e9mergent au milieu du printemps et commencent rapidement \u00e0 manger le feuillage des asperges, mais elles attendent que les asperges d\u00e9veloppent des baies pour pondre leurs \u0153ufs. Apr\u00e8s l'\u00e9closion des \u0153ufs, les larves percent les baies pour se nourrir.\n<\/p>\n<h2>Ennemis naturels des scarab\u00e9es de l'asperge&nbsp ;<br \/>\n<\/h2>\n<p>Les oiseaux mangent souvent les coccinelles de l'asperge et les larves, qui apparaissent pendant la saison de nidification, lorsque les oiseaux ont besoin de plus de prot\u00e9ines.&nbsp;Les coccinelles mangent les jeunes larves, mais le pr\u00e9dateur le plus efficace est la petite gu\u00eape eulophide noire ( Tetrastichus asparagi ), qui mange les \u0153ufs de coccinelles de l'asperge au d\u00e9but de la saison, et pond ses \u0153ufs dans les \u0153ufs de coccinelles de l'asperge en \u00e9t\u00e9. Cet insecte b\u00e9n\u00e9fique, qui est si utile dans la lutte contre le scarab\u00e9e de l'asperge, a \u00e9t\u00e9 identifi\u00e9 dans le Massachusetts en 1915 et on le trouve maintenant partout o\u00f9 l'on cultive des asperges. Il n'est actuellement pas propos\u00e9 \u00e0 la vente dans le commerce.\n<\/p>\n<h2>Lutte biologique contre le scarab\u00e9e de l'asperge<br \/>\n<\/h2>\n<p>Pour lutter contre le scarab\u00e9e de l'asperge, les m\u00e9thodes de lutte biologique peuvent \u00eatre tr\u00e8s efficaces. Une cl\u00e9&nbsp;est d'enlever les d\u00e9bris v\u00e9g\u00e9taux de la parcelle \u00e0 l'automne et de les composter dans un tas de compost actif. Les larves et les adultes peuvent \u00eatre enlev\u00e9s \u00e0 la main. Lors de la cueillette manuelle, placez un seau d'eau sur le sol, et de nombreux col\u00e9opt\u00e8res y tomberont lorsqu'ils seront arrach\u00e9s des plantes. Les gu\u00eapes b\u00e9n\u00e9fiques parasiteront les oeufs des scarab\u00e9es.&nbsp;Les poulets font \u00e9galement un bon travail de collecte des scarab\u00e9es de l'asperge lorsqu'on les laisse fouiller dans la parcelle \u00e0 la fin de l'\u00e9t\u00e9. Dans les situations graves, vous pouvez obtenir un bon contr\u00f4le biologique des scarab\u00e9es de l'asperge en pulv\u00e9risant les plantes avec&nbsp;du neem au d\u00e9but de la saison, lorsque les populations sont modestes. N'utilisez pas de neem ni aucun autre pesticide si de petites gu\u00eapes noires sont pr\u00e9sentes dans votre parcelle d'asperges.\n<\/p>\n<p>Les asperges tachet\u00e9es seront d\u00e9courag\u00e9es si les asperges plant\u00e9es sont des cultivars uniquement m\u00e2les qui ne forment pas de baies. Si vos plantes produisent des baies, ramassez et compostez toutes les baies d'asperges si des scarab\u00e9es tachet\u00e9s ont \u00e9t\u00e9 vus. C'est le meilleur moyen de lutte biologique contre le scarab\u00e9e de l'asperge.\n<\/p>\n<h2>Plus de&nbsp;conseils de lutte biologique contre les parasites pour&nbsp;les scarab\u00e9es de l'asperge<br \/>\n<\/h2>\n<p>R\u00e9duisez les populations d'adultes hivernants des deux ravageurs de l'asperge en maintenant la zone environnante l\u00e9g\u00e8rement labour\u00e9e et en \u00e9liminant les d\u00e9bris v\u00e9g\u00e9taux. Cela oblige les col\u00e9opt\u00e8res de l'asperge \u00e0 hiberner dans le sol, o\u00f9 des pr\u00e9dateurs souterrains les mangent.\n<\/p>\n<p>Au d\u00e9but du printemps, coupez rapidement les turions au niveau du sol avec un couteau bien aiguis\u00e9. Une r\u00e9colte attentive emp\u00eachera de nombreux \u0153ufs de coccinelle de l'asperge d'\u00e9clore.\n<\/p>\n<p>Les deux types de scarab\u00e9es d'asperges peuvent \u00eatre facilement r\u00e9colt\u00e9s \u00e0 la main. L&#8217instinct d&#8217un scarab\u00e9e est de se laisser tomber au sol lorsqu&#8217il se sent d\u00e9rang\u00e9, alors tenez un r\u00e9cipient d&#8217eau sous la plante avant de la secouer doucement, et les insectes tomberont dans l&#8217eau. Une feuille de papier journal ou une bo\u00eete \u00e0 pizza fonctionne bien aussi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cet article fait partie de notre s\u00e9rie sur la lutte biologique contre les parasites, qui comprend des articles sur la fa\u00e7on d'attirer les insectes b\u00e9n\u00e9fiques, de lutter contre certains parasites du jardin et d'utiliser des pesticides biologiques ; Le plus commun des ravageurs de l'asperge, le scarab\u00e9e de l'asperge affaiblit les plantes lorsqu'il est nourri [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":80794,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121],"tags":[],"class_list":["post-80789","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-pest-control"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/posts\/80789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/comments?post=80789"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/posts\/80789\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/media\/80794"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/media?parent=80789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/categories?post=80789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/tags?post=80789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}