{"id":79931,"date":"2023-03-07T10:17:52","date_gmt":"2023-03-07T07:17:52","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/fr-cultiver-et-utiliser-le-calendula-a-usages-multiples\/"},"modified":"2023-03-07T10:17:52","modified_gmt":"2023-03-07T07:17:52","slug":"fr-cultiver-et-utiliser-le-calendula-a-usages-multiples","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/fr\/2023\/03\/07\/fr-cultiver-et-utiliser-le-calendula-a-usages-multiples\/","title":{"rendered":"Cultiver et utiliser le calendula \u00e0 usages multiples"},"content":{"rendered":"<p>Je cultive depuis longtemps des fleurs, en particulier des soucis et des tournesols, dans le cadre de mon potager biologique. Les avantages de la pollinisation et des plantes compagnes potentielles m'ont toujours servi d'excuse pour ajouter quelques plantes qui sont \"simplement jolies\" \u00e0 mon potager, par ailleurs utilitaire et producteur de nourriture. Cette ann\u00e9e, j'ai pouss\u00e9 ma plantation de soucis un peu plus loin et j'ai d\u00e9cid\u00e9 de faire pousser du Calendula officinalis, connu sous le nom de calendula, au lieu des soucis plus communs du genre Tagetes.\n<\/p>\n<p>J'ai choisi de le faire parce que je voulais profiter des propri\u00e9t\u00e9s de gu\u00e9rison de la peau associ\u00e9es au calendula de l'esp\u00e8ce officinalis. De nombreuses entreprises ont tir\u00e9 parti de ces propri\u00e9t\u00e9s et cr\u00e9\u00e9 des produits de soins corporels raffin\u00e9s \u00e0 base d'infusions de calendula ou d'huile essentielle de calendula. Alors, pourquoi ne pas cultiver cette fleur polyvalente pour fabriquer mes propres produits ?\n<\/p>\n<p>J'ai commenc\u00e9 mes calendula \u00e0 l'int\u00e9rieur environ six semaines avant la derni\u00e8re gel\u00e9e pr\u00e9vue dans ma r\u00e9gion, et je les ai depuis transplant\u00e9s le long des bords de mes lits de pommes de terre, de tomates et de poivrons. Nous avons plusieurs bourgeons et deux fleurs ouvertes. Au fur et \u00e0 mesure que les fleurs s'ouvrent, je vais recueillir les p\u00e9tales pour infuser des huiles, tr\u00e8s probablement de l'huile d'olive. Apr\u00e8s au moins quelques semaines de mac\u00e9ration, les huiles peuvent \u00eatre m\u00e9lang\u00e9es \u00e0 n'importe quelle recette de produit de soins corporels qui n\u00e9cessite un composant huileux liquide. J'ai l'intention de faire une pommade aux herbes, comme le montre cette vid\u00e9o.\n<\/p>\n<p>De plus, les p\u00e9tales de calendula sont comestibles et constituent une belle garniture pour les salades de printemps et d'\u00e9t\u00e9. En outre, les fleurs s\u00e9ch\u00e9es peuvent \u00eatre utilis\u00e9es pour colorer les fromages et les beurres faits maison et sont \u00e9galement employ\u00e9es comme substitut bon march\u00e9 du safran. Elles peuvent \u00eatre m\u00e9lang\u00e9es \u00e0 d'autres herbes pour donner plus de saveur aux th\u00e9s. Vous pouvez m\u00eame les m\u00e9langer dans une recette de muffins au ma\u00efs. Avec toutes ces options, qu&#8217est-ce qu&#8217on ne peut pas ne pas aimer ? Voil\u00e0 pour le \"juste joli\" !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je cultive depuis longtemps des fleurs, en particulier des soucis et des tournesols, dans le cadre de mon potager biologique. Les avantages de la pollinisation et des plantes compagnes potentielles m'ont toujours servi d'excuse pour ajouter quelques plantes qui sont \"simplement jolies\" \u00e0 mon potager, par ailleurs utilitaire et producteur de nourriture. Cette ann\u00e9e, j'ai [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":79936,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[120],"tags":[],"class_list":["post-79931","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-ornamentals"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/posts\/79931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/comments?post=79931"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/posts\/79931\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/media\/79936"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/media?parent=79931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/categories?post=79931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/fr\/wp-json\/wp\/v2\/tags?post=79931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}