{"id":81839,"date":"2023-03-07T11:30:07","date_gmt":"2023-03-07T08:30:07","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/de-planen-sie-ihr-permakultur-grundstuck\/"},"modified":"2023-03-07T11:30:07","modified_gmt":"2023-03-07T08:30:07","slug":"de-planen-sie-ihr-permakultur-grundstuck","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/de\/2023\/03\/07\/de-planen-sie-ihr-permakultur-grundstuck\/","title":{"rendered":"Planen Sie Ihr Permakultur-Grundst\u00fcck"},"content":{"rendered":"<p>Nehmen Sie sich Zeit, um Ihre Ressourcen, Bed\u00fcrfnisse und W\u00fcnsche zu erfassen, damit Sie erfolgreich eine Permakultur-Farm oder ein Permakultur-Grundst\u00fcck gestalten k\u00f6nnen.\n<\/p>\n<p>Die Umsetzung von Permakultur-Praktiken kann \u00fcberw\u00e4ltigend sein, aber nicht wegen eines Mangels an Informationen, Werkzeugen, Techniken, F\u00e4higkeiten oder Rezepten. Vielmehr ist es das Fehlen eines klar definierten Prozesses, um ein Permakultur-Grundst\u00fcck zu entwerfen, zu entwickeln und zu verwalten, was viele Menschen daran hindert. Gl\u00fccklicherweise k\u00f6nnen Sie die Anzahl der Optionen, die Sie beim Bau eines Permakultur-Grundst\u00fccks in Betracht ziehen m\u00fcssen, erheblich reduzieren, wenn Sie sich die Zeit nehmen, ein Venn-Diagramm zu erstellen, das aufzeigt, was Sie haben, was Sie wollen und was richtig ist.\n<\/p>\n<p>Die gute Nachricht ist, dass die Permakultur bereits die meisten Werkzeuge und Ideen enth\u00e4lt, die uns bei diesem Prozess der Eliminierung helfen k\u00f6nnen. Diese Werkzeuge und Ideen m\u00fcssen nur anders organisiert und angewandt werden, als sie es bisher getan haben. Insbesondere die zentrale Bed\u00fcrfnis- und Ertragsanalyse des Permakultur-Designs, bei der ein Element des Designs ausgew\u00e4hlt und aufgelistet wird, was es ben\u00f6tigt und was es produziert, f\u00fchren wir selten f\u00fcr das zentrale Element unserer Systeme durch: uns selbst. Wie Sie sehen werden, hilft Ihnen diese Methode bei der L\u00f6sung der ersten beiden Gruppen in Ihrem Venn-Diagramm: was Sie haben und was Sie wollen. Eine Anleitung f\u00fcr die letzte Gruppe (das, was richtig ist) kann in keiner anderen als den drei Permakultur-Ethiken gefunden werden: Sorge f\u00fcr die Erde, Sorge f\u00fcr die Menschen und Sorge f\u00fcr die Zukunft. Indem Sie diese bestehenden Konzepte innerhalb der Permakultur erweitern, werden Sie Ihr eigenes Venn-Diagramm vervollst\u00e4ndigen und den Kampf \u00fcberwinden, nicht zu wissen, was zu tun ist.\n<\/p>\n<h2>Was haben Sie?<br \/>\n<\/h2>\n<p>Bevor Sie entscheiden, was Sie selbst bei kleinen Projekten tun wollen, geschweige denn bei der Planung und Erschlie\u00dfung von Grundst\u00fccken, sollten Sie sich einen umfassenden \u00dcberblick \u00fcber die Ihnen zur Verf\u00fcgung stehenden Ressourcen verschaffen.\n<\/p>\n<p>Die beiden Arten von Ressourcen, an die man zuerst denkt, sind in der Regel finanzielle und materielle. Aber es gibt noch viel mehr Ressourcen als das Geld auf Ihrem Bankkonto oder die Werkzeuge und Materialien in Ihrer Garage. Bevor Sie wissen, wie Sie vorgehen sollen, m\u00fcssen Sie eine ganzheitliche Bestandsaufnahme aller Ressourcen erstellen, die Sie besitzen oder zu denen Sie Zugang haben und die Ihnen helfen oder Sie behindern k\u00f6nnen.\n<\/p>\n<p>Die acht Formen des Kapitals, die von den Permakulturwissenschaftlern Ethan Roland und Gregory Landua entwickelt wurden, sind ein ganzheitlicher Rahmen zur Erweiterung unserer Definition von Ressourcen. Der Rahmen umfasst lebende, soziale, spirituelle, erfahrungsbezogene, intellektuelle und kulturelle Ressourcen, zus\u00e4tzlich zu den allgemeineren finanziellen und materiellen Ressourcen. Der obige Link beschreibt diese Ressourcen und zeigt f\u00fcr jede einzelne die gemeinsamen W\u00e4hrungen, die N\u00fctzlichkeit f\u00fcr das letztendliche Ziel, das Wohlbefinden zu steigern, und die gemeinsamen vorhandenen Inventare.\n<\/p>\n<p>Bei einer Bestandsaufnahme der pers\u00f6nlichen Ressourcen m\u00fcssen Sie alle Dinge innerhalb dieser acht Kategorien auflisten, die Sie zur Erreichung Ihrer Ziele einsetzen oder nutzen k\u00f6nnen, und auch alle negativen Ressourcen oder Schulden innerhalb dieser Ressourcen. Zum Beispiel k\u00f6nnten Sie einer Bank Geld schulden (eine Schuld bei Ihren finanziellen Ressourcen) oder einem Freund einen Gefallen schulden (eine Schuld bei Ihren sozialen Ressourcen).\n<\/p>\n<p>Ich erinnere mich, dass ich drei wichtige Erkenntnisse hatte, als ich mir zum ersten Mal die Zeit nahm, diese \u00dcbung durchzuf\u00fchren. Meine erste Erkenntnis war, wie reich ich wirklich war. Wenn man fr\u00fcher nur meine Einkommenssteuererkl\u00e4rung als Ma\u00dfstab f\u00fcr meinen Reichtum herangezogen h\u00e4tte, h\u00e4tte es den Anschein gehabt, dass ich knapp \u00fcber der Armutsgrenze lebte. Jetzt, mit einem Rahmen, der die anderen wertvollen Ressourcen, die ich besitze oder auf die ich zugreifen kann, ganzheitlich kommuniziert, w\u00fcrde dieselbe Person Reichtum sehen. Und das Beste daran ist, dass dieser Reichtum steuerfrei und immun gegen die Schwankungen eines Fiat-Geldsystems ist.\n<\/p>\n<p>Meine zweite Offenbarung war, dass ich nun eine klarere Vorstellung von meinem gew\u00fcnschten Ziel hatte, zus\u00e4tzlich zu meinen neu gefundenen Ressourcen, die ein Mittel waren, um dorthin zu gelangen. Mit einer vollgestopften Garage und einem vollen Bankkonto zu sterben, hatte mich nie gereizt, aber die Investition in meine lebendigen, sozialen, spirituellen, erfahrungsbezogenen, intellektuellen und kulturellen Ressourcen wurde zu einem starken Motivator.\n<\/p>\n<p>Meine dritte Erkenntnis war, dass mein Ringen um die richtige Entscheidung nicht mehr so komplex erschien. So wie das Wasser zuverl\u00e4ssig zum tiefsten Punkt einer Landschaft flie\u00dft, schienen sich meine Entscheidungen intuitiv auf einen neuen Schwerpunkt zu konzentrieren, der eine erweiterte Definition von Wohlbefinden darstellt.\n<\/p>\n<p>Die Erstellung eines pers\u00f6nlichen Ressourceninventars half mir, die Kreise &#8220;Was hast du? &#8221; und &#8220;Was willst du? &#8221; in meinem Venn-Diagramm zu zeichnen und all die unendlichen M\u00f6glichkeiten in meinem Leben einzugrenzen. Auf diese Weise begann mein Kampf, herauszufinden, was ich tun sollte, zu versiegen.\n<\/p>\n<p>Wenn Sie Ihr eigenes pers\u00f6nliches Ressourceninventar erstellen, sollten Sie ein Format w\u00e4hlen, das leicht zu navigieren und zu aktualisieren ist. Eine digitale Tabellenkalkulation oder ein Ringbuch mit Registern f\u00fcr die acht Arten von pers\u00f6nlichen Ressourcen eignen sich beide gut. Anstatt die Liste auf einem leeren Blatt Papier zu erstellen, k\u00f6nnen Sie einfach in der Spalte &#8220;Gemeinsame bestehende Verzeichnisse&#8221; nachsehen und eine Kopie der bestehenden Liste oder Ausz\u00fcge unter dem entsprechenden Reiter ablegen. Speichern Sie zum Beispiel Ihre aktuellsten Finanzausz\u00fcge oder Bank\u00fcbersichten unter der Registerkarte &#8220;Finanzielle Ressourcen&#8221; eine Liste wichtiger Personen und sozialer Verbindungen unter der Registerkarte &#8220;Soziale Ressourcen&#8221;; und so weiter. Wahrscheinlich werden Sie feststellen, dass die vorhandenen Listen unvollst\u00e4ndig sind, so dass Sie auch ein wenig Brainstorming betreiben m\u00fcssen, um ein vollst\u00e4ndigeres Bild in Bezug auf Ihr Permakulturprojekt zu erhalten.\n<\/p>\n<h2>Was wollen Sie, und was ist richtig?<br \/>\n<\/h2>\n<p>Zus\u00e4tzlich zu dem Ressourceninventar, das Sie erstellen, um zu kl\u00e4ren, was Sie haben, erstellen Sie eine Seite, die klarstellt, was Sie wollen und was richtig ist. Ich nenne dies einen &#8220;Werte und Visionen One-Pager.&#8221; Die &#8220;Werte und Visionen&#8221; Liste unten bietet eine Vorlage, die nur neun S\u00e4tze verwendet. Der erste Satz sollte Ihre grundlegenden Werte wiedergeben (die Sie auf die Permakultur-Ethik der Sorge um die Erde, die Menschen und die Zukunft st\u00fctzen k\u00f6nnen), und die acht anderen S\u00e4tze sind Aussagen \u00fcber Visionen. Ich empfehle Ihnen, f\u00fcr jede der acht Ressourcenkategorien (Leben, Soziales, Spiritualit\u00e4t, Erfahrung, Intellekt, Kultur, Finanzen und Material) einen Satz zu schreiben. Jede Visionsaussage wird die optimale Auspr\u00e4gung dieser Ressource im Hinblick auf Ihr gr\u00f6\u00dferes Wohlbefinden definieren. Einmal fertiggestellt, wird dieses Dokument nicht nur Sie und Ihre Mitentscheider auf die gleiche Seite bringen; es wird auch als pers\u00f6nlicher Coach fungieren, der Sie motiviert, wenn Sie auf dem richtigen Weg sind, oder als Schiedsrichter, der Ihnen helfen kann, Ihre Handlungen zu lenken, wenn Sie sich verirren.\n<\/p>\n<p>Sie denken vielleicht: &#8220;Warum sollte ich kl\u00e4ren, was ich will? Ich wei\u00df doch, was ich will!&#8221; Viele meiner Kunden haben sich anfangs dagegen gestr\u00e4ubt, dass ich auf diesen Schritt bestehe. Was wir zu wollen glauben, ist jedoch oft durch unsere Paradigmen getr\u00fcbt und durch eine enge Sichtweise der pers\u00f6nlichen Ressourcen begrenzt. Wenn Sie sich die Zeit nehmen, ein Ressourceninventar zu erstellen und einen One-Pager mit Werten und Visionen anzulegen, k\u00f6nnen Sie Ihre Ideen aus Ihrem eigenen Kopf herausholen und ans Tageslicht bringen, wo Sie sie mit der Klarheit der Distanz pr\u00fcfen und gestalten k\u00f6nnen. Dies wird Ihnen helfen, herauszufinden, was Sie tun k\u00f6nnen, um das Wohlbefinden aller zu steigern. Und es wird zu besseren und leichteren Entscheidungen f\u00fchren, mit mehr \u00dcbereinstimmung, weniger Konflikten und mehr Seelenfrieden. Es ist eine absolute Voraussetzung f\u00fcr den erfolgreichen Bau eines Permakultur-Grundst\u00fccks.\n<\/p>\n<h2>Bewerten Sie Ihre Visionsaussagen<br \/>\n<\/h2>\n<p>Eine meiner Lieblings\u00fcbungen, die ich mit meinen Kunden durchf\u00fchre, nachdem sie ihre Werte und Visionen ausgef\u00fcllt haben, besteht darin, dass sie sich \u00fcberlegen, wie nahe ihre derzeitige Realit\u00e4t den gerade geschriebenen Visionsaussagen ist. Ich ermutige sie, die einzelnen Aussagen f\u00fcr jede Ressource zu \u00fcberpr\u00fcfen und sich dann zu fragen, wie nah sie an der Verwirklichung ihrer Vision sind. Oft haben die Menschen das Gef\u00fchl, dass sie in einer oder zwei der pers\u00f6nlichen Ressourcenkategorien sehr gut abschneiden, aber in anderen Bereichen manchmal deutlich zur\u00fcckbleiben. Es kann auch interessant sein, wenn Partner eine L\u00fccke (oder das Fehlen einer L\u00fccke) anders sehen, was dann zu weiteren Gespr\u00e4chen und Einsichten f\u00fchrt. Denken Sie daran, dass hier die Reflexion, nicht das Schreiben, den wahren Wert hat.\n<\/p>\n<p>Der letzte Schritt dieser \u00dcbung besteht darin, sich auf die Visionsaussagen zu einigen und dann die Reihenfolge zu \u00e4ndern, in der sie auf Ihrem One-Pager erscheinen. Die Aussagen, bei denen die L\u00fccke am gr\u00f6\u00dften ist, sollten oben auf der Seite oder in der N\u00e4he davon erscheinen.\n<\/p>\n<p>Nachdem ich Dutzende von v\u00f6llig unterschiedlichen Versionen der Werte und Visionen gesehen habe, die meine Studenten, Kunden und Kollegen erstellt haben, habe ich noch keine gelesen, die ich nicht mit meinem eigenen Namen versehen wollte, h\u00f6chstens mit ein paar kleinen \u00c4nderungen. Es ist erstaunlich, dass wir, wenn wir uns die Zeit nehmen, innezuhalten und nachzudenken, alle das Gleiche wollen und wissen, was richtig ist. Ich frage mich oft, was passieren w\u00fcrde, wenn sich jeder auf unserem Planeten die Zeit nehmen w\u00fcrde, diese einfachen \u00dcbungen zu machen. Der Autor Jared Diamond fasste seine Studie \u00fcber zusammengebrochene Gesellschaften mit den Worten zusammen: &#8220;Zwei Arten von Entscheidungen scheinen mir ausschlaggebend f\u00fcr den Erfolg oder Misserfolg zu sein: langfristige Planung und die Bereitschaft, grundlegende Werte zu \u00fcberdenken.&#8221;\n<\/p>\n<h2>Werte<br \/>\n<\/h2>\n<p>So zu leben, dass es mir selbst und meinen Verwandten gut geht, und dass andere die gleichen oder bessere Chancen in der Zukunft haben.\n<\/p>\n<h2>Visionen<br \/>\n<\/h2>\n<ul>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Finanziell. <\/font><font style=\"vertical-align: inherit\">Ich verf\u00fcge \u00fcber einen vielf\u00e4ltigen \u00dcberschuss an finanziellen Ressourcen und eine kontinuierliche, zuverl\u00e4ssige Einkommensgenerierung, die mit meinen Visionen und Werten \u00fcbereinstimmt.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Sozial. <\/font><font style=\"vertical-align: inherit\">Ich habe sch\u00f6ne, unterst\u00fctzende, liebevolle, ehrliche und bedeutungsvolle Beziehungen innerhalb einer bl\u00fchenden und stabilen Gemeinschaft von selbstmotivierten, reifen Wesen, die ihren Selbstwert wertsch\u00e4tzen und sich der Gef\u00fchle, Rechte und Menschenw\u00fcrde anderer bewusst sind.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Material. <\/font><font style=\"vertical-align: inherit\">Ich besitze oder habe Zugriff auf die minimale Menge an ethischen Besitzt\u00fcmern, die mich dabei unterst\u00fctzen, belastbar, sicher und sicher zu sein, und die mir Freude bereiten.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Leben. <\/font><font style=\"vertical-align: inherit\">Ich bin bei ausgezeichneter Gesundheit und verwalte eine ruhige Umgebung, die immer mehr an F\u00fclle gewinnt.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Intellektuell. <\/font><font style=\"vertical-align: inherit\">Ich bringe meine Ideen in den kollaborativen, st\u00e4ndig wachsenden Pool zug\u00e4nglicher und aussagekr\u00e4ftiger Informationen ein, die die Welt zu einem besseren Ort machen.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Erlebnis. <\/font><font style=\"vertical-align: inherit\">Ich teile und lerne weiterhin die F\u00e4higkeiten, die meine Visionen und Werte unterst\u00fctzen.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Spirituell. <\/font><font style=\"vertical-align: inherit\">Ich bin zuversichtlich, friedlich und in einem ausgeglichenen Geisteszustand; <\/font><font style=\"vertical-align: inherit\">Ich habe die Freiheit, meine Zeit selbst zu bestimmen und meinen Leidenschaften in vollem Umfang nachzugehen, w\u00e4hrend ich Dienst, Dankbarkeit und Vergebung praktiziere.<\/font><\/font><\/li>\n<li><font style=\"vertical-align: inherit\"><font style=\"vertical-align: inherit\">Kulturell. <\/font><font style=\"vertical-align: inherit\">Meine Familien- und Gemeinschaftsrituale, Traditionen, Kunstformen und sozialen Muster inspirieren alle dazu, Sch\u00f6nheit zu schaffen und die gemeinsamen Werte der F\u00fcrsorge f\u00fcr die Erde, die F\u00fcrsorge f\u00fcr die Menschen und die F\u00fcrsorge f\u00fcr die Zukunft zu feiern.<\/font><\/font><\/li>\n<\/ul>\n<p>Rob Avis und Michelle Avis sind Miteigent\u00fcmer von Adaptive Habitat, einem f\u00fchrenden Unternehmen f\u00fcr Immobilienplanung, und Verge Permaculture, einem weltweit anerkannten und preisgekr\u00f6nten Bildungsunternehmen. Takota Coen ist Permakultur-Lehrer, Red Seal Carpenter, Biobauer der zweiten Generation und Miteigent\u00fcmer und Betreiber der Coen Farm, einer preisgekr\u00f6nten 250-Hektar-Permakultur-Farm in Alberta, Kanada. Dies ist ein Auszug aus ihrem Buch Building Your Permaculture Property (New Society Publishers).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nehmen Sie sich Zeit, um Ihre Ressourcen, Bed\u00fcrfnisse und W\u00fcnsche zu erfassen, damit Sie erfolgreich eine Permakultur-Farm oder ein Permakultur-Grundst\u00fcck gestalten k\u00f6nnen. Die Umsetzung von Permakultur-Praktiken kann \u00fcberw\u00e4ltigend sein, aber nicht wegen eines Mangels an Informationen, Werkzeugen, Techniken, F\u00e4higkeiten oder Rezepten. Vielmehr ist es das Fehlen eines klar definierten Prozesses, um ein Permakultur-Grundst\u00fcck zu entwerfen, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81860,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[116],"tags":[],"class_list":["post-81839","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-garden-planning"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts\/81839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/comments?post=81839"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts\/81839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/media\/81860"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/media?parent=81839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/categories?post=81839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/tags?post=81839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}