{"id":81371,"date":"2023-03-07T11:11:16","date_gmt":"2023-03-07T08:11:16","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/de-karottensorten-fur-das-ganze-jahr\/"},"modified":"2023-03-07T11:11:16","modified_gmt":"2023-03-07T08:11:16","slug":"de-karottensorten-fur-das-ganze-jahr","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/de\/2023\/03\/07\/de-karottensorten-fur-das-ganze-jahr\/","title":{"rendered":"Karottensorten f\u00fcr das ganze Jahr"},"content":{"rendered":"<p>Wenn Sie die richtigen Karottensorten ausw\u00e4hlen und im Fr\u00fchjahr und Sommer s\u00e4en, k\u00f6nnen Sie das ganze Jahr \u00fcber frische Karotten essen. Sie k\u00f6nnen M\u00f6hren ernten, wenn Sie sie brauchen, einige im Boden \u00fcberwintern lassen und immer welche im K\u00fchlschrank haben, die gewaschen und verzehrfertig sind.\n<\/p>\n<p>Die nordamerikanischen M\u00f6hren werden anhand der Form ihrer Wurzeln in f\u00fcnf Hauptkategorien eingeteilt. Es gibt viele \u00dcberschneidungen zwischen den Kategorien (z. B. Nantes-Imperator-Typen), aber diese allgemeinen Klassifizierungen sind n\u00fctzlich f\u00fcr die Auswahl von M\u00f6hrensorten auf der Grundlage des Bodentyps in Ihrem Garten und der Jahreszeit, in der Sie sie anbauen m\u00f6chten.\n<\/p>\n<p>Nantes: gerade, zylindrische Wurzeln, 5 bis 7 Zoll lang; s\u00fc\u00dfer Geschmack und knackige Textur; begrenzte Lagerf\u00e4higkeit Sorten: &#8216;Early Nantes&#8217; (OP*), &#8216;Nelson&#8217; (F1*), &#8216;Mokum&#8217; (F1) Saison: Fr\u00fchjahr bis Fr\u00fchsommer, Sp\u00e4tsommer bis Herbst Boden: lockerer, sandiger Boden oder mit organischen Stoffen angereicherte Hochbeete Tage bis zur Reife: 55 bis 70 im Fr\u00fchjahr, 60 bis 75 im Herbst\n<\/p>\n<p>Chantenay: konische Wurzeln mit breiten Schultern und abgerundeten Spitzen; reichhaltiger, s\u00fc\u00dfer Geschmack und gute Lagerf\u00e4higkeit Sorten: &#8216;Red Core Chantenay&#8217; (OP), &#8216;Kuttiger&#8217; (OP), &#8216;Kurota&#8217; (OP) Saison: Fr\u00fchjahr bis Fr\u00fchsommer, Hochsommer bis Sp\u00e4therbst Boden: beste Sorten f\u00fcr Lehmboden oder jeden fruchtbaren Lehm Tage bis zur Reife: 55 bis 70 im Fr\u00fchjahr; 70 bis 110 im Herbst\n<\/p>\n<p>Imperator: lange, spitz zulaufende Wurzeln mit st\u00e4mmigen Schultern und kr\u00e4ftigen Spitzen; leicht faserige Textur; gut lagerf\u00e4hig Sorten: &#8216;Yellowstone&#8217; (OP), &#8216;Purple Haze&#8217; (F1), &#8216;Sugarsnax&#8217; (F1) Saison: Fr\u00fchjahr bis Sommer in k\u00fchlen Klimazonen, oder Sommer bis Herbst Boden: erfordert tiefgr\u00fcndigen, sandigen Lehm Tage bis zur Reife: 55 bis 100 im Fr\u00fchjahr, 80 bis 110 im Herbst\n<\/p>\n<p>Danvers: dickwurzelige zylindrische Form, oft mit gelblichem Kern; weit verbreitet in der Verarbeitung; gut lagerf\u00e4hig und gut zum Entsaften geeignet Sorten: &#8216;Danvers&#8217; (OP), &#8216;Healthmaster&#8217; (F1), &#8216;Danvers Half Long&#8217; (OP) Saison: Fr\u00fchjahr bis Sommer in k\u00fchlem Klima, oder Sommer bis Herbst Boden: tiefer, sandiger Lehm oder Hochbeete Tage bis zur Reife: 70 bis 80 im Fr\u00fchjahr, 80 bis 110 im Herbst\n<\/p>\n<p>Miniatur & Baby: runde, zylindrische oder spitz zulaufende Wurzeln von weniger als 5 Zoll L\u00e4nge; knackige Textur und h\u00e4ufig recht s\u00fc\u00df; begrenzte Lagerf\u00e4higkeit Sorten: &#8216;D\u00e4umling&#8217; (OP), &#8216;Kleiner Finger&#8217; (OP), &#8216;Parmex&#8217; (OP) Saison: Fr\u00fchjahr bis Fr\u00fchsommer, Sp\u00e4tsommer bis Herbst Boden: jeder fruchtbare Boden, der gut abflie\u00dft Tage bis zur Reife: 50 bis 60 im Fr\u00fchjahr, 60 bis 70 im Herbst\n<\/p>\n<p>*OP = Nicht-Hybrid, Saatgut kann aufbewahrt werden; F1 = Hybrid, Saatgut kann nicht aufbewahrt werden\n<\/p>\n<p>Neugierig auf Karotten? Erfahren Sie in Growing Carrots, wie Sie dieses schmackhafte Gem\u00fcse anbauen k\u00f6nnen, das sich auch als Snack eignet: Karottensorten, Bodenbedingungen und Erntezeiten. Probieren Sie dieses Rezept f\u00fcr eingelegte Karotten mit Ingwer, um Ihren Karotten etwas Pepp zu verleihen.\n<\/p>\n<p>Die Redakteurin Barbara Pleasant g\u00e4rtnert im S\u00fcdwesten Virginias, wo sie Gem\u00fcse, Kr\u00e4uter, Obst, Blumen und ein paar gl\u00fcckliche H\u00fchner anbaut.\n<\/p>\n<p>Urspr\u00fcnglich ver\u00f6ffentlicht als &#8220;Eat Fresh Carrots All Year&#8221; in der April<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn Sie die richtigen Karottensorten ausw\u00e4hlen und im Fr\u00fchjahr und Sommer s\u00e4en, k\u00f6nnen Sie das ganze Jahr \u00fcber frische Karotten essen. Sie k\u00f6nnen M\u00f6hren ernten, wenn Sie sie brauchen, einige im Boden \u00fcberwintern lassen und immer welche im K\u00fchlschrank haben, die gewaschen und verzehrfertig sind. Die nordamerikanischen M\u00f6hren werden anhand der Form ihrer Wurzeln in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81392,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[122],"tags":[],"class_list":["post-81371","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-vegetables"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts\/81371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/comments?post=81371"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts\/81371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/media\/81392"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/media?parent=81371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/categories?post=81371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/tags?post=81371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}