{"id":80981,"date":"2023-03-07T11:01:44","date_gmt":"2023-03-07T08:01:44","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/de-serie-biologische-schadlingsbekampfung-organische-pestizide-verwenden\/"},"modified":"2023-03-07T11:01:44","modified_gmt":"2023-03-07T08:01:44","slug":"de-serie-biologische-schadlingsbekampfung-organische-pestizide-verwenden","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/de\/2023\/03\/07\/de-serie-biologische-schadlingsbekampfung-organische-pestizide-verwenden\/","title":{"rendered":"Serie Biologische Sch\u00e4dlingsbek\u00e4mpfung: Organische Pestizide verwenden"},"content":{"rendered":"<p>Wenn sie mit einem Sch\u00e4dlingsproblem konfrontiert sind, w\u00fcnschen sich G\u00e4rtner oft eine L\u00f6sung aus der Spr\u00fchflasche und nicht die sicherere Variante der biologischen Sch\u00e4dlingsbek\u00e4mpfungsmittel. Es stimmt, dass viele Gifte, die in Gartencentern verkauft werden, alle und oft auch alle Insekten im Garten t\u00f6ten. Aber Pestizide sind gef\u00e4hrlich f\u00fcr Menschen und Wildtiere, und die meisten t\u00f6ten neben den Problemsch\u00e4dlingen auch n\u00fctzliche Insekten.\n<\/p>\n<p>Selbst biologische Sch\u00e4dlingsbek\u00e4mpfungsmittel k\u00f6nnen n\u00fctzliche Insekten abt\u00f6ten, daher sollten sie vorsichtig und nur als letztes Mittel eingesetzt werden. Informieren Sie sich \u00fcber die in Ihrer Region h\u00e4ufig vorkommenden Sch\u00e4dlinge und ihre nat\u00fcrlichen Feinde sowie \u00fcber Anbaumethoden, die die Populationen niedrig halten, bevor Sie sich f\u00fcr den Anbau von Nutzpflanzen entscheiden.\n<\/p>\n<p>Die auf diesen Seiten beschriebenen biologischen Sch\u00e4dlingsbek\u00e4mpfungsmittel schaden nur minimal den Organismen, die Sie nicht sch\u00e4digen wollen, einschlie\u00dflich der Menschen. Diese Produkte sind auch nach den Standards des National Organic Program zugelassen, das als Rahmen f\u00fcr die zertifizierte \u00f6kologische Lebensmittelproduktion dient. Das gemeinn\u00fctzige Organic Materials Review Institute (OMRI) wiederum bewertet, ob bestimmte Produkte diesen Standards entsprechen oder nicht. OMRI setzt ein Expertengremium ein, dem Landwirte, Wissenschaftler, Umweltsch\u00fctzer und Gesch\u00e4ftsleute angeh\u00f6ren, um zu entscheiden, welche Produkte f\u00fcr die Verwendung durch \u00f6kologische Landwirte zugelassen werden sollten. Zugelassene Produkte tragen in der Regel das OMRI-Siegel auf ihrem Etikett, oder Sie k\u00f6nnen bei OMRI nachsehen, ob ein Produkt zugelassen, eingeschr\u00e4nkt oder nicht zugelassen ist.\n<\/p>\n<p>OMRI hat zwei Kategoriecodes f\u00fcr zul\u00e4ssige Produkte: &#8220;A&#8221; f\u00fcr erlaubt und &#8220;R&#8221; f\u00fcr eingeschr\u00e4nkt. Zugelassene Produkte k\u00f6nnen nach dem Ermessen des Landwirts verwendet werden; die meisten von ihnen sind Bodenverbesserungsmittel und organische D\u00fcngemittel. Viele biologische Pestizide sind mit einem eingeschr\u00e4nkten Code versehen, da sie n\u00fctzliche Insekten und andere Wildtiere sch\u00e4digen k\u00f6nnen und daher sparsam verwendet werden sollten. Obwohl alle hier aufgelisteten Produkte eine OMRI-Zulassung haben, fallen viele in die Kategorie mit eingeschr\u00e4nktem Anwendungsbereich und sollten nur dann eingesetzt werden, wenn kulturelle Kontrollen versagt haben, und zwar immer gem\u00e4\u00df den Anweisungen auf dem Etikett.\n<\/p>\n<\/p>\n<p>Zwei altbew\u00e4hrte nat\u00fcrliche Sch\u00e4dlingsbek\u00e4mpfungsmittel, Rotenon und Sabadilla, werden hier nicht aufgef\u00fchrt, da sie nicht mehr im Handel erh\u00e4ltlich sind und daher wahrscheinlich nicht mehr verwendet werden. Rotenon wurde fr\u00fcher von Biog\u00e4rtnern h\u00e4ufig eingesetzt, um hartn\u00e4ckige Sch\u00e4dlinge wie Kartoffelk\u00e4fer und Kohlw\u00fcrmer zu bek\u00e4mpfen. Das aus den pulverisierten Samen von Jicama und anderen tropischen Reben hergestellte Rotenon war ein Grundnahrungsmittel in Gartenst\u00e4uben und Flohpulvern f\u00fcr Haustiere. Rotenon ist nicht mehr f\u00fcr die Verwendung bei Tieren oder in G\u00e4rten zugelassen, was auch gut so ist. Eine k\u00fcrzlich durchgef\u00fchrte Studie hat Rotenon mit einer signifikanten Zunahme der Parkinson-Krankheit beim Menschen in Verbindung gebracht. Der einzige derzeit zugelassene Verwendungszweck von Rotenon ist die gezielte Bek\u00e4mpfung von invasiven Arten.\n<\/p>\n<\/p>\n<p>Sabadillastaub, der aus den getrockneten Samen einer s\u00fcdamerikanischen Lilie gewonnen wird, wurde fr\u00fcher von Biog\u00e4rtnern h\u00e4ufig zur Bek\u00e4mpfung von K\u00fcrbiswanzen verwendet. Er ist jedoch auch sehr reizend f\u00fcr Augen und Lunge und giftig f\u00fcr viele n\u00fctzliche Insektenarten. Derzeit sind keine Bio-Sabadilla-Produkte erh\u00e4ltlich, und die einzige zugelassene Verwendung f\u00fcr Sabadilla-Produkte ist die Bek\u00e4mpfung von saugenden Insekten auf Zitrusfr\u00fcchten und Mangos.\n<\/p>\n<p>Sehen Sie sich auch die anderen Abschnitte unserer Serie \u00fcber biologische Sch\u00e4dlingsbek\u00e4mpfung an: N\u00fctzliche Insekten und gew\u00f6hnliche Gartensch\u00e4dlinge.\n<\/p>\n<h3>Bt (Bacillus thuringiensis)<br \/>\n<\/h3>\n<p>Erfahren Sie, wie Sie Bt-Produkte (Bacillus thuringiensis) zur Bek\u00e4mpfung von Raupen und Sch\u00e4dlingen in Ihrem Gem\u00fcsegarten einsetzen k\u00f6nnen. Bt ist eines der sichersten nat\u00fcrlichen Pestizide, die Sie zur Bek\u00e4mpfung von Raupensch\u00e4dlingen einsetzen k\u00f6nnen, ohne n\u00fctzliche Insekten zu sch\u00e4digen.\n<\/p>\n<h3>H\u00fchner<br \/>\n<\/h3>\n<p>H\u00fchner sind zwar keine biologischen Sch\u00e4dlingsbek\u00e4mpfungsmittel, aber sie fressen jedes Insekt, das sich bewegt, einschlie\u00dflich Heuschrecken, Kartoffelk\u00e4fer, Schnecken und mehr. Wenn Sie es H\u00fchnern nicht zutrauen, in Ihren Gem\u00fcse- und Blumenbeeten herumzustreifen, f\u00fcttern Sie sie mit der Hand mit gefangenen Insekten.\n<\/p>\n<h3>Kieselgur (DE)<br \/>\n<\/h3>\n<p>Kieselgur (DE) schneidet in den K\u00f6rper der Insekten ein, so dass sie auf nat\u00fcrliche Weise an Austrocknung sterben. Achten Sie beim Kauf von Kieselgur f\u00fcr den Hausgebrauch darauf, ein Produkt zu kaufen, das als \"lebensmittelecht\" gekennzeichnet ist;\n<\/p>\n<h3>Gartenbau\u00f6le<br \/>\n<\/h3>\n<p>Gartenbau\u00f6le sind besonders n\u00fctzlich im \u00f6kologischen Obstbau, wo sie Sch\u00e4dlinge bek\u00e4mpfen, die in Rindenspalten \u00fcberwintern. Die empfohlene Praxis f\u00fcr die Anwendung von Gartenbau\u00f6len ist das Bespr\u00fchen der B\u00e4ume im Fr\u00fchjahr, kurz bevor sich die Bl\u00fctenknospen \u00f6ffnen.\n<\/p>\n<h3>Insektizide Seife<br \/>\n<\/h3>\n<p>Erfahren Sie, wie Sie Insektizidseife zur Bek\u00e4mpfung von Weichk\u00f6rpersch\u00e4dlingen wie Blattl\u00e4usen, Wei\u00dfen Fliegen und anderen einsetzen k\u00f6nnen. Bei guter Lagerung k\u00f6nnen insektizide Seifenprodukte f\u00fcnf Jahre oder l\u00e4nger halten. &nbsp;\n<\/p>\n<h3>Neem<br \/>\n<\/h3>\n<p>Neem\u00f6l ist ein Derivat des asiatischen immergr\u00fcnen Baumes. Es ist ein nat\u00fcrliches Steroid und bewirkt, dass Insekten ihren Appetit und die Lust am Eierlegen verlieren.  Neem wird am besten pr\u00e4ventiv eingesetzt, bevor Sch\u00e4dlinge zu einem ernsten Problem werden.\n<\/p>\n<h3>Pyrethrum<br \/>\n<\/h3>\n<p>Bio-Pyrethrumspray l\u00e4hmt Insekten, die damit in Ber\u00fchrung kommen, und ist das st\u00e4rkste Insektizid, das nach den Richtlinien der Nationalen \u00d6kologischen Standards zugelassen ist. Erfahren Sie, wie Sie dieses wirksame Bio-Pestizid herstellen, anwenden und lagern k\u00f6nnen.\n<\/p>\n<h3>Spinosad<br \/>\n<\/h3>\n<p>Das biologische Sch\u00e4dlingsbek\u00e4mpfungsmittel Spinosad bek\u00e4mpft alle Arten von Raupen sowie die Larven des Kartoffelk\u00e4fers und des Blasenk\u00e4fers. Erfahren Sie, wie Sie dieses wirksame biologische Pestizid f\u00fcr eine effektive biologische Sch\u00e4dlingsbek\u00e4mpfung anwenden und lagern k\u00f6nnen.\n<\/p>\n<h2>Leitfaden f\u00fcr Garteninsekten<br \/>\n<\/h2>\n<p>Laden Sie hier Ihren kostenlosen Leitfaden f\u00fcr Gartensch\u00e4dlinge herunter und erfahren Sie, welche Sch\u00e4dlinge Freund oder Feind sind und welche biologischen Sch\u00e4dlingsbek\u00e4mpfungsmethoden es gibt.\n<\/p>\n<h2>Leitfaden f\u00fcr Garteninsekten<br \/>\n<\/h2>\n<p>Laden Sie hier Ihren kostenlosen Leitfaden f\u00fcr Gartensch\u00e4dlinge herunter und erfahren Sie, welche Sch\u00e4dlinge Freund oder Feind sind und welche biologischen Sch\u00e4dlingsbek\u00e4mpfungsmethoden es gibt.\n<\/p>\n<h2>Haben Sie einen K\u00e4fer in Ihrem Garten entdeckt?<br \/>\n<\/h2>\n<p>Erz\u00e4hlen Sie uns davon, und Sie helfen dem Citizen-Science-Projekt Big Bug Hunt.\n<\/p>\n<h2>Noch mehr Artikel \u00fcber&nbsp;Bio-Pestizide<br \/>\n<\/h2>\n<p>Sichere hausgemachte nat\u00fcrliche Pestizide\n<\/p>\n<p>Wenn Sie Ihren Garten von vielen zerst\u00f6rerischen Insekten befreien wollen, ohne auf gef\u00e4hrliche Chemikalien zur\u00fcckzugreifen, finden Sie hier einige Vorschl\u00e4ge f\u00fcr sichere, selbstgemachte nat\u00fcrliche Pestizide.\n<\/p>\n<p>H\u00fchner im Garten: Organische Sch\u00e4dlingsbek\u00e4mpfung\n<\/p>\n<p>Die beste nat\u00fcrliche Sch\u00e4dlingsbek\u00e4mpfung bietet die Herde in Ihrem Hinterhof.\n<\/p>\n<p>Milch als nat\u00fcrliches, hausgemachtes Pestizid\n<\/p>\n<p>Die meisten Menschen kennen den Wert von Milch, aber nur wenige wissen, dass sie ein wesentlicher Bestandteil eines einfachen Insektenschutzmittels ist. Erfahren Sie, wie Sie Milch einsetzen k\u00f6nnen, um Ihre Familie vor Ungeziefer zu sch\u00fctzen.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wenn sie mit einem Sch\u00e4dlingsproblem konfrontiert sind, w\u00fcnschen sich G\u00e4rtner oft eine L\u00f6sung aus der Spr\u00fchflasche und nicht die sicherere Variante der biologischen Sch\u00e4dlingsbek\u00e4mpfungsmittel. Es stimmt, dass viele Gifte, die in Gartencentern verkauft werden, alle und oft auch alle Insekten im Garten t\u00f6ten. Aber Pestizide sind gef\u00e4hrlich f\u00fcr Menschen und Wildtiere, und die meisten t\u00f6ten [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":81002,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121],"tags":[],"class_list":["post-80981","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-pest-control"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts\/80981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/comments?post=80981"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts\/80981\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/media\/81002"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/media?parent=80981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/categories?post=80981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/tags?post=80981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}