{"id":80747,"date":"2023-03-07T10:55:56","date_gmt":"2023-03-07T07:55:56","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/de-essbare-rosen-schone-und-kostliche-gartenmerkmale\/"},"modified":"2023-03-07T10:55:56","modified_gmt":"2023-03-07T07:55:56","slug":"de-essbare-rosen-schone-und-kostliche-gartenmerkmale","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/de\/2023\/03\/07\/de-essbare-rosen-schone-und-kostliche-gartenmerkmale\/","title":{"rendered":"Essbare Rosen: Sch\u00f6ne und k\u00f6stliche Gartenmerkmale"},"content":{"rendered":"<p>Eat Your Yard! (Gibbs Smith, 2010) enth\u00e4lt Informationen \u00fcber 35 essbare Pflanzen, die das Beste aus Landschaft und K\u00fcche bieten. Essbare Gartenpflanzen bieten Fr\u00fchlingsbl\u00fcten, farbenfrohe Fr\u00fcchte und Blumen, \u00fcppiges Gr\u00fcn, Herbstlaub und eine sch\u00f6ne Struktur, aber auch Fr\u00fcchte, N\u00fcsse und Samen, die man essen, kochen und einmachen kann. Rosen eignen sich besonders gut f\u00fcr die Gestaltung einer essbaren Landschaft, wie der folgende Auszug zeigt.\n<\/p>\n<p>Kaufen Sie dieses Buch im MOTHER EARTH NEWS Shop: Eat Your Yard!\n<\/p>\n<p>Lesen Sie mehr von Eat Your Yard!  - Essbare Minze f\u00fcr Ihren Garten - Wachsende Haseln\u00fcsse im Garten\n<\/p>\n<h2>Rosen essen<br \/>\n<\/h2>\n<p>Die Rose ist ein botanisches Mutterschiff, das mit vielem verbunden ist, was in unseren G\u00e4rten w\u00e4chst: von Nektarinen bis zu Erdbeeren<\/p>\n<p>&#8220;K\u00f6nigin der Blumen!&#8221; ruft eine Quelle aus.\n<\/p>\n<p>Rosen sind wegen des intensiven Dufts und der bezaubernden Sch\u00f6nheit ihrer Bl\u00fcten weltweit beliebt. Au\u00dferdem tragen sie zur Best\u00e4ubung anderer Pflanzen bei.\n<\/p>\n<p>Es gibt Wildrosen, die in Nordamerika beheimatet sind, oder solche, die eingef\u00fchrt und eingeb\u00fcrgert wurden und sich von der K\u00fcste bis zu den Berggipfeln anpassen. Und es gibt gez\u00fcchtete, reinrassige Rosen, die sich nur dort eignen, wo das Klima mitspielt und die Menschen sie verw\u00f6hnen k\u00f6nnen<\/p>\n<p>Wildrosen, um die Situation noch komplizierter zu machen, k\u00f6nnen im Garten sehr gut gedeihen &#8212; oder sehr zerst\u00f6rerisch sein.\n<\/p>\n<p>Lassen Sie&#8217;s zustimmen, um zu betr\u00fcgen und einige geb\u00fcrtige nordamerikanische Rosen und einige importierte Rosen zusammen zu betrachten (importiert, das hei\u00dft, w\u00e4hrend der kolonialen Zeiten oder fr\u00fch und dann verbreitend), bevor man das n\u00fctzlichste und am wenigsten intrusive f\u00fcr die essbare Landschaft w\u00e4hlt<\/p>\n<p>Zun\u00e4chst ein Wort dazu, warum Rosen \u00fcberhaupt als essbar gelten sollten.\n<\/p>\n<p>Zum einen haben Rosenbl\u00fcten einen leichten, s\u00fc\u00dfen Geschmack und k\u00f6nnen frisch in Salaten gegessen werden, wo sie unerwartete Farbe hinzuf\u00fcgen; ein Autor kombiniert sie mit Gurken f\u00fcr einen optischen Genuss. Die jungen Triebe einiger Rosen, die sorgf\u00e4ltig ges\u00e4ubert werden, sind ebenfalls essbar und haben einen angenehmen Knack.\n<\/p>\n<p>Es ist die Frucht der Rose, die Aufmerksamkeit verdient und die eine lange, ern\u00e4hrungsphysiologisch wichtige Rolle in der Zivilisation spielt, vor allem in n\u00f6rdlichen Klimazonen, wo andere Fr\u00fcchte schwer anzubauen sind, und in Kriegszeiten, wenn die Versorgung mit Vitamin C unterbrochen ist.<\/p>\n<p>Die kleinen Fr\u00fcchte, die Hagebutten genannt werden, haben den h\u00f6chsten Vitamin-C-Gehalt aller frischen Lebensmittel, und obwohl sie roh verzehrt werden k\u00f6nnen, werden Hagebutten meist vor dem Gebrauch gekocht. Die Samen, die haarig sind und ein unangenehmes Kitzeln im Hals verursachen, werden fast immer entweder gekocht und abgeseiht oder einfach ausgespuckt. Hagebutten k\u00f6nnen zu Saft verarbeitet werden, um Gelee, Sirup und So\u00dfen herzustellen. Dieser Saft kann in Flaschen abgef\u00fcllt und das ganze Jahr \u00fcber aufbewahrt werden. Aus Hagebutten und Rosenbl\u00e4ttern werden auch spezielle Weine, Schn\u00e4pse und Lik\u00f6re hergestellt.<\/p>\n<p>Hagebutten sind breiige, mit Samen gef\u00fcllte Schoten, die im Sp\u00e4therbst die Rosenstr\u00e4ucher mit ihren roten oder orangefarbenen (auch dunkelblauen) Farben schm\u00fccken. Die Hagebutten variieren in Gr\u00f6\u00dfe und Form, meist sind sie nicht viel gr\u00f6\u00dfer als eine Weintraube. Mit Frost bedeckt sind sie in einer ansonsten farblosen Landschaft ein spektakul\u00e4rer Anblick.\n<\/p>\n<p>Im Gegensatz zu den anspruchsvolleren Hybridrosen haben sich Wildrosen im Laufe von Millionen von Jahren an die \u00f6rtlichen Bedingungen angepasst. Sie sind nahezu frei von Krankheiten und Sch\u00e4dlingen. Sie m\u00fcssen kaum beschnitten oder ged\u00fcngt werden, vertragen Temperaturen weit unter dem Gefrierpunkt und k\u00f6nnen auch auf kargen B\u00f6den wachsen.\n<\/p>\n<p>In manchen F\u00e4llen werden Wildrosen bis zu zehn oder f\u00fcnfzehn Meter hoch und bilden beeindruckende Hecken. Bevor Sie Wildrosen pflanzen, sollten Sie sich auf jeden Fall bei den \u00f6rtlichen Landwirtschaftsbeh\u00f6rden erkundigen, ob Ihre Wahl \u00fcberhaupt legal ist&#8211;einige Wildrosen gelten als sch\u00e4dlich und sind verboten. Von der Gattung Rosa sind die Hauptverursacher Multiflora-Rosen, einschlie\u00dflich der Cherokee-Rose (die ironischerweise nicht wirklich einheimisch ist). Pflanzen Sie diese nicht<\/p>\n<p>Erforschen Sie auch andere Rosa-Arten, um herauszufinden, was sie zu Ihrer eigenen essbaren Landschaft beitragen k\u00f6nnen: Hundsrose, Pr\u00e4rie-Rose, Carolina-Rose, Glauca-Rose, Nootka-Rose (eine im Westen beheimatete Rose) und zahllose gekreuzte einheimische Rosen.\n<\/p>\n<p>Mein Favorit ist R. rugosa, die Faltenrose. Ich liebe ihre stark strukturierten gr\u00fcnen Bl\u00e4tter und ihre berauschenden rosa Bl\u00fcten<\/p>\n<h2>Hagebuttenso\u00dfe Rezept f\u00fcr Fleisch<br \/>\n<\/h2>\n<p>2 Tassen Hagebutten, entkernt 1 1\n<\/p>\n<p>Die Hagebutten in dem Wasser 1 Stunde lang k\u00f6cheln lassen. Den Zucker hinzuf\u00fcgen und weitere 5 Minuten kochen lassen. Die Speisest\u00e4rke hinzugeben und unter st\u00e4ndigem R\u00fchren 3 Minuten weiterk\u00f6cheln lassen. Eventuell kurz vor dem Servieren den Wei\u00dfwein hinzugeben.\n<\/p>\n<p>Nachgedruckt aus A Taste of Heritage: Crow Indian Recipes and Herbal Medicines von Alma Hogan Snell mit Genehmigung der University of Nebraska Press. 2006 von Alma Hogan Snell.\n<\/p>\n<h2>Hagebuttengelee-Rezept<br \/>\n<\/h2>\n<p>Am besten wird sie nach dem ersten Frost zubereitet. Etwa ein Pfund Hagebutten pfl\u00fccken und die Bl\u00fcte abschneiden. Kaum mit Wasser bedecken und k\u00f6cheln lassen, bis die Fr\u00fcchte sehr weich sind. Mit einem Geleebeutel den Saft auffangen. Eine Dose Pektin zugeben, schnell aufkochen und eine der Saftmenge entsprechende Menge Zucker zugeben. Zum Kochen bringen und eine Minute lang halten. Umr\u00fchren und absch\u00e4umen. In sterilisierte Gl\u00e4ser f\u00fcllen und mit Paraffin bedecken.\n<\/p>\n<p>(Anmerkung des Autors: Die Gl\u00e4ser k\u00f6nnen statt mit Paraffin auch in einem herk\u00f6mmlichen kochenden Wasserbad versiegelt werden).\n<\/p>\n<p>Nachdruck mit Genehmigung von Southern Appalachian Mountain Cookin&#8217;: Authentic Ol&#8217; Mountain Family Recipes, &copy;2004, APS, Inc.\n<\/p>\n<p>Nachgedruckt mit Genehmigung von Eat Your Yard! Essbare B\u00e4ume, Str\u00e4ucher, Reben, Kr\u00e4uter und Blumen f\u00fcr Ihre Landschaft von Nan K. Chase, ver\u00f6ffentlicht von Gibbs Smith, 2010. Kaufen Sie dieses Buch in unserem Shop: Eat Your Yard! Essbare B\u00e4ume, Str\u00e4ucher, Reben, Kr\u00e4uter und Blumen f\u00fcr Ihre Landschaft.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eat Your Yard! (Gibbs Smith, 2010) enth\u00e4lt Informationen \u00fcber 35 essbare Pflanzen, die das Beste aus Landschaft und K\u00fcche bieten. Essbare Gartenpflanzen bieten Fr\u00fchlingsbl\u00fcten, farbenfrohe Fr\u00fcchte und Blumen, \u00fcppiges Gr\u00fcn, Herbstlaub und eine sch\u00f6ne Struktur, aber auch Fr\u00fcchte, N\u00fcsse und Samen, die man essen, kochen und einmachen kann. Rosen eignen sich besonders gut f\u00fcr die [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":80768,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[120],"tags":[],"class_list":["post-80747","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-ornamentals"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts\/80747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/comments?post=80747"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts\/80747\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/media\/80768"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/media?parent=80747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/categories?post=80747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/tags?post=80747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}