{"id":80617,"date":"2023-03-07T10:55:03","date_gmt":"2023-03-07T07:55:03","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/de-wie-man-trauben-im-garten-anbaut\/"},"modified":"2023-03-07T10:55:03","modified_gmt":"2023-03-07T07:55:03","slug":"de-wie-man-trauben-im-garten-anbaut","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/de\/2023\/03\/07\/de-wie-man-trauben-im-garten-anbaut\/","title":{"rendered":"Wie man Trauben im Garten anbaut"},"content":{"rendered":"<p>(Einzelheiten zum Anbau vieler anderer Gem\u00fcse- und Obstsorten finden Sie auf unserer Seite Ernte auf einen Blick).\n<\/p>\n<p>Langlebige Weintrauben k\u00f6nnen in den meisten Klimazonen angebaut werden, vorausgesetzt, Sie w\u00e4hlen die f\u00fcr Ihre Region geeigneten Sorten. In Minnesota gez\u00fcchtete, k\u00e4lteresistente Sorten k\u00f6nnen Temperaturen von bis zu minus 30 Grad Celsius \u00fcberstehen, w\u00e4hrend krankheitsresistente Muscadine-Trauben in warmen Klimazonen mit begrenzter Winterabk\u00fchlung hervorragend gedeihen. Der biologische Anbau von Weintrauben ist im trockenen Westen einfacher als im feuchten Osten, wo die Krankheitsvorbeugung eine h\u00f6here Priorit\u00e4t hat.\n<\/p>\n<h2>Traubensorten zum Probieren<br \/>\n<\/h2>\n<p>Kernlose Tafeltrauben liefern saftige, d\u00fcnnh\u00e4utige Beeren, die sich gut zum Frischverzehr, zum Trocknen als Rosinen oder zur Herstellung von Saft eignen.\n<\/p>\n<p>Die Labrusca-Trauben haben wilde nordamerikanische Trauben in ihrem Stammbaum, was ihnen einen kr\u00e4ftigen Geschmack verleiht, der ideal f\u00fcr Saft und Gelee ist. Labrusca-Trauben vertragen kalte Wintertemperaturen gut.\n<\/p>\n<p>Muscadine-Trauben werden am besten in warmen, feuchten Klimazonen angebaut und liefern s\u00fc\u00dfe Beeren mit einem kr\u00e4ftigen, moschusartigen Geschmack, der sich hervorragend zum Frischverzehr, f\u00fcr Saft, Gelee oder Wein eignet.\n<\/p>\n<p>Wei\u00dfweintrauben, die aus der Kreuzung europ\u00e4ischer und nordamerikanischer Trauben hervorgegangen sind, k\u00f6nnen in g\u00fcnstigen Lagen biologisch angebaut werden. Wei\u00dfweintrauben reifen fr\u00fcher als dunkle Trauben und sind daher die beste Wahl in Gebieten mit kurzen Sommern. Einige Sorten, wie die Traminette, brauchen nur 110 Tage von der Bl\u00fcte bis zur Ernte.\n<\/p>\n<p>Rotweintrauben brauchen zwischen 105 und 140 Tagen nach der Bl\u00fcte, um reif zu werden; w\u00e4hlen Sie daher in kalten Klimazonen fr\u00fch reifende Sorten. Rotweintrauben k\u00f6nnen Ertr\u00e4ge von \u00fcber 30 Pfund pro Pflanze liefern.\n<\/p>\n<figure><img decoding=\"async\" src=\"https:\/\/my-garden.blog\/auto_content\/local_image\/868488876618150.webp\" \/><\/figure>\n<h2>Wann man Trauben pflanzt<br \/>\n<\/h2>\n<p>Setzen Sie die gekauften Pflanzen im Fr\u00fchjahr 4 bis 6 Wochen vor dem letzten Frost, wenn die Pflanzen aus der Winterruhe kommen. Traubensorten, die im Container gezogen werden, k\u00f6nnen bis zum Fr\u00fchsommer gepflanzt werden.\n<\/p>\n<h2>Wie man Trauben pflanzt<br \/>\n<\/h2>\n<p>Der Anbau von Weintrauben in voller Sonne f\u00f6rdert die Entwicklung s\u00fc\u00dfer, geschmackvoller Fr\u00fcchte. Die Pflanzen k\u00f6nnen jahrzehntelang Fr\u00fcchte tragen, wenn sie in einem tiefgr\u00fcndigen, fruchtbaren Boden wachsen, der gut entw\u00e4ssert. Vor dem Pflanzen sollten Sie alle mehrj\u00e4hrigen Unkr\u00e4uter ausgraben und den Boden mit mindestens 5 cm reifem Kompost oder anderen hochwertigen organischen Stoffen anreichern. Wenn Ihr Boden eher sauer ist, k\u00f6nnen Sie den pH-Wert durch leichte Zugabe von Kalk oder Holzasche auf 5,6 bis 6,2 anheben.\n<\/p>\n<p>Die meisten Weintrauben sollten in einem Abstand von 7 bis 9 Fu\u00df gepflanzt werden, wobei bei der Pflanzung ein haltbares Spalier angebracht werden sollte. Gie\u00dfen Sie die Trauben nach der Pflanzung gr\u00fcndlich und mulchen Sie die Fl\u00e4che unter den Pflanzen mit 2 bis 4 Zoll Holzsp\u00e4nen oder einem anderen organischen Mulch.\n<\/p>\n<h2>Spalieren und Beschneiden von Trauben<br \/>\n<\/h2>\n<p>Wenn Sie die Gestaltung Ihres Spaliers und den Schnitt auf die nat\u00fcrliche Wuchsform der von Ihnen gew\u00e4hlten Rebsorte abstimmen, k\u00f6nnen Sie Krankheiten vorbeugen und die Produktivit\u00e4t maximieren. Im Allgemeinen bilden Concord-Trauben und andere Labrusca-Sorten an langen St\u00f6cken nach unten gerichtete Zweige, die eine Kaskade von Bl\u00e4ttern bilden. Sie gedeihen daher am besten an einem hohen Spalier oder einer Laube. Auch Muscadine-Trauben lassen sich am einfachsten an einem rechteckigen Spalier, auch X-Spalier genannt, kultivieren. Bei diesen kr\u00e4ftigen Fr\u00fcchten sollte der Schnitt darauf ausgerichtet sein, zwei bis vier 1,5 m lange Ruten zu erhalten und gleichzeitig \u00fcbersch\u00fcssiges Wachstum abzuschneiden.\n<\/p>\n<p>Die meisten Tafel- und Keltertrauben bilden nach oben gerichtete Triebe aus. Daher ist ein zweistufiges Spalier am besten geeignet, das die Zweige st\u00fctzt, wenn sie an H\u00f6he gewinnen. Spaliere aus engmaschigem Draht sind vorzuziehen, da sie die Reben gut st\u00fctzen, wenn sie mit Fr\u00fcchten beladen werden. Der R\u00fcckschnitt von Tafel- und Keltertrauben sollte aggressiv sein: Entfernen Sie alle alten Triebe mit Ausnahme ausgew\u00e4hlter Fruchttriebe. Wenn Sie Tafeltrauben an einer Laube anbauen, k\u00f6nnen Sie etwas weniger schneiden, wenn Sie eine dichte Laubdecke erhalten wollen.\n<\/p>\n<p>Schneiden Sie die Trauben im Sp\u00e4twinter, bevor die Knospen zu schwellen beginnen. Konzentrieren Sie sich im ersten Jahr nach der Pflanzung darauf, Ihren jungen Pflanzen zu einem geraden, kr\u00e4ftigen Stamm zu verhelfen. Die Ausbildung der Seitenzweige beginnt im zweiten Jahr, so dass die Knospen drei Jahre nach der Pflanzung bereit sind, Fr\u00fcchte zu tragen. Jede Rebsorte, die Sie anbauen, reagiert anders auf die verschiedenen Beschneidungsmethoden, also seien Sie darauf vorbereitet, Ihre Methoden zu verfeinern.\n<\/p>\n<h2>Weinlese und Lagerung von Trauben<br \/>\n<\/h2>\n<p>Trauben sind reif, wenn sie s\u00fc\u00df schmecken. Fr\u00fch reifende wei\u00dfe oder rote Sorten k\u00f6nnen einen Monat vor den sp\u00e4ter reifenden blauen oder schwarzen Trauben erntereif sein. Lassen Sie die Trauben so lange am Rebstock h\u00e4ngen, bis die Beeren eine wei\u00dfliche Bl\u00fcte auf der Schale zeigen, aber holen Sie sie herein, wenn eine feuchte Wetterperiode vorhergesagt ist. Reife Trauben brechen oft nach starken Regenf\u00e4llen.\n<\/p>\n<p>Bewahren Sie ungewaschene Weintrauben in Plastikt\u00fcten im K\u00fchlschrank auf, um die Feuchtigkeit zu erhalten. Frische oder gefrorene Trauben k\u00f6nnen zu Saft, Gelee oder Wein verarbeitet werden. Kernlose Trauben lassen sich am einfachsten zu Rosinen trocknen.\n<\/p>\n<h2>Vermehrung von Weintrauben<br \/>\n<\/h2>\n<p>Weintrauben lassen sich leicht vermehren, indem man im Sp\u00e4twinter oder im zeitigen Fr\u00fchjahr 5 cm lange Stammstecklinge bewurzelt. Steckt man sie 5 cm tief in ein Anzuchtbeet im Freien oder in Beh\u00e4lter mit feuchter Blumenerde, bewurzeln die meisten Stecklinge innerhalb von zwei Monaten und k\u00f6nnen noch in derselben Wachstumsperiode eingesetzt werden. Weintrauben sollten immer aus Stecklingen vermehrt werden, da sie aus Samen nicht keimf\u00e4hig sind.\n<\/p>\n<h2>Tipps zur Sch\u00e4dlings- und Krankheitsbek\u00e4mpfung<br \/>\n<\/h2>\n<p>Alle Traubenkrankheiten lassen sich zum Teil durch sorgf\u00e4ltiges Spalieren, Schneiden und Mulchen verhindern. In allen Gebieten kann der Echte Mehltau (erkennbar an wei\u00dflichen Flecken auf den Bl\u00e4ttern) die Pflanzen schw\u00e4chen und den Geschmack der Trauben beeintr\u00e4chtigen. Vorbeugende Spritzungen mit einer 1-Teil-Milch-zu-5-Teilen-Wasser-L\u00f6sung k\u00f6nnen dieses Problem minimieren.\n<\/p>\n<p>Im Westen selten, ist die als Schwarzf\u00e4ule bekannte Pilzkrankheit eine st\u00e4ndige Bedrohung f\u00fcr die Trauben im Osten. Die Pflanzen m\u00fcssen h\u00e4ufig regelm\u00e4\u00dfig mit organischen Fungiziden auf Kupferbasis bespr\u00fcht werden, selbst wenn die Sorte krankheitstolerant ist. Mikrobielle Fungizide auf der Basis von Bacillus subtilis (wie Serenade) k\u00f6nnen ebenfalls einen bedeutenden Schutz bieten.\n<\/p>\n<p>Im Sun Belt sollten G\u00e4rtner Sorten w\u00e4hlen, die resistent gegen die Pierce-Krankheit sind, die in B\u00f6den mit warmem Klima h\u00e4ufig auftritt. Eine gute Wahl sind &#8216;Black Spanish,&#8217; &#8216;Blanc du Bois&#8217; und &#8216;Victoria Red.&#8217;\n<\/p>\n<p>Traubenbl\u00e4tter geh\u00f6ren zu den Lieblingsspeisen der japanischen K\u00e4fer, und die Fr\u00fcchte sind ein beliebter Snack f\u00fcr viele Wildv\u00f6gel. Ein fr\u00fchzeitiges Einsammeln der K\u00e4fer von Hand ist f\u00fcr eine gute Bek\u00e4mpfung unerl\u00e4sslich, und T\u00fcllnetze k\u00f6nnen helfen, die Pflanzen vor hungrigen V\u00f6geln zu sch\u00fctzen.\n<\/p>\n<h2>Weintrauben in der K\u00fcche<br \/>\n<\/h2>\n<figure><img decoding=\"async\" src=\"https:\/\/my-garden.blog\/auto_content\/local_image\/7629673831323490.webp\" \/><\/figure>\n<p>Kernlose Tafeltrauben eignen sich hervorragend zum Naschen, k\u00f6nnen Salaten oder Chutneys zugef\u00fcgt oder zu Rosinen getrocknet werden. Alle Traubensorten geben ihren Saft ab, wenn sie kaum erhitzt werden, bevor sie zerdr\u00fcckt und abgetropft werden. Stellen Sie den Traubensaft mindestens 24 Stunden lang in den K\u00fchlschrank, damit er klar wird, gie\u00dfen Sie dann den Saft ab und entsorgen Sie die Weins\u00e4urekristalle am Boden des Beh\u00e4lters. Traubensaft kann eingemacht, eingefroren oder zu Gelee oder Wein verarbeitet werden.\n<\/p>\n<p>Weintrauben liefern Ballaststoffe, Kalium und eine Reihe von Vitaminen und Mineralien, aber die wahre N\u00e4hrstoffkraft kommt von den Phenolen und Antioxidantien, die in dunkelfarbigen Trauben am reichlichsten vorhanden sind. Die Antioxidantien in dunkelviolettem Traubensaft k\u00f6nnen die Gehirnfunktion verbessern, und sowohl Saft als auch Wein aus dunklen Trauben sind gut f\u00fcr Ihr Herz.\n<\/p>\n<p>Die Redakteurin Barbara Pleasant g\u00e4rtnert in S\u00fcdwest-Virginia, wo sie Gem\u00fcse, Kr\u00e4uter, Obst, Blumen und ein paar gl\u00fcckliche H\u00fchner anbaut. Kontaktieren Sie Barbara \u00fcber ihre Website.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Einzelheiten zum Anbau vieler anderer Gem\u00fcse- und Obstsorten finden Sie auf unserer Seite Ernte auf einen Blick). Langlebige Weintrauben k\u00f6nnen in den meisten Klimazonen angebaut werden, vorausgesetzt, Sie w\u00e4hlen die f\u00fcr Ihre Region geeigneten Sorten. In Minnesota gez\u00fcchtete, k\u00e4lteresistente Sorten k\u00f6nnen Temperaturen von bis zu minus 30 Grad Celsius \u00fcberstehen, w\u00e4hrend krankheitsresistente Muscadine-Trauben in warmen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":80638,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115],"tags":[],"class_list":["post-80617","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-fruits"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts\/80617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/comments?post=80617"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts\/80617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/media\/80638"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/media?parent=80617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/categories?post=80617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/tags?post=80617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}