{"id":80175,"date":"2023-03-07T10:41:08","date_gmt":"2023-03-07T07:41:08","guid":{"rendered":"https:\/\/demo5.teaser-cube.ru\/2023\/03\/07\/de-wie-man-tomatensamen-aufbewahrt\/"},"modified":"2023-03-07T10:41:08","modified_gmt":"2023-03-07T07:41:08","slug":"de-wie-man-tomatensamen-aufbewahrt","status":"publish","type":"post","link":"https:\/\/my-garden.blog\/de\/2023\/03\/07\/de-wie-man-tomatensamen-aufbewahrt\/","title":{"rendered":"Wie man Tomatensamen aufbewahrt"},"content":{"rendered":"<p>Das Aufbewahren von Tomatensamen stellt sicher, dass die wertvollen, k\u00f6stlichen Tomaten von gestern auch in den G\u00e4rten der Zukunft wieder wachsen. Zu lernen, wie man Tomatensamen aufbewahrt, ist eine Absicherung gegen die Unsicherheit von morgen.\n<\/p>\n<p>Der Hochsommer ist da, und das bedeutet f\u00fcr die meisten G\u00e4rtner: Tomatensaison! Tomaten sind die unbestrittenen K\u00f6niginnen des Gartens und eine der beliebtesten Pflanzen, die auf der ganzen Welt angebaut werden. Mit \u00fcber 3.000 Sorten, die von Experten wie Craig LeHoullier, dem Autor des 2019 erscheinenden Buches Epic Tomatoes, beschrieben werden, haben Tomaten dem Gartenliebhaber eine Menge zu bieten. Man k\u00f6nnte sogar sagen, dass kein einzelner G\u00e4rtner jemals hoffen kann, sie alle anzubauen.\n<\/p>\n<p>Aber man kann es ja mal versuchen!\n<\/p>\n<p>Ganz gleich, ob sie sich daf\u00fcr entscheiden, Jahr f\u00fcr Jahr ein paar ausgew\u00e4hlte Sorten gesch\u00e4tzter Erbst\u00fccke anzubauen oder sich in den Tomatenwahn zu st\u00fcrzen, die meisten G\u00e4rtner w\u00fcnschen sich irgendwann, ihre eigenen Tomatensamen zu retten. Die Gr\u00fcnde f\u00fcr den Wunsch, eigenes Saatgut zu ernten und aufzubewahren, sind vielf\u00e4ltig und reichen von der Schwierigkeit, einige seltene Erbst\u00fccke zu beschaffen, bis hin zur Unbest\u00e4ndigkeit der gro\u00dfen Saatgutunternehmen, die eine Lieblingssorte ohne Vorwarnung aus dem Sortiment nehmen k\u00f6nnen.\n<\/p>\n<p>Der eigene Saatgutvorrat ist eine Absicherung gegen die Ungewissheit und eine Garantie daf\u00fcr, dass die kostbaren, k\u00f6stlichen Tomaten von einst auch in den G\u00e4rten der Zukunft wieder wachsen.\n<\/p>\n<h2>Das Risiko der Fremdbest\u00e4ubung<br \/>\n<\/h2>\n<p>Die Saatgutaufbewahrung beginnt mit der Auswahl von Pflanzen, die Merkmale aufweisen, die es wert sind, f\u00fcr k\u00fcnftige Generationen erhalten zu werden. G\u00e4rtnerinnen und G\u00e4rtner sollten immer Samen von Pflanzen aufbewahren, die die besten Eigenschaften der von ihnen gew\u00e4hlten Sorten aufweisen, wie Wuchsst\u00e4rke, hoher Ertrag und Resistenz gegen Tomatenkrankheiten. Es kann schwierig sein, diese Eigenschaften zu quantifizieren, und es kann noch schwieriger sein, Pflanzen zu finden, die alle w\u00fcnschenswerten Eigenschaften auf einmal aufweisen, so dass das Ausschlussverfahren ein zeitsparender und gesundheitsf\u00f6rdernder Prozess sein kann!\n<\/p>\n<p>Der n\u00e4chste Schritt zur Erhaltung der Saatgutreinheit ist das Einpacken der Bl\u00fcten. Das Thema der Tomatenkreuzung ist sehr umstritten. Tomaten haben perfekte, selbstbest\u00e4ubende Bl\u00fcten und sind durchaus in der Lage, auch ohne die Anwesenheit eines Best\u00e4ubers Fr\u00fcchte zu tragen, aber es m\u00fcssen einige Vorsichtsma\u00dfnahmen getroffen werden, um die Reinheit des Saatguts zu gew\u00e4hrleisten, wenn viele Sorten nahe beieinander angebaut werden, wie es in Hausg\u00e4rten h\u00e4ufig der Fall ist. Wie die erfahrene Saatgutsammlerin Suzanne Ashworth in ihrem 2002 erschienenen renommierten Buch &#8220;Seed to Seed,&#8221; schreibt, kommt es bei Tomaten zu unterschiedlich starken Kreuzungen. Die Anatomie der Bl\u00fcte spielt eine gro\u00dfe Rolle dabei, ob sich eine Sorte auskreuzt oder nicht. Laut Ashworth haben beispielsweise alle Kartoffelblattsorten einen abstehenden Griffel, der den empf\u00e4nglichen weiblichen Teil der Bl\u00fcte f\u00fcr Pollen von au\u00dfen zug\u00e4nglich macht. Gef\u00fcllte Bl\u00fcten, wie sie bei gro\u00dfen Beefsteak-Tomaten \u00fcblich sind, haben ebenfalls freiliegende Narben, was sie anf\u00e4llig f\u00fcr Fremdbest\u00e4ubung durch Insekten macht.\n<\/p>\n<p>Um den Bl\u00fctentyp einer bestimmten Tomatensorte zu bestimmen, sollte der G\u00e4rtner eine Probe der Bl\u00fcten von jeder Pflanze unter einer Lupe untersuchen. Es ist zu beachten, dass die meisten erh\u00e4ltlichen Kirschtomaten, Pastetentomaten, Schnitttomaten und Beefsteak-Tomaten eingezogene Stile haben (abgesehen von den Doppelbl\u00fcten bei Beefsteaks) und f\u00fcr die Sortenerhaltung sicher verwendet werden k\u00f6nnen.\n<\/p>\n<h2>Zeitmessung<br \/>\n<\/h2>\n<p>Die Ernte von Samen unterscheidet sich von der Ernte f\u00fcr den Tisch. Die meisten G\u00e4rtner ernten gro\u00dfe Beefsteak-Tomaten, sobald sie err\u00f6ten, um sie vor Viechern und anderen Plagegeistern zu sch\u00fctzen, und ziehen es vor, sie in der Sicherheit eines Innenraums reifen zu lassen.\n<\/p>\n<p>Dies ist keine optimale Wahl, wenn es um das Speichern von Saatgut geht. Tomaten, die f\u00fcr die Samenaufbewahrung ausgew\u00e4hlt und geerntet werden, sollten sehr reif sein, d. h. fast \u00fcber das essbare Stadium hinaus. Je l\u00e4nger die Samen an der Pflanze reifen k\u00f6nnen, desto mehr lebensf\u00e4hige Samen werden gesammelt. Eine einzige Tomate kann je nach Sorte und Gr\u00f6\u00dfe zwischen f\u00fcnfzig und dreihundert Samen hervorbringen - mehr als genug Samen f\u00fcr den Saatgutsammler zu Hause, an denen er sich in den n\u00e4chsten Jahren erfreuen kann.\n<\/p>\n<h2>Wie man Tomatensamen aufbewahrt<br \/>\n<\/h2>\n<p>Jeder Tomatensamen ist von einer gallertartigen H\u00fclle umgeben, die Chemikalien enth\u00e4lt, die die Keimung verhindern. Dieser kleine Trick der Natur verhindert, dass die Samen im Fruchtfleisch der Tomate keimen. W\u00e4re die reife Tomate sich selbst \u00fcberlassen, w\u00fcrde sie im Herbst und Winter von der Pflanze fallen und verfaulen, wodurch der Gelsack zerst\u00f6rt und die Keimung im Fr\u00fchjahr erm\u00f6glicht w\u00fcrde, wenn die Wachstumsbedingungen optimal sind.\n<\/p>\n<p>Dieser Prozess muss f\u00fcr die h\u00e4usliche Saatgutaufbewahrung nachgebildet werden, und das ist mit Hilfe von . Durch die Fermentierung wird der Gelsack vor dem Trocknen entfernt, wodurch der nat\u00fcrliche Prozess in kurzer Zeit dupliziert wird.\n<\/p>\n<p>Der erste Schritt besteht darin, die Kerne aus der oder den ausgew\u00e4hlten Fr\u00fcchten zu entfernen. Schneiden Sie die Tomate in zwei H\u00e4lften und dr\u00fccken Sie das Gel und die Kerne in einen gro\u00dfen Glasbeh\u00e4lter. Fahren Sie fort, bis Sie das gesamte Gel und alle Samen gesammelt haben. F\u00fcllen Sie dann das Glas mit Wasser bei Raumtemperatur, so dass die Kerne vollst\u00e4ndig bedeckt sind.\n<\/p>\n<p>Der folgende Schritt wird am besten drau\u00dfen an einem schattigen Ort durchgef\u00fchrt, da es ziemlich stinken kann. Lassen Sie die Mischung aus Wasser, Gel und Samen in einem offenen Gef\u00e4\u00df g\u00e4ren (es kann hilfreich sein, es mit einem Seihtuch abzudecken, wenn Fliegen anwesend sind). Der nat\u00fcrliche G\u00e4rungsprozess wird in den n\u00e4chsten Tagen ablaufen. Sobald sich eine graue oder wei\u00dfe Schimmelschicht auf der Oberfl\u00e4che gebildet hat und die Samen auf den Boden gefallen sind, ist das Gel verdaut und die Samen k\u00f6nnen gereinigt und getrocknet werden.\n<\/p>\n<p>Um die Samen zu reinigen, schaufeln Sie alle an der Oberfl\u00e4che schwimmenden Pflanzenteile und die Schimmelschicht heraus und entsorgen Sie sie - oder noch besser: kompostieren Sie sie! Gie\u00dfen Sie dann das Wasser vorsichtig aus. Machen Sie sich keine Sorgen um die schwimmenden Samen, die versuchen zu entkommen; diese sind leichter als die anderen, weil ihnen der Embryo fehlt, der die Samen lebensf\u00e4hig macht. Die schwereren Samen, die am Boden warten, sind diejenigen, die Sie behalten wollen.\n<\/p>\n<p>F\u00fcllen Sie das Gef\u00e4\u00df erneut mit Wasser, sch\u00fctteln Sie es und gie\u00dfen Sie es aus. Wiederholen Sie den Vorgang, bis Ihre Samen sauber sind. Zu diesem Zeitpunkt kann es n\u00fctzlich sein, ein feinmaschiges Sieb zu verwenden.\n<\/p>\n<h2>Trocknen<br \/>\n<\/h2>\n<p>Das Trocknen ist vielleicht der wichtigste Teil des gesamten Prozesses der Samenaufbewahrung. Legen Sie Ihr frisch gereinigtes Saatgut zum Trocknen einfach auf eine ebene Fl\u00e4che, die vor direkter Sonneneinstrahlung gesch\u00fctzt ist. Machen Sie nicht den Fehler, Ihre Samen zum Trocknen auf ein nasses Papiertuch zu legen! Das Papier l\u00e4sst sich kaum noch entfernen, wenn die Samen eingetrocknet sind. Eine Keramik- oder Kunststoffplatte gen\u00fcgt, aber manche Leute verwenden auch gerne Kaffeefilter.\n<\/p>\n<p>R\u00fchren Sie die Samen t\u00e4glich um, am besten zweimal am Tag, damit sie nicht zusammenklumpen.\n<\/p>\n<p>Die Samen m\u00fcssen vor der Lagerung vollst\u00e4ndig trocken sein, daher sollten sie mindestens zwei Wochen in einer trockenen Umgebung trocknen. Die Verwendung eines Dehydratisierungsger\u00e4ts auf niedrigster Stufe, um die Feuchtigkeit zu entziehen, ist ebenfalls n\u00fctzlich, und viele Saatgutsammler kaufen ein solches Ger\u00e4t nur zu diesem Zweck. Lagern Sie Ihr Saatgut nicht in einem verschlossenen Beh\u00e4lter, wenn es nicht gr\u00fcndlich getrocknet ist. Jede Feuchtigkeit verdirbt das Saatgut.\n<\/p>\n<h2>Lebensf\u00e4higkeit des Saatguts und Lagerf\u00e4higkeit<br \/>\n<\/h2>\n<p>Tomatensamen sind bekanntlich sehr lange haltbar! Unter idealen Lagerungsbedingungen wird allgemein eine Spanne von 4 bis 7 Jahren angenommen. Lagern Sie Ihre Samen einfach an einem k\u00fchlen, trockenen und lichtgesch\u00fctzten Ort, um die Keimrate hoch zu halten. Alternativ k\u00f6nnen die Samen nach dem Trocknen eingefroren werden, wodurch sich die Haltbarkeit auf ein Jahrzehnt oder mehr verl\u00e4ngert.\n<\/p>\n<p>Marjorie Beausoleil &#8211; Als lebenslange G\u00e4rtnerin und Liebhaberin von allem, was mit Pflanzen zu tun hat, entdeckte Marjorie Beausoleil ihre wahre Leidenschaft f\u00fcr den Erhalt und die F\u00f6rderung von Erbst\u00fccksorten von Blumen, Kr\u00e4utern und Gem\u00fcse, nachdem sie 2008 als frischgebackene Mutter ihren ersten Gem\u00fcsegarten angelegt hatte. Ihr Unternehmen, Ethos Seed Company, wird von ihrer kleinen Farm in Connecticut aus betrieben, wo sie viele der in ihrem Gesch\u00e4ft angebotenen Sorten anbaut. Ihre gr\u00f6\u00dften Leidenschaften sind Tomaten, Paprika, Bohnen und Salate.\n<\/p>\n<p>Finden Sie Ethos Seed Company auf Instagram, Facebook und Pinterest.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Aufbewahren von Tomatensamen stellt sicher, dass die wertvollen, k\u00f6stlichen Tomaten von gestern auch in den G\u00e4rten der Zukunft wieder wachsen. Zu lernen, wie man Tomatensamen aufbewahrt, ist eine Absicherung gegen die Unsicherheit von morgen. Der Hochsommer ist da, und das bedeutet f\u00fcr die meisten G\u00e4rtner: Tomatensaison! Tomaten sind die unbestrittenen K\u00f6niginnen des Gartens und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":80196,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[122],"tags":[],"class_list":["post-80175","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-vegetables"],"_links":{"self":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts\/80175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/comments?post=80175"}],"version-history":[{"count":0,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/posts\/80175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/media\/80196"}],"wp:attachment":[{"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/media?parent=80175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/categories?post=80175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/my-garden.blog\/de\/wp-json\/wp\/v2\/tags?post=80175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}